{"id":58375,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=58375"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"crypto-miner-sphere-3d-sues-gryphon-digital-mining-details","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/de\/crypto-miner-sphere-3d-sues-gryphon-digital-mining-details\/","title":{"rendered":"Crypto Miner Sphere 3D verklagt Gryphon Digital Mining: Details"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Laut Gerichtsdokumenten hat Sphere 3D eine Klage gegen seinen Partner Gryphon Digital Mining wegen der unregelm\u00e4\u00dfigen \u00dcbertragung von Bitcoin (BTC) eingereicht.<\/strong><\/li>\n\n\n\n<li><strong>Das Bergbauunternehmen behauptet, dass Gryphon Digital Mining die Verm\u00f6genswerte von Sphere 3D gef\u00e4hrdet habe.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>Wir glauben, dass Gryphon die Verm\u00f6genswerte des Unternehmens erheblich gef\u00e4hrdet und vors\u00e4tzlich gegen seine vertraglichen Pflichten versto\u00dfen hat.\u201c sagte der CEO des Bergbauunternehmens.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>Rob Chang, CEO von Gryphon, soll durch einen Spoofing-Angriff Bitcoin (BTC) an einen Betr\u00fcger \u00fcbertragen haben, der behauptet, der Finanzvorstand von Sphere 3D zu sein.<\/strong><\/li>\n\n\n\n<li><strong>Die Klage basiert auf dieser \u00dcbertragung von BTC durch CEO Chang an den Betr\u00fcger.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Kryptow\u00e4hrungs-Mining-Unternehmen waren vom Preisverfall bei Kryptow\u00e4hrungen stark betroffen und viele Unternehmen meldeten sogar Insolvenz an. Inmitten dieser unsicheren Zeiten hat das Krypto-Mining-Unternehmen Sphere 3D eine Klage gegen seinen Partner Gryphon Digital Mining wegen der unregelm\u00e4\u00dfigen \u00dcbertragung von Bitcoin (BTC) eingereicht, wie aus am 7. April dem Gericht vorgelegten Dokumenten hervorgeht.&nbsp;<\/p>\n\n\n\n<p>Laut einer Presse<a href=\"https:\/\/sphere3d.gcs-web.com\/news-releases\/news-release-details\/sphere-3d-files-litigation-against-gryphon-digital-mining\" rel=\"nofollow noopener\" target=\"_blank\"> Ver\u00f6ffentlichung<\/a>Sphere 3D, dessen Ziel es ist, ein f\u00fchrendes CO2-neutrales Krypto-Mining-Unternehmen zu werden, behauptet, dass Gryphon Digital Mining die Verm\u00f6genswerte des Unternehmens gef\u00e4hrdet habe. Es ist wichtig zu beachten, dass die beiden Unternehmen einst \u00fcber eine Fusion nachgedacht hatten, sich die Situation jedoch allm\u00e4hlich verschlechterte.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eHeute haben wir einen Rechtsstreit gegen Gryphon, den Verwahrungsverwaltungsdienstleister unserer Blockchain- und Kryptow\u00e4hrungsdienste, wegen erheblicher Verletzung des Master Services Agreement (\u201eMSA\u201c), das wir mit Gryphon abgeschlossen haben, eingereicht. Wir glauben, dass Gryphon die Verm\u00f6genswerte des Unternehmens erheblich gef\u00e4hrdet und vors\u00e4tzlich gegen seine vertraglichen Pflichten versto\u00dfen hat.\u201c sagte Patricia Trompeter, CEO von Sphere 3D.<\/p>\n<\/blockquote>\n\n\n\n<p>Sphere 3D und Gryphon schlossen am 19. August 2021 den MSA ab, der anschlie\u00dfend am 29. Dezember 2021 ge\u00e4ndert wurde und Gryphon aufforderte, \u201edie Krypto-Mining-Aktivit\u00e4ten von Sphere 3D zu verwalten und treuh\u00e4nderische Pflichten bez\u00fcglich der digitalen Verm\u00f6genswerte von Sphere wahrzunehmen.\u201c&nbsp;<\/p>\n\n\n\n<p>Als Ergebnis der Vereinbarung zwischen den beiden erh\u00e4lt Gryphon 22,51 TP5T des Gewinns des Krypto-Miners im Austausch f\u00fcr die oben genannten Dienstleistungen.&nbsp;<\/p>\n\n\n\n<p>Laut Beschwerde<a href=\"https:\/\/ecf.nysd.uscourts.gov\/doc1\/127133144335\" rel=\"nofollow noopener\" target=\"_blank\"> abgelegt<\/a> Laut Anw\u00e4lten des Krypto-Mining-Unternehmens soll Gryphon-CEO Rob Chang am 18. Januar durch einen Spoofing-Angriff Bitcoin (BTC) an einen Betr\u00fcger \u00fcbertragen haben, der behauptete, der Finanzvorstand von Sphere 3D zu sein. Weitere acht Bitcoins wurden einige Tage sp\u00e4ter an dieselbe Adresse gesendet sp\u00e4ter auch.<\/p>\n\n\n\n<p>Unter einem Spoofing-Angriff versteht man eine betr\u00fcgerische Aktivit\u00e4t, bei der der Angreifer vorgibt, eine andere Person zu sein, indem er mithilfe \u00e4hnlicher IP-Adressen, E-Mail-Header oder Benutzeranmeldeinformationen seine Identit\u00e4t f\u00e4lscht. Anschlie\u00dfend verschaffen sich die Angreifer Zugriff auf ein System, stehlen sensible Informationen oder starten weitere Angriffe.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eMeine Aufgabe besteht in erster Linie darin, die Verm\u00f6genswerte des Unternehmens zu sch\u00fctzen und den Shareholder Value zu maximieren. Die heutige Einreichung zeigt, dass wir nicht nur das Unternehmen sch\u00fctzen werden, f\u00fcr dessen Bew\u00e4ltigung wir alle im vergangenen Jahr so hart gearbeitet haben, sondern auch, dass wir nicht von Leuten wie Gryphon schikaniert oder bedroht werden. Unternehmensintegrit\u00e4t ist auch in unserer Branche von wesentlicher Bedeutung. Gryphon hat es vers\u00e4umt, mit Integrit\u00e4t zu handeln, hat unseren Vertrag nicht eingehalten und wir werden sie zur Rechenschaft ziehen\u201c, sagte Trompeter.<\/p>\n<\/blockquote>\n\n\n\n<p>Andererseits war New York der erste US-Bundesstaat, der ein vor\u00fcbergehendes Verbot von Proof-of-Work-Mining-Aktivit\u00e4ten ank\u00fcndigte, nachdem die Gouverneurin des Bundesstaates, Kathy Hochul, das Gesetz unterzeichnet hatte<a href=\"https:\/\/bitcoinwisdom.com\/de\/new-york-sign-the-proof-of-work-mining-morato\/\"> Proof-of-Work (PoW)-Moratorium f\u00fcr den Bergbau gesetzlich verankert<\/a>. <\/p>\n\n\n\n<p>Das Kriegsgefangenengesetz wird nicht nur neue Bergbaubetriebe verbieten, sondern auch Unternehmen, die bereits im Bundesstaat t\u00e4tig sind, daran hindern, ihre Genehmigungen zu erneuern. Bergbauunternehmen d\u00fcrfen nur dann t\u00e4tig werden, wenn sie erneuerbare Energiequellen nutzen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cryptocurrency mining companies were deeply impacted by the fall in the price of crypto coins, and many companies even filed for bankruptcy as well. Amid these uncertain times, crypto mining company Sphere 3D has filed a lawsuit against its partner Gryphon Digital Mining over the irregular transfer of Bitcoin (BTC), as per documents submitted in [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":58376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[135,172],"class_list":["post-58375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-blockchain","tag-crypto"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Sphere-3D-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/de\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Cryptocurrency mining companies were deeply impacted by the fall in the price of crypto coins, and many companies even filed for bankruptcy as well. Amid these uncertain times, crypto mining company Sphere 3D has filed a lawsuit against its partner Gryphon Digital Mining over the irregular transfer of Bitcoin (BTC), as per documents submitted in&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/posts\/58375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/comments?post=58375"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/posts\/58375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/media\/58376"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/media?parent=58375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/categories?post=58375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/tags?post=58375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}