{"id":68739,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=68739"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"dogecoin-investors-accuse-elon-musk-of-insider","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/de\/dogecoin-investors-accuse-elon-musk-of-insider\/","title":{"rendered":"Dogecoin-Investoren beschuldigen Elon Musk des Insiderhandels"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Elon Musk hat seit 2019 seine \u00f6ffentliche Unterst\u00fctzung f\u00fcr Dogecoin zum Ausdruck gebracht.<\/strong><\/li>\n\n\n\n<li><strong>Musks Tweets und Aussagen zu Dogecoin haben sich oft auf den Preis der Kryptow\u00e4hrung ausgewirkt.<\/strong><\/li>\n\n\n\n<li><strong>Musk k\u00fcndigte k\u00fcrzlich Pl\u00e4ne an, als CEO von Twitter zur\u00fcckzutreten und durch Linda Yaccarino, ehemalige Vorsitzende f\u00fcr globale Werbung und Partnerschaften bei NBCUniversal, ersetzt zu werden.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Einige Dogecoin-Investoren haben den Gesch\u00e4ftsmann und CEO von Tesla Inc., Elon Musk, beschuldigt, die Kryptow\u00e4hrung manipuliert zu haben, was sie Milliarden von Dollar gekostet hat, und haben die \u00c4nderung einer Sammelklage beantragt, in der Musk Insiderhandel vorgeworfen wird.<\/p>\n\n\n\n<p>In einer Klageschrift beim Bundesgericht in Manhattan behaupteten die Investoren, Musk habe angeheuerte Social-Media-Influencer, Tweets, seinen Auftritt in der NBC-Sendung \u201eSaturday Night Live\u201c im Jahr 2021 und andere \u201eWerbegags\u201c genutzt, um auf ihre Kosten von der Kryptow\u00e4hrung zu profitieren. <\/p>\n\n\n\n<p>Als Beispiel f\u00fcr Musks manipulatives Vorgehen nannten die Investoren Musks j\u00fcngste Entscheidung, das blaue Logo von Twitter durch das beliebte Shiba-Inu-Logo von Dogecoin zu ersetzen. Berichten zufolge verkaufte der Twitter-CEO im April Dogecoin im Wert von rund $124 Millionen, was zu einem Preisanstieg von Dogecoin um 30% f\u00fchrte.<\/p>\n\n\n\n<p>Die Investoren <a aria-label=\"abgelegt (\u00f6ffnet sich in einem neuen Tab)\" href=\"https:\/\/bitcoinwisdom.com\/de\/elon-musk-might-be-sued-for-dogecoin-losses\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">abgelegt<\/a> ihre <a aria-label=\"Beschwerde (\u00f6ffnet sich in einem neuen Tab)\" href=\"https:\/\/assets2.pacermonitor.com\/filings\/Johnson_v_Musk_et_al\/Johnson_v_Musk_et_al__nysdce-22-05037__0001.0.pdf?X-Amz-Security-Token=IQoJb3JpZ2luX2VjELn%2F%2F%2F%2F%2F%2F%2F%2F%2F%2FwEaCXVzLWVhc3QtMSJHMEUCICe8v9QbE5ucxkNw%2F4uIyKQkjJprelAClmtWXaGaR63yAiEAmtTds26Or20TjflZQuFt8E5KHvARjGVAJVpAzkBd4iYq3AQIwv%2F%2F%2F%2F%2F%2F%2F%2F%2F%2FARADGgw5MjQ2NTE0MDgzOTgiDHdleGUYt3IzNA4WxCqwBMxc7LYGv%2F3FmkzepvB1iEhKy4WrV60iR%2BC6sgRWd7KRvpeKutlBGRhY%2BSpmfSN2P5eTxK1sprMAOk4RMJbwXMB2IwFCatBro0IJPS26eMo3TpqDLwCVQAfqVqTxlvqdgOv%2Fvesj6yET6XWuPEY08iW2ZbF%2F9fqXXy3ujKokd2%2BOMPORrbBGZ3wYx5E1Ux7GsuU7a55EJfmihcgkf22mcb2yW%2F25nolZn26PATe1SVfwfc%2BJPOFpch%2BpIDZDINfzNgnYW%2BNc60KcB%2FWBluXiuINNUw%2FqBPcx4FgwyAyTTt0%2BbPFpQnYc%2FzQ9XDwgOOge%2FK8mT3q3svyKADAW4LOmGnjxCMshOnxLrcWVA5pdQT6Xp1V56%2Br%2BSXD986u3EHnCTGoTiIP311bCYq1o4pcpjdcrCZE%2F%2F3rtF%2FehTr%2By3Iy9%2FdH3Dbp4RUl7%2BP16eOQvUeCCEukWX8M9OgFLYcvrdsAox1l%2Fw%2FUQ3dfLYpia7fVObcoo%2FRUN8ak85FMqBkgyKGB7mfCqDLM6vU%2Bw5Hianz3hWo9WuCcTEvKsqv%2FY6L0rIAC1uFw%2FC%2F4%2F%2Bs3qDpJhu%2BnvZGCCGv9%2FVPfjwvAI9XcQ6%2Bc2TC7kx5%2BPm7PyY0SKBM5C4a6JTMPcKog44sq9HTTeMawq1fBvsbBITYxKmjxRuE4rFCn2seFta5Elc54qv1Y0X5P0oQkjOESiNWyArByjoh4KLwtS9xiAA9Uh5Av0sFrFeGm5LKvXQaQz5YXAMOG6rZUGOqkB0oSanITZYUmLZlbgCjFCckfK8%2FTGfAR1DMznAy%2FFM1HNAh9Bi6glBFifnM68QF9sBoXrOZOICHPvTnPyEPQjClub0Bg1Fj9%2BH%2FL3rYsdeci303GLJtGoeuG5dMfIQI9hzTVw7qOi81%2FF68mt0OeLODNJNcw2j1nyQmb8%2FfWKut0BOzkDDZIchN9jIbI3ViOdimrq960jFJj7YVWSOD%2FrDKyHANsocddz9A%3D%3D&amp;X-Amz-Algorithm=AWS4-HMAC-SHA256&amp;X-Amz-Date=20220616T172931Z&amp;X-Amz-SignedHeaders=host&amp;X-Amz-Expires=599&amp;X-Amz-Credential=ASIA5OSMEZQHHGKLHKVM%2F20220616%2Fus-east-1%2Fs3%2Faws4_request&amp;X-Amz-Signature=e89dbab48532f1335e571cea705859ffa86dd08c2139a572d86c7cdbfb8c62c4\" target=\"_blank\" rel=\"noreferrer noopener nofollow\" class=\"ek-link\">Beschwerde<\/a> im Juni 2022, haben es jedoch als Reaktion auf Musks Ma\u00dfnahmen zweimal \u00fcberarbeitet. Sie baten das Gericht um Erlaubnis, ihre Klage zu \u00e4ndern, und argumentierten, dass Musk sich des Insiderhandels mit DOGE schuldig gemacht habe und dass der Token nach den Regeln der US-B\u00f6rsenaufsichtsbeh\u00f6rde Securities and Exchange Commission als Wertpapier qualifiziert sei.<\/p>\n\n\n\n<p>Der ge\u00e4nderten Klage zufolge<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Hierbei handelt es sich um eine Sammelklage wegen Wertpapierbetrugs, die aus einer vors\u00e4tzlichen Vorgehensweise des reichsten Mannes der Welt, Elon Musk, mit Marktmanipulation und Insiderhandel entsteht, der ein aufkommendes Popkultur-Ph\u00e4nomen missbraucht hat, um sich und seine Unternehmen gegenseitig zu promoten und seine Obsz\u00f6nit\u00e4t zu untermauern Verm\u00f6gen, das die ernsthaften Hoffnungen gef\u00e4hrdeter Amerikaner, darunter Kriegsveteranen, Arbeiter und \u00e4ltere Menschen, ausnutzt.<\/p>\n<\/blockquote>\n\n\n\n<p>Die Rechtsabteilung von Musk hat bereits einen Antrag auf Abweisung der zweiten \u00c4nderung der Beschwerde eingereicht und darauf hingewiesen, dass \u201elustige Bilder\u201c und \u201eTwittern unterst\u00fctzender Worte\u201c keine betr\u00fcgerischen Aktivit\u00e4ten seien. Musk hat ein besonderes Interesse an Kryptow\u00e4hrungen gezeigt, scheint jedoch spezieller an Dogecoin zu sein, f\u00fcr das er seit 2019 wirbt.<\/p>\n\n\n\n<p>Musk gab k\u00fcrzlich bekannt, dass er als CEO von Twitter zur\u00fccktreten werde, um sich auf andere Unternehmungen zu konzentrieren.<\/p>","protected":false},"excerpt":{"rendered":"<p>Some dogecoin investors have accused businessman and CEO of Tesla Inc., Elon Musk, of manipulating the cryptocurrency and costing them billions of dollars and have requested to amend a class action lawsuit charging Musk with insider trading. The investors, in a filing in Manhattan federal court, claimed Musk used hired social media influencers, tweets, his [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":15457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[172,214],"class_list":["post-68739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-crypto","tag-elon-musk"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2.jpg",1200,800,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2-300x200.jpg",300,200,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2-768x512.jpg",640,427,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2.jpg",1200,800,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2.jpg",1200,800,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Elon-Musk-2-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Lawrence Woriji","author_link":"https:\/\/bitcoinwisdom.com\/de\/author\/lawrencew\/"},"uagb_comment_info":0,"uagb_excerpt":"Some dogecoin investors have accused businessman and CEO of Tesla Inc., Elon Musk, of manipulating the cryptocurrency and costing them billions of dollars and have requested to amend a class action lawsuit charging Musk with insider trading. The investors, in a filing in Manhattan federal court, claimed Musk used hired social media influencers, tweets, his&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/posts\/68739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/comments?post=68739"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/posts\/68739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/media\/15457"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/media?parent=68739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/categories?post=68739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/de\/wp-json\/wp\/v2\/tags?post=68739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}