{"id":17318,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=17318"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"revolut-expands-staff-following-approval-for-providing-crypto-service-in-singapore","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/es\/revolut-expands-staff-following-approval-for-providing-crypto-service-in-singapore\/","title":{"rendered":"Revolut ampl\u00eda el personal, luego de la aprobaci\u00f3n para proporcionar un servicio criptogr\u00e1fico en Singapur"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>La empresa fintech Revolut ha confirmado que ha aumentado la capacidad de su personal en m\u00e1s de 20%, lo que marca un hito importante en un mercado bajista<\/strong><\/li><li><strong>Adem\u00e1s, la empresa tambi\u00e9n ha sido autorizada para proporcionar servicios relacionados con criptograf\u00eda a clientes en Singapur. Admitir\u00e1 m\u00e1s de 80 tokens criptogr\u00e1ficos<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>La compa\u00f1\u00eda brit\u00e1nica de tecnolog\u00eda financiera Revolut lanz\u00f3 recientemente sus servicios de criptograf\u00eda en Singapur, brindando a los criptoinversionistas opciones de compra, venta y tenencia de m\u00e1s de 80 tokens de criptomonedas en su aplicaci\u00f3n.<\/p>\n\n\n\n<p>Seg\u00fan un reciente <a href=\"https:\/\/www.businesstimes.com.sg\/garage\/revolut-launches-cryptocurrency-trading-in-singapore\" rel=\"nofollow noopener\" target=\"_blank\">reporte<\/a> por The Business Times, la compa\u00f1\u00eda dijo que el intercambio permite a los usuarios convertir oro, plata o hasta 27 monedas fiduciarias en criptoactivos en un solo paso sin tarifas de cambio de divisas.<\/p>\n\n\n\n<p>La compa\u00f1\u00eda ha decidido establecer las tarifas de transacci\u00f3n para los clientes en funci\u00f3n de los niveles en los que se encuentran. Mientras que a los usuarios en el nivel Est\u00e1ndar se les cobrar\u00e1 2.5% de la transacci\u00f3n total, los usuarios Premium y Metal solo tendr\u00e1n que pagar una tarifa de 1.5%.<\/p>\n\n\n\n<p>El jefe de riqueza y comercio designado en diciembre en Revolut Singapur, Deepak Khanna, revel\u00f3 m\u00e1s planes para la compa\u00f1\u00eda al afirmar:&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cPlaneamos brindar funciones educativas en los pr\u00f3ximos meses para ayudar a los clientes a comprender mejor las tendencias y los riesgos asociados con las criptomonedas\u201d.<\/p><\/blockquote>\n\n\n\n<p>Agreg\u00f3 que la compa\u00f1\u00eda cree en el compromiso proactivo de la industria y las fortalezas regulatorias en Singapur. El informe afirma que Revolut tambi\u00e9n ha planeado establecer centros de productos globales en la ciudad-estado. En particular, desde que surgi\u00f3 el brote de Covid-19 en 2020, la base de usuarios de la compa\u00f1\u00eda en la regi\u00f3n se ha multiplicado por seis y, en el \u00faltimo a\u00f1o, su tasa de ejecuci\u00f3n de ingresos se ha m\u00e1s que duplicado.&nbsp;<\/p>\n\n\n\n<p>En abril, la Autoridad Monetaria de Singapur otorg\u00f3 una importante licencia de instituci\u00f3n de pago a Revolut para ofrecer servicios de token de pago digital en la regi\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Revolut planea expandir su equipo de criptomonedas para 20%<\/h2>\n\n\n\n<p>La estrategia de expansi\u00f3n de la compa\u00f1\u00eda marc\u00f3 un hito importante, ya que la compa\u00f1\u00eda anunci\u00f3 m\u00e1s tarde el jueves que aumentar\u00e1 el tama\u00f1o de su equipo de criptograf\u00eda en 20% en los pr\u00f3ximos seis meses. Seg\u00fan un reciente Bloomberg <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-08-04\/revolut-bulks-up-its-crypto-business-with-hiring-push\" rel=\"nofollow noopener\" target=\"_blank\">historia<\/a>, la empresa ya ha contratado a 43 personas para su equipo de criptograf\u00eda en 2022, casi triplicando el tama\u00f1o del equipo.<\/p>\n\n\n\n<p>Actualmente, la compa\u00f1\u00eda ha anunciado 13 puestos relacionados con la industria, incluidos puestos para ingenieros de software, especialistas en criptograf\u00eda y expertos en cumplimiento financiero y prevenci\u00f3n de delitos.<\/p>\n\n\n\n<p>&quot;Vemos a las criptomonedas como un juego a largo plazo y nos mantenemos optimistas sobre la industria de las criptomonedas&quot;, dijo Emil Urmanshin, gerente general de la divisi\u00f3n de criptomonedas de la compa\u00f1\u00eda. Revel\u00f3 que las criptomonedas generan de 5 a 10% de los ingresos totales de Revolut. Al comentar sobre el criptoinvierno en curso, Urmanshin declar\u00f3:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Aunque ha habido confusi\u00f3n, el inter\u00e9s en los criptoactivos ha aumentado y todav\u00eda tenemos m\u00e1s clientes que comercian con criptos que durante julio de 2021&quot;.<\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Fintech firm Revolut has confirmed increasing its staff capacity by over 20%, marking a major milestone in a bearish market Moreover, the firm has also been authorized to provide crypto-related services to customers in Singapore. It will support more than 80 crypto tokens British financial technology company Revolut has recently launched its crypto services in [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":17324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1290],"class_list":["post-17318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-revolut"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Revolut-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/es\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Fintech firm Revolut has confirmed increasing its staff capacity by over 20%, marking a major milestone in a bearish market Moreover, the firm has also been authorized to provide crypto-related services to customers in Singapore. It will support more than 80 crypto tokens British financial technology company Revolut has recently launched its crypto services in&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/17318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/comments?post=17318"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/17318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media\/17324"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media?parent=17318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/categories?post=17318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/tags?post=17318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}