{"id":19808,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=19808"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"fractional-receives-20m-from-paradigm","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/es\/fractional-receives-20m-from-paradigm\/","title":{"rendered":"NFT Ownership Platform Fractional recibe $20M de Paradigm"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Fractional ha anunciado que cambiar\u00e1 su nombre a Tessera y ha recibido nuevos fondos de Paradigm, una empresa de criptoinversi\u00f3n.<\/strong><\/li><li><strong>Paradigm ha invertido $20 millones en Tessera, que utilizar\u00e1 para contratar nuevos empleados para el equipo de 24 miembros y tambi\u00e9n para proporcionar recursos adicionales en un nuevo protocolo que est\u00e1 desarrollando.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>La plataforma de propiedad colectiva de NFT, Fractional, ha anunciado que cambiar\u00e1 su marca a Tessera y ha recibido nuevos fondos de Paradigm, una empresa de criptoinversi\u00f3n. <\/p>\n\n\n\n<p>De acuerdo con la <a href=\"https:\/\/fortune.com\/2022\/08\/17\/nfts-fractional-tessera-paradigm-20-million-funding-round\/\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">anuncio<\/a> el mi\u00e9rcoles, Fractional cerr\u00f3 una ronda de recaudaci\u00f3n de fondos Serie A de $20 millones liderada por Paradigm y tambi\u00e9n confirm\u00f3 sus intenciones de cambiar su marca a Tessera. La plataforma de propiedad de NFT permite a los entusiastas vender fracciones de sus tokens no fungibles. <\/p>\n\n\n\n<p>El fundador y CEO de Tessera, Andy Chorlian, confirm\u00f3 que los fondos se utilizar\u00e1n para agregar m\u00e1s empleados al equipo, que actualmente consta de 24 miembros. Adicionalmente, se contratar\u00e1n profesionales pertenecientes a los roles de marketing y external-facing, as\u00ed como desarrolladores e ingenieros. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cFue una barrera muy, muy grande para muchos de nuestros usuarios, que est\u00e1n tan acostumbrados a negociar NFT en OpenSea o en cualquiera de estos otros mercados, y ese nivel de educaci\u00f3n y tratar de explicar c\u00f3mo funciona todo esto fue solo un paso. demasiado lejos para mucha gente\u201d, <\/p><cite>Chorlian le dijo a Fortune.<\/cite><\/blockquote>\n\n\n\n<p>La empresa utilizar\u00e1 los fondos proporcionados por Paradigm para proporcionar recursos adicionales en un nuevo protocolo que est\u00e1 desarrollando y tambi\u00e9n transformar\u00e1 las piezas digitales del NFT de una persona en NFT y no en tokens digitales ERC-20 como USDT o USDC.<\/p>\n\n\n\n<p>Adem\u00e1s, los NFT fraccionarios se pueden comparar con la impresi\u00f3n de una obra de arte original seg\u00fan Chorlian y tambi\u00e9n proporcionar\u00e1n una mayor simplificaci\u00f3n del proceso de negociaci\u00f3n para aquellos que conocen los NFT pero no est\u00e1n acostumbrados al concepto de tokens digitales. <\/p>\n\n\n\n<p>\u201cRealmente, lo que m\u00e1s nos emociona en general acerca de esto es c\u00f3mo hacemos conexiones interesantes con otras personas\u201d, dijo Chorlian. \u201c\u00bfC\u00f3mo empoderamos a los artistas y creadores?\u201d\u00a0<\/p>\n\n\n\n<p>Fraccionar los NFT puede verse como un movimiento de inversi\u00f3n y el sitio web de Tessera confirma que uno de los beneficios de hacer esto incluye obtener liquidez para un NFT sin tener que vender estos tokens basados en blockchain y al mismo tiempo recaudar tarifas de las personas que compran fracciones de su NFT.<\/p>\n\n\n\n<p>Seg\u00fan Chorlian, Fractional (Tessera) se fund\u00f3 en 2021 y desde entonces ha facilitado $2 mil millones en volumen total de operaciones y alberga alrededor de 70 000 titulares \u00fanicos de NFT fraccionarios. La anterior ronda de financiaci\u00f3n de la plataforma <a href=\"https:\/\/www.theblock.co\/linked\/115122\/fractional-nft-platform-raises-7-9-million-in-seed-funding\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">tuvo lugar<\/a> en agosto de 2021, donde Fractional recaud\u00f3 $7,6 millones de Paradigm. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cA medida que avanzamos en esta pr\u00f3xima fase, el nombre Tessera se siente m\u00e1s representativo de nuestra plataforma, que se trata de brindar a las personas la capacidad de coleccionar cosas que aman y con las que se identifican\u201d. <\/p><cite>dijo una Tessera <a href=\"https:\/\/www.theblock.co\/post\/164001\/paradigm-leads-20-million-round-for-fractional-as-it-rebrands-to-tessera\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">portavoz<\/a>.\u00a0<\/cite><\/blockquote>\n\n\n\n<p>Paradigma tambi\u00e9n <a href=\"https:\/\/bitcoinwisdom.com\/es\/hang-acquires-16m-from-series-a-funding-round-led-by-paradigm\/\" class=\"ek-link\">invirti\u00f3 $16 millones en Hang<\/a> que ayuda a las marcas a aprovechar los NFT para reemplazar sus programas de membres\u00eda y lealtad existentes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Fractional has announced that it is rebranding to Tessera and has received new funding from Paradigm, a crypto investment firm. Paradigm has invested $20 million in Tessera, which it will use to hire new employees to the 24-membered team and also provide additional resources on a new protocol it\u2019s developing. Collective NFT ownership platform Fractional [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":19818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12,187],"tags":[131,915],"class_list":["post-19808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-nft-news","tag-nft","tag-paradigm"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Fractional-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/es\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Fractional has announced that it is rebranding to Tessera and has received new funding from Paradigm, a crypto investment firm. Paradigm has invested $20 million in Tessera, which it will use to hire new employees to the 24-membered team and also provide additional resources on a new protocol it\u2019s developing. Collective NFT ownership platform Fractional&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/19808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/comments?post=19808"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/19808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media\/19818"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media?parent=19808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/categories?post=19808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/tags?post=19808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}