{"id":20462,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=20462"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"hacker-stole-money-from-bitcoin-atm-users","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/es\/hacker-stole-money-from-bitcoin-atm-users\/","title":{"rendered":"Hacker rob\u00f3 dinero de usuarios de cajeros autom\u00e1ticos de Bitcoin"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>El fabricante de cajeros autom\u00e1ticos de Bitcoin, General Bytes, enfrent\u00f3 un compromiso en sus servidores a trav\u00e9s de un ataque de d\u00eda cero que ocurri\u00f3 la semana pasada.<\/strong><\/li><li><strong>La compa\u00f1\u00eda no revel\u00f3 la cantidad de fondos robados ni la cantidad de cajeros autom\u00e1ticos comprometidos. Sin embargo, General Bytes ha aconsejado a los operadores de cajeros autom\u00e1ticos que actualicen urgentemente su software.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>El renombrado fabricante de cajeros autom\u00e1ticos de Bitcoin, General Bytes, se enfrent\u00f3 recientemente a un compromiso en sus servidores a trav\u00e9s de un ataque de d\u00eda cero que ocurri\u00f3 la semana pasada. El incidente permiti\u00f3 a los atacantes actuar como administradores predeterminados y cambiar la configuraci\u00f3n para transferir todos los fondos a la direcci\u00f3n de su billetera.<\/p>\n\n\n\n<p>Ni la compa\u00f1\u00eda revel\u00f3 la cantidad de fondos robados ni la cantidad de cajeros autom\u00e1ticos de Bitcoin comprometidos. Sin embargo, General Bytes tiene <a href=\"https:\/\/generalbytes.atlassian.net\/wiki\/spaces\/ESD\/pages\/2785509377\/Security+Incident+August+18th+2022\" rel=\"nofollow noopener\" target=\"_blank\">aconsejado<\/a> Los operadores de cajeros autom\u00e1ticos actualizar\u00e1n urgentemente su software.<\/p>\n\n\n\n<p>Seg\u00fan el aviso de la compa\u00f1\u00eda publicado el jueves, el pirata inform\u00e1tico identific\u00f3 un error de seguridad en la interfaz de administraci\u00f3n de CAS. Escanearon el espacio de direcciones IP del proveedor de alojamiento en la nube Digital Ocean y hicieron un mal uso de la vulnerabilidad para identificar los servicios CAS en ejecuci\u00f3n en los puertos 7777 o 443. Despu\u00e9s de esto, crearon un nuevo usuario administrador, organizaci\u00f3n y terminal predeterminados.&nbsp;<\/p>\n\n\n\n<p>Despu\u00e9s de evaluar minuciosamente la interfaz CAS, el atacante cambi\u00f3 el nombre del usuario administrador predeterminado a &quot;gb&quot;. Despu\u00e9s de esto, realizaron cambios en la configuraci\u00f3n criptogr\u00e1fica de las m\u00e1quinas bidireccionales con la configuraci\u00f3n de la billetera Thor. Esto result\u00f3 en que los cajeros autom\u00e1ticos de Bitcoin bidireccionales reenviaran criptomonedas a la billetera del atacante cuando los clientes enviaban sus fondos a los cajeros autom\u00e1ticos:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;El atacante pudo crear un usuario administrador de forma remota a trav\u00e9s de la interfaz administrativa de CAS mediante una llamada URL en la p\u00e1gina que se utiliza para la instalaci\u00f3n predeterminada en el servidor y la creaci\u00f3n del primer usuario administrativo&quot;.<\/p><\/blockquote>\n\n\n\n<p>A pesar de la desafortunada violaci\u00f3n, General Bytes afirma que no se ha realizado ning\u00fan acceso a la base de datos. Adem\u00e1s, el atacante no obtuvo acceso a la operaci\u00f3n del host ni al sistema de archivos. La empresa con sede en Praga, Rep\u00fablica Checa, aclar\u00f3 que todas las contrase\u00f1as, hashes de contrase\u00f1as, sales, claves API y claves privadas son seguras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La urgencia del marcador de cajeros autom\u00e1ticos de Bitcoin para los clientes<\/h2>\n\n\n\n<p>General Bytes, que posee y opera 8827 cajeros autom\u00e1ticos de Bitcoin repartidos en m\u00e1s de 120 pa\u00edses, ofrece a los clientes la oportunidad de comprar y vender m\u00e1s de 40 criptomonedas. <\/p>\n\n\n\n<p>La compa\u00f1\u00eda ha instado a los clientes que se ejecutan en 20220531 a que dejen de usar sus servidores ATM de General Bytes hasta que actualicen sus servidores a las versiones de parche 20220725.22 y 20220531.38. <\/p>\n\n\n\n<p>Tambi\u00e9n se ha alentado a los usuarios a cambiar la configuraci\u00f3n del firewall de su servidor para que solo se pueda acceder a la interfaz de administraci\u00f3n de CAS desde las direcciones IP permitidas.\u00a0 <\/p>\n\n\n\n<p>General Bytes tambi\u00e9n recomend\u00f3 a los consumidores que verificaran su &quot;Configuraci\u00f3n de criptograf\u00eda de VENDER&quot; antes de reiniciar las terminales para asegurarse de que los piratas inform\u00e1ticos no hubieran cambiado la configuraci\u00f3n para que el dinero recibido se transfiriera a ellos (y no a los clientes).<\/p>\n\n\n\n<p>Desde su fundaci\u00f3n en 2020, General Bytes afirm\u00f3 que se han realizado m\u00faltiples auditor\u00edas de seguridad, pero ninguna de ellas descubri\u00f3 esta vulnerabilidad.<\/p>\n\n\n\n<p>En particular, el ataque se produjo apenas tres d\u00edas despu\u00e9s de que la empresa hiciera anuncios p\u00fablicos sobre una funci\u00f3n de \u201cAyuda a Ucrania\u201d en sus cajeros autom\u00e1ticos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bitcoin ATM maker General Bytes faced a compromise on its servers via a zero-day attack that happened last week. The company did not reveal the amount of funds stolen, or the number of ATMs compromised. However, General Bytes has advised ATM operators to urgently update their software. Renowned Bitcoin ATM maker General Bytes has recently [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":20468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1406],"class_list":["post-20462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bitcoin-atm"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitcoin-2-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/es\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Bitcoin ATM maker General Bytes faced a compromise on its servers via a zero-day attack that happened last week. The company did not reveal the amount of funds stolen, or the number of ATMs compromised. However, General Bytes has advised ATM operators to urgently update their software. Renowned Bitcoin ATM maker General Bytes has recently&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/20462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/comments?post=20462"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/20462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media\/20468"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media?parent=20462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/categories?post=20462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/tags?post=20462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}