{"id":41498,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=41498"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"sale-of-ftx-subsidiaries-challenged-by-trustee","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/es\/sale-of-ftx-subsidiaries-challenged-by-trustee\/","title":{"rendered":"Venta de subsidiarias de FTX cuestionada por fideicomisario de EE. UU. mientras los ejecutivos buscan recuperar millones donados"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>El fideicomisario de los Estados Unidos desafi\u00f3 recientemente los planes de FTX para vender su moneda digital y su c\u00e1mara de compensaci\u00f3n LedgerX, junto con otras subsidiarias.<\/strong><\/li>\n\n\n\n<li><strong>El fideicomisario Andrew Vara pidi\u00f3 una investigaci\u00f3n independiente antes de cualquier venta. <\/strong><\/li>\n\n\n\n<li><strong>La nueva direcci\u00f3n de apunta a vender divisiones en Jap\u00f3n y Europa junto con LedgerX y la plataforma de compensaci\u00f3n de acciones Embed.<\/strong><\/li>\n\n\n\n<li><strong>\u201cVarios destinatarios de aportaciones u otros pagos\u201d se han puesto en contacto <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/es\/ftx-review\/\" title=\"FTX\" data-wpil-keyword-link=\"linked\">FTX<\/a> devolver los fondos que hab\u00eda donado.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Los problemas asociados con el intercambio de criptomonedas FTX no parecen terminar, ya que el Fideicomisario de los Estados Unidos desafi\u00f3 recientemente los planes de la plataforma l\u00edder de intercambio de criptomonedas para vender su moneda digital y <a href=\"https:\/\/bitnation.co\/ftx-subsidiary-ledgerx-is-up-for-sale-report\/\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">c\u00e1mara de compensaci\u00f3n LedgerX<\/a>, junto con los de otras empresas.<\/p>\n\n\n\n<p>Seg\u00fan un informe reciente de Reuters, el 7 de enero, el s\u00edndico estadounidense Andrew Vara pidi\u00f3 una investigaci\u00f3n independiente antes de cualquier venta. Seg\u00fan la presentaci\u00f3n, Vara cree que esto evitar\u00eda que se comprometa cualquier informaci\u00f3n valiosa relacionada con la quiebra de FTX. El documento dice:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cLa venta de causas de acci\u00f3n potencialmente valiosas contra los directores, funcionarios y empleados de los Deudores, o cualquier otra persona o entidad, no debe permitirse hasta que haya habido una investigaci\u00f3n completa e independiente de todas las personas y entidades que puedan haber estado involucradas en cualquier malversaci\u00f3n, negligencia u otra conducta procesable\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p>La nueva administraci\u00f3n del otrora l\u00edder en el intercambio de cifrado ten\u00eda la intenci\u00f3n de vender su <a href=\"https:\/\/bitnation.co\/ftx-japan-confirms-customer-withdrawals-will-start-soon\/\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">divisiones en japon<\/a> y Europa, as\u00ed como la bolsa de derivados LedgerX y la <a href=\"https:\/\/bitcoinwisdom.com\/es\/crypto-exchange-ftx-acquires-stock-clearing-platform\/\" class=\"ek-link\">plataforma de liquidaci\u00f3n de existencias Embed<\/a>, en un esfuerzo por recuperar los fondos perdidos de sus usuarios.&nbsp;<\/p>\n\n\n\n<p>En particular, una presentaci\u00f3n del 15 de diciembre revela que los abogados de FTX argumentaron que vender estas entidades maximizar\u00eda el valor para el estado de FTX. Adem\u00e1s, tambi\u00e9n cre\u00edan que, dado que hab\u00edan sido adquiridas recientemente y funcionaban independientemente de FTX, la venta de estas entidades ser\u00eda mucho m\u00e1s sencilla.&nbsp;<\/p>\n\n\n\n<p>Se esperaba que las subastas de la compa\u00f1\u00eda comenzaran la venta con Embed en febrero y continuaran con las otras tres subastas en marzo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">New FTX Management tiene nuevos planes<\/h2>\n\n\n\n<p>FTX, que alguna vez fue el mayor rival de <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/es\/binance-review\/\" title=\"Binance\" data-wpil-keyword-link=\"linked\">Binance<\/a>, se declar\u00f3 en quiebra en noviembre del a\u00f1o pasado. De acuerdo a un <a href=\"https:\/\/www.wsj.com\/articles\/ftx-seeks-to-recoup-sam-bankman-frieds-charitable-donations-11673049354\" rel=\"nofollow noopener\" target=\"_blank\">reporte<\/a> Seg\u00fan el Wall Street Journal, la nueva direcci\u00f3n de la bolsa planea recientemente recuperar millones de d\u00f3lares en donaciones realizadas por la bolsa y su ex director ejecutivo, Sam Bankman-Fried.<\/p>\n\n\n\n<p>En septiembre del a\u00f1o pasado, la unidad ben\u00e9fica de FTX, Future Fund, comprometi\u00f3 m\u00e1s de $160 millones a m\u00e1s de 110 organizaciones sin fines de lucro, incluidos investigadores universitarios y nuevas empresas de biotecnolog\u00eda comprometidas con el desarrollo de vacunas COVID-19, as\u00ed como organizaciones sin fines de lucro en India, China y Brasil.<\/p>\n\n\n\n<p>Future Fund comprometi\u00f3 $5 millones a Atlas Fellowship para becas y programas de verano en la escuela secundaria y otros $3,6 millones a AVECRIS, una empresa que crea una plataforma de vacunas gen\u00e9ticas.<\/p>\n\n\n\n<p>Un representante de la empresa afirm\u00f3 que las ganancias comerciales, no los dep\u00f3sitos de los usuarios, se utilizaron para financiar donaciones ben\u00e9ficas. En febrero de 2022, Future Fund anunci\u00f3 sus planes para desplegar m\u00e1s de $100 millones en su primer a\u00f1o y superar hasta $1 mil millones en donaciones.<\/p>\n\n\n\n<p>Los fiscales de Estados Unidos tambi\u00e9n est\u00e1n investigando las donaciones de FTX a partidos pol\u00edticos y candidatos. Curiosamente, con contribuciones por un total de $5,2 millones, Bankman-Fried fue el segundo mayor \u201ccontribuyente CEO\u201d de la campa\u00f1a 2020 de Joe Biden.<\/p>\n\n\n\n<p>Las empresas y los inversores pueden verse obligados a reembolsar miles de millones de d\u00f3lares donados en los meses previos al colapso de FTX. Seg\u00fan la nueva direcci\u00f3n de FTX, &quot;varios destinatarios de contribuciones u otros pagos&quot; se han puesto en contacto con la empresa para devolver los fondos.<\/p>","protected":false},"excerpt":{"rendered":"<p>The problems associated with crypto exchange FTX do not seem to end, as the United States Trustee recently challenged the plans of the once-leading crypto exchange platform to sell its digital currency and clearinghouse LedgerX, along with those of other businesses. According to a recent report by Reuters, on January 7, U.S. Trustee Andrew Vara [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":41645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[],"class_list":["post-41498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/FTX-2-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/es\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The problems associated with crypto exchange FTX do not seem to end, as the United States Trustee recently challenged the plans of the once-leading crypto exchange platform to sell its digital currency and clearinghouse LedgerX, along with those of other businesses. According to a recent report by Reuters, on January 7, U.S. Trustee Andrew Vara&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/41498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/comments?post=41498"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/posts\/41498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media\/41645"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/media?parent=41498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/categories?post=41498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/es\/wp-json\/wp\/v2\/tags?post=41498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}