{"id":20995,"date":"2022-08-24T05:17:38","date_gmt":"2022-08-24T05:17:38","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=20995"},"modified":"2022-08-24T05:17:46","modified_gmt":"2022-08-24T05:17:46","slug":"bitfinex-debuts-new-chain-split-tokens","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/bitfinex-debuts-new-chain-split-tokens\/","title":{"rendered":"Bitfinex lance de nouveaux jetons de division de cha\u00eene avant la fusion d&#039;Ethereum"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Bitfinex, la plate-forme de crypto-trading bas\u00e9e aux \u00eeles Vierges britanniques, a annonc\u00e9 le lancement de Ethereum (ETH) Chain Split Tokens (CST).<\/strong><\/li><li><strong>Les CST permettront aux utilisateurs d&#039;\u00e9changer sur le prochain \u00e9v\u00e9nement de fork tr\u00e8s attendu dans le protocole de consensus Ethereum.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>\u00c0 l&#039;approche de The Merge d&#039;Ethereum, Bitfinex, plateforme de trading de crypto bas\u00e9e aux \u00eeles Vierges britanniques, a annonc\u00e9 le lancement de jetons Chain Split (CST) Ethereum (ETH).<\/p>\n\n\n\n<p>Selon une annonce r\u00e9cente de l&#039;op\u00e9rateur Bitfinex iFinex Financial Technologies Limited, les CST permettront aux utilisateurs de n\u00e9gocier sur le prochain \u00e9v\u00e9nement tr\u00e8s attendu de fork dans le protocole de consensus Ethereum qui pourrait conduire \u00e0 ETH Proof of Work (PoW) et ETH Proof of Stake ( PdV).&nbsp;<\/p>\n\n\n\n<p>Notamment, iFinex Financial Technologies Limited rendra les nouveaux jetons CST appel\u00e9s ETHW (pour PoW) et ETHS (pour PoS) disponibles en paires de n\u00e9gociation sur les plateformes d\u00e9riv\u00e9es. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abNous sommes ravis de permettre \u00e0 nos utilisateurs d&#039;acc\u00e9der \u00e0 ces nouveaux jetons Ethereum Chain Split pour les aider \u00e0 se pr\u00e9parer \u00e0 toutes les \u00e9ventualit\u00e9s \u00e0 l&#039;approche de la fusion Ethereum.\u00bb<\/p><cite>Le directeur de la technologie (CTO) de Bitfinex Derivatives, Paolo Ardoino, a d\u00e9clar\u00e9.<\/cite><\/blockquote>\n\n\n\n<p>De plus, le chef de produit chez Bitfinex Derivatives, Jag Kooner, a expliqu\u00e9 qu&#039;en plus d&#039;essayer de fournir la meilleure exp\u00e9rience \u00e0 ses clients, la soci\u00e9t\u00e9 demande \u00e9galement leurs commentaires lors de la conception de tels produits.<\/p>\n\n\n\n<p>Notamment, iFinex Financial Technologies Limited, qui a \u00e9t\u00e9 cr\u00e9\u00e9e en septembre 2019, propose un service de d\u00e9riv\u00e9s accessible via Bitfinex.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bitfinex d\u00e9crit trois cas possibles<\/h2>\n\n\n\n<p>Dans l&#039;annonce, Bitfinex Derivatives a d\u00e9crit trois sc\u00e9narios potentiels et les r\u00f4les des jetons ETHW et ETHS dans ces situations pour donner aux utilisateurs la possibilit\u00e9 de se pr\u00e9parer \u00e0 divers r\u00e9sultats.<\/p>\n\n\n\n<p>Selon la soci\u00e9t\u00e9, si la fusion n&#039;entra\u00eene pas de changement de consensus sur l&#039;Ethereum actuel (cha\u00eene PoW), l&#039;ETHS expirera et l&#039;ETH sera donn\u00e9 en \u00e9change de chaque avoir ETHW. Cependant, si l\u2019\u00e9v\u00e9nement r\u00e9ussit et que le consensus change pour la cha\u00eene Ethereum PoS sans fork, ETHW expirera et Bitfinex fournira une quantit\u00e9 \u00e9quivalente d\u2019ETH pour les avoirs ETHS.<\/p>\n\n\n\n<p>De plus, les utilisateurs recevront leurs pi\u00e8ces ETHW et ETHS correspondantes si le changement de fourchette et de consensus pour Ethereum r\u00e9ussit.&nbsp;<\/p>\n\n\n\n<p>Lorsqu&#039;un utilisateur cr\u00e9e des CST \u00e0 l&#039;aide du gestionnaire de jetons, ETH sera d\u00e9bit\u00e9 de son compte et une quantit\u00e9 correspondante d&#039;ETHW\/ETHS sera cr\u00e9dit\u00e9e. De plus, les utilisateurs auront la possibilit\u00e9 d&#039;inverser ce processus \u00e0 tout moment en \u00e9changeant une quantit\u00e9 \u00e9gale d&#039;ETHW et d&#039;ETHS contre de l&#039;ETH. Il est important de noter que ces CST expireront \u00e0 la fin de l&#039;ann\u00e9e, soit le 31 d\u00e9cembre 2022.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bitfinex, plateforme de trading de crypto bas\u00e9e aux \u00celes Vierges britanniques, a annonc\u00e9 le lancement des jetons Chain Split (CST) Ethereum (ETH). Les CST permettront aux utilisateurs de n\u00e9gocier sur le prochain \u00e9v\u00e9nement fork tr\u00e8s attendu du protocole de consensus Ethereum. \u00c0 l&#039;approche de The Merge d&#039;Ethereum, Bitfinex, plateforme de trading de crypto bas\u00e9e aux \u00eeles Vierges britanniques, a annonc\u00e9 le lancement d&#039;Ethereum (ETH) [\u2026]<\/p>","protected":false},"author":21,"featured_media":21004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[12],"tags":[1156],"class_list":["post-20995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bitfinex"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Bitfinex-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"British Virgin Islands-based crypto trading platform Bitfinex has announced the launch of Ethereum (ETH) Chain Split Tokens (CSTs). The CSTs will allow users to trade on the upcoming highly-anticipated fork event in the Ethereum consensus protocol. As Ethereum\u2019s The Merge approaches, British Virgin Islands-based crypto trading platform Bitfinex has announced the launch of Ethereum (ETH)\u2026","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/20995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=20995"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/20995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/21004"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=20995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=20995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=20995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}