{"id":21145,"date":"2022-08-25T05:48:31","date_gmt":"2022-08-25T05:48:31","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=21145"},"modified":"2022-08-25T05:48:38","modified_gmt":"2022-08-25T05:48:38","slug":"miami-crew-charged-for-running-crypto-fraud","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/miami-crew-charged-for-running-crypto-fraud\/","title":{"rendered":"L&#039;\u00e9quipage de Miami accus\u00e9 d&#039;avoir ex\u00e9cut\u00e9 un stratag\u00e8me de fraude \u00e0 la cryptographie"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Le DoJ a inculp\u00e9 trois r\u00e9sidents de Miami \u2013 Esteban Cabrera Da Corte, Luis Hernandez Gonzalez et Asdrubal Ramirez Meza \u2013 pour avoir pr\u00e9tendument fraud\u00e9 des banques et une plateforme de cryptographie.<\/strong><\/li><li><strong>Les trois individus, qui seront pr\u00e9sent\u00e9s devant le tribunal de district am\u00e9ricain du district sud de la Floride, ont achet\u00e9 des actifs num\u00e9riques en utilisant de fausses identit\u00e9s.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Le minist\u00e8re de la Justice des \u00c9tats-Unis (DOJ) semble lancer une s\u00e9rie d\u2019attaques contre les escroqueries li\u00e9es \u00e0 la cryptographie. R\u00e9cemment, le minist\u00e8re de la Justice a inculp\u00e9 trois r\u00e9sidents de Miami \u2013 Esteban Cabrera Da Corte, Luis Hernandez Gonzalez et Asdrubal Ramirez Meza \u2013 pour avoir pr\u00e9tendument fraud\u00e9 des banques et une plateforme de cryptographie afin de voler plus de $4 millions.<\/p>\n\n\n\n<p>Selon le r\u00e9cent <a href=\"https:\/\/www.justice.gov\/usao-sdny\/pr\/three-members-miami-crew-charged-defrauding-banks-and-cryptocurrency-exchange-more-4\" rel=\"nofollow noopener\" target=\"_blank\">annonce<\/a>, les trois individus, qui seront pr\u00e9sent\u00e9s devant le tribunal de district am\u00e9ricain du district sud de la Floride, ont achet\u00e9 des actifs num\u00e9riques en utilisant de fausses identit\u00e9s. Apr\u00e8s cela, ils ont menti aux institutions financi\u00e8res que les transactions n&#039;\u00e9taient pas autoris\u00e9es, demandant un remboursement afin de gagner plus. Ils ont tromp\u00e9 les banques pour qu&#039;elles annulent ces transactions et red\u00e9posent les fonds sur les comptes bancaires contr\u00f4l\u00e9s par les d\u00e9fendeurs. Le trio a ensuite retir\u00e9 l&#039;argent des comptes bancaires. Le trio pourrait passer jusqu&#039;\u00e0 30 ans dans une prison f\u00e9d\u00e9rale pour leur crime.<\/p>\n\n\n\n<p>Le procureur am\u00e9ricain a expliqu\u00e9 que le trio avait tromp\u00e9 \u00ab les banques am\u00e9ricaines en leur faisant croire qu&#039;elles \u00e9taient elles-m\u00eames victimes de la fraude de quelqu&#039;un d&#039;autre \u00bb alors qu&#039;elles utilisaient des identit\u00e9s vol\u00e9es. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Gr\u00e2ce aux efforts du groupe de travail El Dorado [des enqu\u00eates sur la s\u00e9curit\u00e9 int\u00e9rieure], leur duplicit\u00e9 a \u00e9t\u00e9 d\u00e9couverte et ils font d\u00e9sormais face \u00e0 de graves accusations f\u00e9d\u00e9rales\u00a0\u00bb<\/p><cite>Il ajouta.<\/cite><\/blockquote>\n\n\n\n<p>Notamment, le HSI a identifi\u00e9 les violations et organis\u00e9 l&#039;arrestation. Il s&#039;est engag\u00e9 \u00e0 continuer \u00e0 travailler avec ses partenaires du district sud de New York pour lutter contre toute forme future de fraude cryptographique. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Cabrera, Hernandez et Ramirez ont coordonn\u00e9 cette op\u00e9ration \u00e0 grande \u00e9chelle visant \u00e0 blanchir des millions de dollars via des bourses de crypto-monnaie et des banques am\u00e9ricaines, exploitant finalement \u00e0 la fois le march\u00e9 des devises virtuelles et le syst\u00e8me financier am\u00e9ricain.&quot;<\/p><cite>Ricky J. Patel, agent sp\u00e9cial par int\u00e9rim de HSI, a d\u00e9clar\u00e9.<\/cite><\/blockquote>\n\n\n\n<p>Les accus\u00e9s ont cr\u00e9\u00e9 des comptes sur l&#039;\u00e9change cryptographique pour mener \u00e0 bien ce stratag\u00e8me frauduleux, en utilisant fr\u00e9quemment des images de faux passeports am\u00e9ricains, de faux permis de conduire et des informations personnelles vol\u00e9es. Les comptes bancaires d\u00e9tenus par les accus\u00e9s \u00e9taient li\u00e9s aux comptes d\u2019\u00e9change de crypto-monnaie. Les accus\u00e9s effectuaient souvent une s\u00e9rie de d\u00e9p\u00f4ts en esp\u00e8ces \u00e0 l\u2019aide de distributeurs automatiques sur les comptes bancaires associ\u00e9s pour acheter des crypto-monnaies. Ensuite, les accus\u00e9s et leurs complices ont rapidement transf\u00e9r\u00e9 ces jetons vers d&#039;autres portefeuilles qu&#039;ils contr\u00f4laient et qui n&#039;\u00e9taient pas connect\u00e9s \u00e0 l&#039;\u00e9change cryptographique. \u00c0 la suite du transfert de crypto-monnaie, les accus\u00e9s ont ill\u00e9galement affirm\u00e9 que les achats de crypto-monnaie n&#039;\u00e9taient pas autoris\u00e9s via des appels t\u00e9l\u00e9phoniques aux banques am\u00e9ricaines, ce qui a conduit les banques \u00e0 annuler les transactions.<\/p>\n\n\n\n<p>Les trois fraudeurs bas\u00e9s \u00e0 Miami sont accus\u00e9s de \u00ab complot en vue de commettre une fraude \u00e9lectronique et une fraude bancaire, passibles d&#039;une peine maximale de 30 ans de prison, de fraude \u00e9lectronique, passible d&#039;une peine maximale de 20 ans de prison, et d&#039;usurpation d&#039;identit\u00e9 aggrav\u00e9e, qui est passible d&#039;une peine maximale de 30 ans de prison. est passible d\u2019une peine minimale obligatoire de 2 ans de prison.<\/p>\n\n\n\n<p>De plus, l&#039;annonce r\u00e9v\u00e8le que Cabrera est \u00e9galement accus\u00e9 de s&#039;\u00eatre engag\u00e9 dans une transaction financi\u00e8re en utilisant des actifs obtenus par fraude \u00e9lectronique et fraude bancaire, un crime passible de dix ans de prison.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le DoJ a inculp\u00e9 trois r\u00e9sidents de Miami \u2013 Esteban Cabrera Da Corte, Luis Hernandez Gonzalez et Asdrubal Ramirez Meza \u2013 pour avoir pr\u00e9tendument fraud\u00e9 des banques et une plateforme de cryptographie. Les trois individus, qui seront pr\u00e9sent\u00e9s devant le tribunal de district am\u00e9ricain du district sud de Floride, ont achet\u00e9 des actifs num\u00e9riques en utilisant de fausses identit\u00e9s. Le minist\u00e8re de la Justice des \u00c9tats-Unis (DOJ) semble [\u2026]<\/p>","protected":false},"author":21,"featured_media":21148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-21145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Miami-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The DoJ charged three Miami residents\u2014Esteban Cabrera Da Corte, Luis Hernandez Gonzalez, and Asdrubal Ramirez Meza\u2014for allegedly defrauding banks and a crypto platform. The three individuals, who will be presented in the U.S. District Court for the Southern District of Florida, purchased digital assets using false identities. The United States Department of Justice (DOJ) seems\u2026","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/21145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=21145"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/21145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/21148"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=21145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=21145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=21145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}