{"id":23150,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=23150"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"btbt-stock-up-1-3-bit-digital-reports-profitable-22q2-earnings-results","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/btbt-stock-up-1-3-bit-digital-reports-profitable-22q2-earnings-results\/","title":{"rendered":"BTBT Stock Up 1.3%, Bit Digital annonce des r\u00e9sultats rentables pour le 22T2\u00a0"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Bit Digital a gagn\u00e9 197,28 Bitcoins et 104,29 ETH au cours du deuxi\u00e8me trimestre, qui s&#039;est termin\u00e9 le 30 juin.<\/strong><\/li><li><strong>La soci\u00e9t\u00e9 a re\u00e7u les 10 000 mineurs pr\u00e9c\u00e9demment annonc\u00e9s achet\u00e9s \u00e0 Bitmain.<\/strong><\/li><li><strong>Bit Digital, qui appartient \u00e0 l&#039;industrie des services technologiques de Zacks, a rat\u00e9 l&#039;estimation du consensus de Zacks de 52,34 %.<\/strong><\/li><\/ul>\n<hr>\n\n\n\n<p>Bit Digital Inc. (Nasdaq : BTBT), une soci\u00e9t\u00e9 mini\u00e8re de crypto-monnaie bas\u00e9e \u00e0 New York, a annonc\u00e9 ses r\u00e9sultats non audit\u00e9s du deuxi\u00e8me trimestre. Pour les trois mois se terminant le 30 juin 2022, Bit Digital a d\u00e9clar\u00e9 des revenus de $6,5 millions provenant de ses op\u00e9rations mini\u00e8res Bitcoin. De plus, la soci\u00e9t\u00e9 a d\u00e9clar\u00e9 un chiffre d&#039;affaires de $0,3 million provenant des op\u00e9rations mini\u00e8res d&#039;Ethereum.<\/p>\n\n\n\n<p>En d&#039;autres termes, Bit Digital a gagn\u00e9 197,28 <a href=\"https:\/\/bitcoinwisdom.com\/fr\/bitcoin-price-falls-below-20k-total-crypto-market-cap-under-1t\/\">Bitcoins<\/a> et 104,29 ETH au cours du deuxi\u00e8me trimestre, qui s&#039;est termin\u00e9 le 30 juin. <a href=\"https:\/\/pricepredictions.com\/forecast\/ethereum\" rel=\"nofollow noopener\" target=\"_blank\">EPF<\/a> \u00e0 860,57 et 313,56 respectivement.<\/p>\n\n\n\n<p>Selon certaines informations, la soci\u00e9t\u00e9 poss\u00e9dait 38 135 mineurs de bitcoins et 731 mineurs d&#039;Ethereum au 30 juin 2022. De plus, la soci\u00e9t\u00e9 a d\u00e9clar\u00e9 que les mineurs de BTC et d&#039;ETH avaient un taux de hachage total maximum estim\u00e9 \u00e0 2,7 EH\/s et 0,3 TH\/s, respectivement.<\/p>\n\n\n\n<p>Il convient de noter que la soci\u00e9t\u00e9 a re\u00e7u les 10 000 mineurs pr\u00e9c\u00e9demment annonc\u00e9s achet\u00e9s \u00e0 Bitmain. Suite aux mineurs d&#039;actifs num\u00e9riques suppl\u00e9mentaires, la soci\u00e9t\u00e9 a sign\u00e9 un nouvel accord d&#039;h\u00e9bergement de 20 MW avec Coinmint LLC.<\/p>\n\n\n\n<p>Bit Digital a annonc\u00e9 avoir vendu 903 mineurs MicroBT Whatsminer M21S Bitcoin et 9 mineurs MicroBT Whatsminer M20S Bitcoin au cours du trimestre.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Apr\u00e8s la fin du trimestre, nous avons \u00e9galement annonc\u00e9 un nouvel accord d&#039;h\u00e9bergement de 5\u00a0MW avec un fournisseur au Canada dans un site principalement hydro\u00e9lectrique\u2026 Nous avons termin\u00e9 le trimestre avec $45 millions en esp\u00e8ces, plus de $70 millions de liquidit\u00e9s totales, aucune dette. , et aucune obligation d&#039;achat de mineur en cours \u00bb, Gestion de Bit Digital <a href=\"https:\/\/www.prnewswire.com\/news-releases\/bit-digital-inc-announces-second-quarter-of-fiscal-year-2022-financial-results-301614926.html\" rel=\"nofollow noopener\" target=\"_blank\">c&#039;est not\u00e9<\/a>.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Bit Digital et les perspectives du march\u00e9<\/h2>\n\n\n\n<p>Suite au rapport non audit\u00e9 du 22\u00e8me trimestre, le march\u00e9 boursier de la soci\u00e9t\u00e9 a gagn\u00e9 environ 1 pour cent aujourd&#039;hui, selon les donn\u00e9es fournies par <a href=\"https:\/\/www.marketwatch.com\/investing\/stock\/btbt?mod=search_symbol\" rel=\"nofollow noopener\" target=\"_blank\">MarketWatch<\/a>. Cependant, le march\u00e9 boursier de la soci\u00e9t\u00e9 a baiss\u00e9 d&#039;environ 88% au cours de la derni\u00e8re ann\u00e9e.<\/p>\n\n\n\n<p>Notamment, le march\u00e9 boursier de Bit Digital a enregistr\u00e9 des pertes importantes au cours de l\u2019ann\u00e9e \u00e9coul\u00e9e, une situation similaire dans le secteur des cryptomonnaies. Selon nos donn\u00e9es de march\u00e9, le prix du Bitcoin se n\u00e9gocie \u00e0 <span data-realtime=\"on\"><span data-live-price=\"BTCUSDT\" data-price=\"77181.94310649677936\" data-rate=\"1\" data-currency=\"USD\"><b class=\"fiat-symbol\">$<\/b><span>77,181.94<\/span><\/span><\/span>, en baisse d&#039;environ 70\u00a0% par rapport \u00e0 l&#039;ATH.<\/p>\n\n\n\n<p>La soci\u00e9t\u00e9 a une valorisation boursi\u00e8re rapport\u00e9e d&#039;environ $120 millions avec 82,43 millions d&#039;actions en circulation.&nbsp;<\/p>\n\n\n\n<p>Bit Digital, qui appartient \u00e0 l&#039;industrie des services technologiques de Zacks, a rat\u00e9 l&#039;estimation du consensus de Zacks de 52,34 %. En outre, la soci\u00e9t\u00e9 a d\u00e9clar\u00e9 des revenus de $28,34 millions il y a un an au m\u00eame trimestre. Depuis lors, la soci\u00e9t\u00e9 n&#039;a pas \u00e9t\u00e9 en mesure de battre les estimations de revenus consensuelles au cours des quatre derniers trimestres.<\/p>\n\n\n\n<p>\u00c0 l&#039;avenir, les analystes ont \u00e9tabli une estimation des b\u00e9n\u00e9fices bas\u00e9e sur le portefeuille d&#039;investissement de l&#039;entreprise. Selon <a href=\"https:\/\/www.zacks.com\/stock\/news\/1974281\/bit-digital-inc-btbt-reports-q2-loss-misses-revenue-estimates?cid=CS-MKTWTCH-HL-tale_of_the_tape%7Cyseop_template_4-1974281&amp;mod=mw_quote_news\" rel=\"nofollow noopener\" target=\"_blank\">Estimations de Zacks<\/a>, l&#039;estimation consensuelle actuelle du BPA est de $0,03 sur $21,1 millions de revenus pour le trimestre \u00e0 venir et de $0,15 sur $73 millions de revenus pour l&#039;exercice en cours.<\/p>\n\n\n\n<p>La soci\u00e9t\u00e9 est cependant fortement investie dans un march\u00e9 volatil des crypto-monnaies hautement impr\u00e9visible. Par cons\u00e9quent, les estimations peuvent ou non jouer selon les attentes. De plus, le march\u00e9 de la crypto-monnaie est entach\u00e9 de sp\u00e9culations folles depuis sa cr\u00e9ation.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bit Digital a gagn\u00e9 197,28 Bitcoins et 104,29 ETH au cours du deuxi\u00e8me trimestre, qui s&#039;est termin\u00e9 le 30 juin.<\/p>","protected":false},"author":18,"featured_media":23207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1628],"class_list":["post-23150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bit-digital"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577.jpg",1600,1067,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-300x200.jpg",300,200,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-768x512.jpg",640,427,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577.jpg",1600,1067,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Rebecca Davidson","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/rebeccad\/"},"uagb_comment_info":0,"uagb_excerpt":"Bit Digital earned 197.28 Bitcoins and 104.29 ETH during the second quarter, which ended on June 30.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/23150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=23150"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/23150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/23207"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=23150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=23150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=23150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}