{"id":25009,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=25009"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"the-ethereum-merge-is-complete-proof-of-stake-is-live-eth-price-down","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/the-ethereum-merge-is-complete-proof-of-stake-is-live-eth-price-down\/","title":{"rendered":"La fusion Ethereum est termin\u00e9e, la preuve de participation est en direct, Eth Price Down"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Le prix Ethereum se n\u00e9gocie \u00e0 <span data-realtime=\"on\"><span data-live-price=\"ETHUSDT\" data-price=\"2385.10590434940286\" data-rate=\"1\" data-currency=\"USD\"><b class=\"fiat-symbol\">$<\/b><span>2,385.11<\/span><\/span><\/span>, en baisse d&#039;environ 1,5 % au cours des derni\u00e8res 24 heures.<\/strong><\/li><li><strong>Avec l&#039;industrie mini\u00e8re ETH en baisse, la logistique de toute personne validant les transactions Ethereum est r\u00e9alisable.&nbsp;<\/strong><\/li><li><strong>La fusion a ouvert la voie \u00e0 d&#039;autres mises \u00e0 niveau d&#039;\u00e9volutivit\u00e9 qui n&#039;\u00e9taient pas possibles dans le cadre du consensus sur la preuve de travail (PoW).<\/strong><\/li><\/ul>\n<hr>\n\n\n\n<p>Le r\u00e9seau Ethereum (ETH) est d\u00e9sormais enti\u00e8rement s\u00e9curis\u00e9 par l&#039;algorithme de consensus Proof-of-Stake (PoS). La mise \u00e0 niveau de Paris, le dernier obstacle vers la fusion, a atteint une difficult\u00e9 totale du terminal de 58750000000000000000000. La cha\u00eene de balises fonctionne actuellement avec des milliers de validateurs qui ont jalonn\u00e9 plus de 14 millions d&#039;ETH.<\/p>\n\n\n\n<p>Suivant le <a href=\"https:\/\/bitcoinwisdom.com\/fr\/ethereum-eth-price-up-6-bellatrix-hard-fork-happens-today-in-preparation-for-the-merge\/\">Fusionner<\/a> mise \u00e0 niveau, le r\u00e9seau Ethereum est hors du radar des r\u00e9gulateurs sur la consommation d&#039;\u00e9lectricit\u00e9. L&#039;\u00e9cosyst\u00e8me Ethereum aurait consomm\u00e9 environ 0,2 % de l&#039;\u00e9lectricit\u00e9 produite dans le monde. Cependant, la mise \u00e0 niveau a contribu\u00e9 \u00e0 r\u00e9duire l&#039;empreinte carbone de la crypto-monnaie, qui est une mission de la plupart des pays.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Et nous avons finalis\u00e9 !<br><br>Bonne fusion \u00e0 tous. C&#039;est un grand moment pour l&#039;\u00e9cosyst\u00e8me Ethereum. Tous ceux qui ont contribu\u00e9 \u00e0 la r\u00e9alisation de la fusion devraient \u00eatre tr\u00e8s fiers aujourd&#039;hui.<\/p>\u2013 vitalik.eth (@VitalikButerin) <a href=\"https:\/\/twitter.com\/VitalikButerin\/status\/1570306185391378434?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">15 septembre 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Et apr\u00e8s la fusion d&#039;Ethereum<\/h2>\n\n\n\n<p>Selon nos donn\u00e9es de march\u00e9, le prix d&#039;Ethereum se n\u00e9gocie \u00e0 <span data-realtime=\"on\"><span data-live-price=\"ETHUSDT\" data-price=\"2385.10590434940286\" data-rate=\"1\" data-currency=\"USD\"><b class=\"fiat-symbol\">$<\/b><span>2,385.11<\/span><\/span><\/span>, en baisse d&#039;environ 1,5 % au cours des derni\u00e8res 24 heures. La capitalisation boursi\u00e8re totale de la cryptographie est d&#039;environ $1,03 billion, en baisse d&#039;environ 1%.<\/p>\n\n\n\n<p>Malgr\u00e9 la tendance \u00e0 la baisse du march\u00e9 de la crypto-monnaie, il a \u00e9t\u00e9 rapport\u00e9 que les investisseurs institutionnels inondent l&#039;industrie.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Malgr\u00e9 des cycles \u00e0 court terme, l&#039;\u00e9lan de l&#039;adoption institutionnelle va dans un sens - vers plus d&#039;exploration et plus d&#039;int\u00e9r\u00eat&quot;, a d\u00e9clar\u00e9 Greg Tusar, vice-pr\u00e9sident des produits institutionnels chez <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/fr\/coinbase-review\/\" title=\"Coinbase\" data-wpil-keyword-link=\"linked\">Coinbase<\/a>.<\/p><\/blockquote>\n\n\n\n<p>Cependant, les effets de la fusion pourraient se mat\u00e9rialiser dans les mois \u00e0 venir. De plus, les march\u00e9s haussiers de la crypto-monnaie dans le pass\u00e9 ont eu lieu un an apr\u00e8s la r\u00e9duction de moiti\u00e9 du Bitcoin.<\/p>\n\n\n\n<p>Le d\u00e9but de la fusion a des effets consid\u00e9rables sur l&#039;ensemble du march\u00e9 de la cryptographie, en particulier sur les investisseurs. Rappelez-vous, la fusion est en pr\u00e9paration depuis six ans, avec plusieurs reports dans le pass\u00e9. En tant que hard fork, tous les actionnaires devaient se mettre d&#039;accord, ce qui en faisait un \u00e9v\u00e9nement majeur.<\/p>\n\n\n\n<p>Avec l&#039;industrie mini\u00e8re ETH en baisse, la logistique de toute personne validant les transactions Ethereum est r\u00e9alisable. De plus, il ne faut que 32 unit\u00e9s d&#039;ETH pour qu&#039;une seule devienne un n\u0153ud complet <a href=\"https:\/\/ethereum.org\/en\/staking\/\" rel=\"nofollow noopener\" target=\"_blank\">validateur<\/a>.&nbsp;<\/p>\n\n\n\n<p>Ayant prouv\u00e9 que les r\u00e9seaux d\u00e9centralis\u00e9s peuvent coordonner un hard fork majeur de mani\u00e8re transparente, davantage d&#039;investisseurs institutionnels sont susceptibles de sauter dans le wagon crypto.<\/p>\n\n\n\n<p>La fusion a ouvert la voie \u00e0 d&#039;autres mises \u00e0 niveau d&#039;\u00e9volutivit\u00e9 qui n&#039;\u00e9taient pas possibles dans le cadre du consensus sur la preuve de travail (PoW). Par cons\u00e9quent, le r\u00e9seau Ethereum est un pas de plus vers la r\u00e9alisation de la mission \u00e0 grande \u00e9chelle, de s\u00e9curit\u00e9 et de durabilit\u00e9.<\/p>\n\n\n\n<p>Il existe une gamme de mises \u00e0 niveau mises en place apr\u00e8s une fusion ETH r\u00e9ussie. De plus, le <a href=\"https:\/\/bitcoinwisdom.com\/fr\/buterin-on-his-plans-post-the-ethereum-merge\/\">Fusionner la mise \u00e0 niveau<\/a> n&#039;incluait pas certaines fonctionnalit\u00e9s anticip\u00e9es telles que la possibilit\u00e9 de retirer des ETH jalonn\u00e9s. Par cons\u00e9quent, la mise \u00e0 niveau de Shanghai devrait suivre apr\u00e8s la fusion, ce qui permettra aux validateurs de retirer les actifs jalonn\u00e9s.<\/p>\n\n\n\n<p>L&#039;autre mise \u00e0 jour majeure qui fait l&#039;objet d&#039;un litige en raison de l&#039;existence de cumuls de couche 2 est la mise \u00e0 niveau de Sharding. Selon certaines informations, la mise \u00e0 niveau du sharding devrait avoir lieu un peu plus tard en 2023. Notamment, le sharding est le processus de division horizontale d&#039;une base de donn\u00e9es pour r\u00e9partir la charge sur une blockchain.<\/p>","protected":false},"excerpt":{"rendered":"<p>Avec l&#039;industrie mini\u00e8re ETH en baisse, la logistique de toute personne validant les transactions Ethereum est r\u00e9alisable.\u00a0<\/p>","protected":false},"author":18,"featured_media":25013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[186,12],"tags":[],"class_list":["post-25009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ethereum-news","category-news"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124.jpg",1280,853,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124-300x200.jpg",300,200,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124-768x512.jpg",640,427,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124-1024x682.jpg",640,426,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124.jpg",1280,853,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124.jpg",1280,853,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/6286124-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Rebecca Davidson","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/rebeccad\/"},"uagb_comment_info":0,"uagb_excerpt":"With the ETH mining industry down onwards, the logistics of anyone validating Ethereum transactions are achievable.\u00a0","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/25009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=25009"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/25009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/25013"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=25009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=25009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=25009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}