{"id":30669,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=30669"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"chainalysis-october-worst-month-in-crypto","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/chainalysis-october-worst-month-in-crypto\/","title":{"rendered":"Chainalysis\u00a0: octobre, le pire mois de ce qui est peut-\u00eatre la pire ann\u00e9e pour la cryptographie"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Environ 11 hacks ont \u00e9t\u00e9 mis en \u0153uvre jusqu&#039;\u00e0 pr\u00e9sent en octobre et les investisseurs ont vu des attaquants drainer environ $718 millions des plates-formes DeFi et des ponts \u00e0 cha\u00eenes crois\u00e9es. <\/strong><\/li><li><strong>Chainalysis confirme que jusqu&#039;\u00e0 pr\u00e9sent en 2022, il y a eu 125 hacks et les pirates ont emport\u00e9 $3 milliards de fonds des investisseurs. <\/strong><\/li><li><strong>En octobre, nous avons vu Zcash, BSC Token Hub et Mango Markets se faire exploiter et \u00e0 ce rythme, 2022 pourrait devenir la pire ann\u00e9e pour la cryptographie.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Le mois d&#039;octobre a \u00e9t\u00e9 assez actif dans l&#039;espace crypto en ce qui concerne le nombre de hacks mis en \u0153uvre dans le monde de DeFi. Selon un rapport de la soci\u00e9t\u00e9 d&#039;analyse blockchain Chainalysis, octobre est le mois avec le plus grand nombre d&#039;exploits et de piratages en 2022, qui est peut-\u00eatre la pire ann\u00e9e dans l&#039;espace crypto. <\/p>\n\n\n\n<p>En 2022, la majorit\u00e9 des crypto-monnaies ont corrig\u00e9 les gains qu&#039;elles avaient r\u00e9alis\u00e9s lors du boom de l&#039;espace crypto en 2021, et les valorisations des entreprises, ainsi que les prix des NFT, les volumes de transactions, se sont tous effondr\u00e9s. Cela a \u00e9t\u00e9 aggrav\u00e9 par la faillite des plateformes de pr\u00eat de crypto <a href=\"https:\/\/bitcoinwisdom.com\/fr\/celsius-has-enough-cash-to-last-until-year-end\/\" class=\"ek-link\">R\u00e9seau Celsius<\/a>, Vauld et Voyager Digital, ainsi que l&#039;ancien fonds sp\u00e9culatif <a href=\"https:\/\/bitcoinwisdom.com\/fr\/court-documents-show-that-three-arrows-capital-3ac-owes-moonbeam-foundation-more-than-27-million\/\" class=\"ek-link\">Capitale des Trois Fl\u00e8ches<\/a>. L&#039;effondrement de l&#039;\u00e9cosyst\u00e8me Terra a \u00e9t\u00e9 un autre \u00e9v\u00e9nement triste qui a effac\u00e9 pr\u00e8s de $40 milliards de l&#039;espace crypto. <\/p>\n\n\n\n<p>Cependant, cela ne suffisait pas. Selon les nouvelles donn\u00e9es de Chainalysis, &quot;Octobre est d\u00e9sormais le mois le plus important de la plus grande ann\u00e9e jamais enregistr\u00e9e pour les activit\u00e9s de piratage, avec plus de la moiti\u00e9 du mois \u00e0 parcourir. Jusqu&#039;\u00e0 pr\u00e9sent ce mois-ci, $718 millions ont \u00e9t\u00e9 vol\u00e9s aux protocoles #DeFi sur 11 hacks diff\u00e9rents.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">1\/ Apr\u00e8s quatre piratages hier, octobre est d\u00e9sormais le mois le plus important de la plus grande ann\u00e9e jamais enregistr\u00e9e pour l&#039;activit\u00e9 de piratage, avec plus de la moiti\u00e9 du mois \u00e0 parcourir. Jusqu&#039;\u00e0 pr\u00e9sent ce mois-ci, $718 millions ont \u00e9t\u00e9 vol\u00e9s \u00e0 <a href=\"https:\/\/twitter.com\/hashtag\/DeFi?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#DeFi<\/a> protocoles \u00e0 travers 11 hacks diff\u00e9rents. <a href=\"https:\/\/t.co\/emz36f6gpK\" rel=\"nofollow\">pic.twitter.com\/emz36f6gpK<\/a><\/p>\u2014 Chainalysis (@chainalysis) <a href=\"https:\/\/twitter.com\/chainalysis\/status\/1580312145451180032?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">12 octobre 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Au cours des 2 premi\u00e8res semaines d&#039;octobre m\u00eame, il y a eu quatre attaques contre des protocoles cryptographiques et des \u00e9changes d\u00e9centralis\u00e9s.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00c0 ce rythme, 2022 d\u00e9passera probablement 2021 comme la plus grande ann\u00e9e de piratage jamais enregistr\u00e9e. Jusqu&#039;\u00e0 pr\u00e9sent, les pirates ont rapport\u00e9 plus de $3 milliards de dollars sur 125 hacks \u00bb, <\/p><cite>confirmer dChainalysis dans un autre <a href=\"https:\/\/twitter.com\/chainalysis\/status\/1580312149557026817\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">Publication sur Twitter<\/a>.<\/cite><\/blockquote>\n\n\n\n<p>La soci\u00e9t\u00e9 d&#039;analyse de la blockchain a \u00e9galement soulign\u00e9 qu&#039;il y avait eu un changement de tendance dans ces hacks et exploits dont les investisseurs sont t\u00e9moins dans l&#039;espace crypto. Plus t\u00f4t en 2019, les plates-formes les plus cibl\u00e9es pour les pirates \u00e9taient l&#039;\u00e9change centralis\u00e9, qui comprend le populaire hack d&#039;\u00e9change Mt. Gox ou m\u00eame l&#039;exploit d&#039;\u00e9change Bitfinex. Cependant, les temps ont chang\u00e9 et maintenant, les hacks ont trouv\u00e9 de nouvelles fa\u00e7ons de mettre en \u0153uvre leurs attaques. <\/p>\n\n\n\n<p>Selon Chainalaysis, les pirates informatiques ciblent de plus en plus les protocoles financiers d\u00e9centralis\u00e9s et cela aussi, il y a un fort pourcentage de ponts inter-cha\u00eenes pirat\u00e9s ou exploit\u00e9s. En effet, les ponts inter-cha\u00eenes sont responsables de la connexion de deux cha\u00eenes de blocs, ce qui sugg\u00e8re que des vuln\u00e9rabilit\u00e9s peuvent \u00eatre attendues.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Les ponts inter-cha\u00eenes restent une cible majeure pour les pirates, avec 3 ponts pirat\u00e9s ce mois-ci et pr\u00e8s de $600 millions vol\u00e9s, ce qui repr\u00e9sente 82% de pertes ce mois-ci et 64% de pertes toute l&#039;ann\u00e9e&quot;,<\/p><p><a href=\"https:\/\/twitter.com\/chainalysis\/status\/1580312156892844035\/photo\/1\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/p><cite>a d\u00e9clar\u00e9 le cabinet d&#039;analyse de la blockchain. <\/cite><\/blockquote>\n\n\n\n<p>Fait int\u00e9ressant, en octobre, nous avons vu des pirates informatiques <a href=\"https:\/\/bitcoinwisdom.com\/fr\/binance-hack-bnb-chain-halted-500m-stolen\/\" class=\"ek-link\">exploiter le BSC Token Hub<\/a>, le pont inter-cha\u00eenes qui relie la BNB Beacon Chain (BEP2) et la BNB Chain (BEP20 ou BSC). Cet exploit a vu des pirates s&#039;emparer de plus de $100 millions et il semble que <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/fr\/binance-review\/\" title=\"Binance\" data-wpil-keyword-link=\"linked\">Binance<\/a> L&#039;\u00e9quipe a \u00e9galement \u00e9t\u00e9 sur les traces des pirates. Afin d&#039;isoler le hack, la cha\u00eene subit un hard fork, ont indiqu\u00e9 les d\u00e9veloppeurs. <\/p>\n\n\n\n<p>Un autre piratage important a \u00e9t\u00e9 le piratage de Mango Markets, un \u00e9change d\u00e9centralis\u00e9 sur Solana avec Zcash, une blockchain ax\u00e9e sur la confidentialit\u00e9. <\/p>","protected":false},"excerpt":{"rendered":"<p>Around 11 hacks have been implemented so far in October and investors saw attackers draining around $718 million from DeFi platforms and cross chain bridges. Chainalysis confirms that so far in 2022, there have been 125 hacks and the hackers have made away with $3 billion worth of investors&#8217; funds. In October, we have seen [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":30671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[466],"class_list":["post-30669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-chainalysis"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/10\/Chainalysis-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Around 11 hacks have been implemented so far in October and investors saw attackers draining around $718 million from DeFi platforms and cross chain bridges. Chainalysis confirms that so far in 2022, there have been 125 hacks and the hackers have made away with $3 billion worth of investors&#8217; funds. In October, we have seen\u2026","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/30669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=30669"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/30669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/30671"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=30669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=30669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=30669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}