{"id":40149,"date":"2023-01-02T18:48:09","date_gmt":"2023-01-02T18:48:09","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=40149"},"modified":"2023-01-02T18:48:09","modified_gmt":"2023-01-02T18:48:09","slug":"btc-core-developer-loses-more-than-3-million","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/btc-core-developer-loses-more-than-3-million\/","title":{"rendered":"Le d\u00e9veloppeur de Bitcoin Core perd plus de $3 millions \u00e0 cause d&#039;un piratage"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Les utilisateurs de crypto craignent qu&#039;un d\u00e9veloppeur Bitcoin Core connu pour \u00eatre soucieux de la s\u00e9curit\u00e9 ne soit pirat\u00e9.<\/strong><\/li>\n\n\n\n<li><strong>Certains experts en s\u00e9curit\u00e9 pensent que Luke Dashjr aurait pu commettre des erreurs qui ont compromis son compte.<\/strong><\/li>\n\n\n\n<li><strong>Changpeng Zhao a propos\u00e9 d&#039;aider \u00e0 surveiller la situation et \u00e0 geler le Bitcoin s&#039;il est d\u00e9pos\u00e9 sur Binance.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Un d\u00e9veloppeur Bitcoin s&#039;est rendu sur Twitter pour annoncer que son compte avait \u00e9t\u00e9 attaqu\u00e9 et vid\u00e9 par un pirate informatique, soulevant de nouvelles questions sur la s\u00e9curit\u00e9. Luke Dashjr, qui pr\u00e9tend \u00eatre l&#039;un des premiers d\u00e9veloppeurs de Bitcoin Core, a d\u00e9clar\u00e9 que le <a href=\"https:\/\/bitcoinwisdom.com\/fr\/raydium-suffers-2m-hack\/\" target=\"_blank\" aria-label=\"attaque (s&#039;ouvre dans un nouvel onglet)\" rel=\"noreferrer noopener\" class=\"ek-link\">attaque<\/a> a eu lieu le soir du Nouvel An.<\/p>\n\n\n\n<p>Bien que le total des fonds vol\u00e9s n&#039;ait pas encore \u00e9t\u00e9 d\u00e9termin\u00e9, Dashjr a d\u00e9clar\u00e9 en avoir suivi une partie jusqu&#039;\u00e0 une adresse de portefeuille qui a re\u00e7u environ 217 BTC ($3,6 millions). Dashjr a d\u00e9clar\u00e9 que le piratage \u00e9tait d\u00fb \u00e0 la compromission de sa cl\u00e9 de confidentialit\u00e9 assez bonne (PGP), ajoutant que l&#039;adresse IP de l&#039;attaquant provenait d&#039;un serveur ColoCrossing.<\/p>\n\n\n\n<p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">PSA\u00a0: Ma cl\u00e9 PGP est compromise, et au moins beaucoup de mes bitcoins ont \u00e9t\u00e9 vol\u00e9s. Je n&#039;ai aucune id\u00e9e de comment. Aidez-moi, s&#039;il vous pla\u00eet. <a href=\"https:\/\/twitter.com\/hashtag\/Bitcoin?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#Bitcoin<\/a><\/p>-Luke Dashjr (@LukeDashjr) <a href=\"https:\/\/twitter.com\/LukeDashjr\/status\/1609613748364509184?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">1er janvier 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n\n\n\n<p>Les d\u00e9veloppeurs de Bitcoin Core sont connus pour \u00eatre soucieux de la s\u00e9curit\u00e9, mais Dashjr a d\u00e9clar\u00e9 qu&#039;il n&#039;avait aucune id\u00e9e de la fa\u00e7on dont son portefeuille froid avait \u00e9t\u00e9 pirat\u00e9, ajoutant qu&#039;il l&#039;avait utilis\u00e9 pour la derni\u00e8re fois en septembre. Certains utilisateurs de Twitter ont mentionn\u00e9 une faille de s\u00e9curit\u00e9 \u00e9voqu\u00e9e par Dashjr en novembre comme raison possible du piratage. Cependant, Dashjr a d\u00e9clar\u00e9 qu\u2019il pensait que \u00ab tout \u00e9tait compromis \u00bb, y compris son Twitter. Le d\u00e9veloppeur Bitcoin Core a \u00e9galement d\u00e9conseill\u00e9 \u00e0 ses abonn\u00e9s d\u2019utiliser Bitcoin Knots, un portefeuille Bitcoin sign\u00e9 par sa cl\u00e9 PGP pirat\u00e9e.<\/p>\n\n\n\n<p><a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/fr\/binance-review\/\" title=\"Binance\" data-wpil-keyword-link=\"linked\">Binance<\/a> Le PDG Changpeng Zhao a r\u00e9agi \u00e0 la publication Twitter de Dashjr, proposant d&#039;aider le d\u00e9veloppeur de toutes les mani\u00e8res possibles. Zhao a en outre promis que son \u00e9quipe de s\u00e9curit\u00e9 garderait un \u0153il sur les actifs et gelerait le Bitcoin s&#039;il arrivait sur Binance.<\/p>\n\n\n\n<p>Zhao, qui a \u00e9t\u00e9 un fervent critique des portefeuilles d&#039;auto-garde, a pris le moment de r\u00e9affirmer sa critique, \u00e9crivant dans un <a aria-label=\"message (s&#039;ouvre dans un nouvel onglet)\" href=\"https:\/\/twitter.com\/cz_binance\/status\/1609664451145334784?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1609664451145334784%7Ctwgr%5E90db6b266c3b88b0018093212484f1c6efc3b4da%7Ctwcon%5Es1_&amp;ref_url=https%3A%2F%2Fdecrypt.co%2F118231%2Fbitcoin-core-dev-loses-at-least-3-6-million-btc-to-hack\" target=\"_blank\" rel=\"noreferrer noopener nofollow\" class=\"ek-link\">Publier<\/a>, <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Triste de voir que m\u00eame un d\u00e9veloppeur OG #Bitcoin Core a perdu plus de 200 BTC ($3,5 millions). La garde personnelle comporte un ensemble de risques diff\u00e9rent. Nous essaierons de surveiller et de voir o\u00f9 nous pouvons aider<\/p>\n<\/blockquote>\n\n\n\n<p>En novembre, Zhao a d\u00e9clar\u00e9 que l&#039;auto-garde pourrait entra\u00eener des erreurs co\u00fbteuses, ajoutant que la communaut\u00e9 devrait veiller \u00e0 la mettre en \u0153uvre correctement. Les portefeuilles en libre-service donnent aux utilisateurs un contr\u00f4le total sur leurs portefeuilles, les faisant agir comme des banquiers. Cependant, les utilisateurs doivent assumer l\u2019enti\u00e8re responsabilit\u00e9 de la s\u00e9curit\u00e9 de leur portefeuille. Ainsi, s\u2019ils perdent leur phrase de d\u00e9part, ils perdront leurs fonds et leur compte.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Un d\u00e9veloppeur Bitcoin a annonc\u00e9 sur Twitter que son compte avait \u00e9t\u00e9 attaqu\u00e9 et vid\u00e9 par un pirate informatique, soulevant de nouvelles questions sur la s\u00e9curit\u00e9. Luke Dashjr, qui pr\u00e9tend \u00eatre l&#039;un des premiers d\u00e9veloppeurs de Bitcoin Core, a d\u00e9clar\u00e9 que l&#039;attaque avait eu lieu la veille du Nouvel An. Alors que le total des fonds vol\u00e9s est encore [\u2026]<\/p>","protected":false},"author":19,"featured_media":8583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[12],"tags":[130,172],"class_list":["post-40149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bitcoin","tag-crypto"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud.jpg",1920,1280,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud-300x200.jpg",300,200,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud-768x512.jpg",640,427,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud.jpg",1920,1280,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Cftc-Accuses-South-African-Bitcoin-Club-Mirror-Trading-International-Of-Committing-A-1.7b-Fraud.jpg",18,12,false]},"uagb_author_info":{"display_name":"Lawrence Woriji","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/lawrencew\/"},"uagb_comment_info":0,"uagb_excerpt":"A Bitcoin developer took to Twitter to announce that his account had been attacked and drained by a hacker, raising fresh questions about security. Luke Dashjr, who claims to be one of the earliest Bitcoin Core developers, said the attack took place on New Year&#8217;s Eve. While the total of the stolen funds is yet\u2026","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/40149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=40149"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/40149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/8583"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=40149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=40149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=40149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}