{"id":42586,"date":"2023-01-13T15:17:50","date_gmt":"2023-01-13T15:17:50","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=42586"},"modified":"2023-01-13T15:18:41","modified_gmt":"2023-01-13T15:18:41","slug":"nexo-to-sue-bulgaria-following-raid-on-office","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/nexo-to-sue-bulgaria-following-raid-on-office\/","title":{"rendered":"Nexo va poursuivre la Bulgarie suite \u00e0 un raid sur son bureau"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Les procureurs bulgares affirment que plus de $94 milliards sont pass\u00e9s par Nexo en 5 ans.<\/strong><\/li>\n\n\n\n<li><strong>Le fonctionnement de Nexo a \u00e9galement \u00e9t\u00e9 remis en question par les r\u00e9gulateurs am\u00e9ricains.<\/strong><\/li>\n\n\n\n<li><strong>Nexo a \u00e9t\u00e9 frapp\u00e9 par un flot de retraits \u00e0 la suite du raid sur son bureau.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Apr\u00e8s une s\u00e9rie de perquisitions approfondies dans ses bureaux de Sofia, la soci\u00e9t\u00e9 de crypto-monnaie en difficult\u00e9, Nexo, envisage d&#039;intenter une action en justice contre le gouvernement bulgare. Un local <a aria-label=\"source (s&#039;ouvre dans un nouvel onglet)\" href=\"https:\/\/www.bta.bg\/bg\/news\/bulgaria\/389415-nexo-koyato-opredelya-kato-sramna-za-aktsiyata-na-prokuraturata-sreshtu-firma\" target=\"_blank\" rel=\"noreferrer noopener nofollow\" class=\"ek-link\">la source<\/a> a annonc\u00e9 vendredi que Nexo s&#039;\u00e9tait plaint des mesures prises par les forces de l&#039;ordre au cours de ses enqu\u00eates.\u00a0<\/p>\n\n\n\n<p>Nexo se pr\u00e9parerait \u00e0 poursuivre le gouvernement en justice pour dommages et int\u00e9r\u00eats r\u00e9sultant de l&#039;interruption brutale de la police. Selon une plainte, les inspecteurs ne se sont pas pr\u00e9sent\u00e9s alors que les enqu\u00eateurs ont attendu des heures avant de pr\u00e9senter un mandat de perquisition.<\/p>\n\n\n\n<p>Les responsables de Nexo affirment que les r\u00e9centes perquisitions dans ses bureaux \u00e9taient ill\u00e9gales et d\u00e9montraient \u00ab l\u2019incomp\u00e9tence totale \u00bb de ceux qui menaient cette \u00ab action honteuse \u00bb. Le fournisseur de services de cryptographie a \u00e9galement accus\u00e9 le gouvernement d\u2019avoir tent\u00e9 de \u00ab piller \u00bb une entreprise florissante.<\/p>\n\n\n\n<p>L&#039;entreprise a \u00e9galement d\u00e9clar\u00e9 qu&#039;elle n&#039;offrait pas ses services aux r\u00e9sidents bulgares en raison de probl\u00e8mes potentiels avec les autorit\u00e9s locales. Nexo a \u00e9galement r\u00e9affirm\u00e9 qu&#039;il se conformait aux r\u00e9glementations anti-blanchiment d&#039;argent et aux restrictions russes, en plus de travailler avec d&#039;importantes soci\u00e9t\u00e9s de renseignement cryptographique comme Chainalysis.<\/p>\n\n\n\n<p>Les responsables de Nexo pensent que gagner le proc\u00e8s compensera l&#039;entreprise pour les pertes caus\u00e9es par le raid. Selon la firme,<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Les compensations que la Bulgarie paiera apr\u00e8s que les r\u00e9clamations auront \u00e9t\u00e9 d\u00e9pos\u00e9es et gagn\u00e9es par Nexo seront un autre montant record de centaines de millions, mais, malheureusement, elles seront aux d\u00e9pens du contribuable bulgare.<\/p>\n<\/blockquote>\n\n\n\n<p>Selon <a aria-label=\"autorit\u00e9s (s&#039;ouvre dans un nouvel onglet)\" href=\"https:\/\/bitcoinwisdom.com\/fr\/nepal-telecom-regulator-bans-crypto-websites\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">les autorit\u00e9s<\/a> en Bulgarie, plus de 300 agents des forces de l&#039;ordre ont particip\u00e9 \u00e0 l&#039;enqu\u00eate contre Nexo. La police locale a \u00e9galement fouill\u00e9 15 sites li\u00e9s \u00e0 l&#039;entreprise, et plusieurs agences internationales ont \u00e9t\u00e9 impliqu\u00e9es dans l&#039;enqu\u00eate.<\/p>\n\n\n\n<p>Nexo est un pr\u00eateur de crypto bas\u00e9 au Royaume-Uni et exer\u00e7ant ses activit\u00e9s en Bulgarie. Les procureurs bulgares ont d\u00e9clar\u00e9 que le raid sur Nexo avait \u00e9t\u00e9 effectu\u00e9 \u00ab dans le but de neutraliser les activit\u00e9s criminelles ill\u00e9gales \u00bb. Un porte-parole du procureur en chef Siika Mileva a d\u00e9clar\u00e9 que la soci\u00e9t\u00e9 faisait l&#039;objet d&#039;une enqu\u00eate pour implication possible dans des fraudes informatiques, des fraudes fiscales, la cybercriminalit\u00e9, le crime organis\u00e9 et le blanchiment d&#039;argent.<\/p>\n\n\n\n<p>L&#039;enqu\u00eate a \u00e9t\u00e9 lanc\u00e9e quatre mois apr\u00e8s que les r\u00e9gulateurs de diff\u00e9rents \u00c9tats am\u00e9ricains ont \u00e9mis des ordonnances de \u00ab cessation et d&#039;abstention \u00bb contre Nexo pour la commercialisation de titres non enregistr\u00e9s. En outre, Nexo a \u00e9t\u00e9 poursuivi en justice par le bureau du procureur g\u00e9n\u00e9ral de New York pour avoir faussement d\u00e9clar\u00e9 qu&#039;il se conformait aux \u00ab r\u00e9glementations applicables et aux exigences en mati\u00e8re de licences \u00bb.<\/p>\n\n\n\n<p>Nexo a annonc\u00e9 en d\u00e9cembre qu&#039;il cesserait de proposer certains de ses produits aux \u00c9tats-Unis, citant le refus du pays de \u00ab fournir une voie \u00e0 suivre pour permettre aux entreprises blockchain \u00bb. Nexo reste l&#039;un des rares pr\u00eateurs de crypto actifs sur le march\u00e9 apr\u00e8s l&#039;effondrement d&#039;autres g\u00e9ants tels que Celsius et BlockFi.<\/p>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s une s\u00e9rie de recherches approfondies dans ses bureaux de Sofia, la soci\u00e9t\u00e9 de crypto-monnaie en difficult\u00e9 Nexo envisage de porter plainte contre le gouvernement bulgare. Une source locale a annonc\u00e9 vendredi que Nexo s&#039;\u00e9tait plaint des mesures prises par les forces de l&#039;ordre lors de leurs enqu\u00eates. Nexo se pr\u00e9parerait \u00e0 poursuivre le gouvernement en justice pour les dommages r\u00e9sultant de [\u2026]<\/p>","protected":false},"author":19,"featured_media":9717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[190,12],"tags":[172,600],"class_list":["post-42586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-crypto","tag-nexo"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition.jpg",1280,853,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition-300x200.jpg",300,200,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition-768x512.jpg",640,427,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition-1024x682.jpg",640,426,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition.jpg",1280,853,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition.jpg",1280,853,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Nexo-And-Vauld-Sign-A-Term-Sheet-For-A-Potential-Acquisition.jpg",18,12,false]},"uagb_author_info":{"display_name":"Lawrence Woriji","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/lawrencew\/"},"uagb_comment_info":0,"uagb_excerpt":"After a series of extensive searches at its offices in Sofia, the embattled cryptocurrency firm, Nexo, plans to file a lawsuit against the Bulgarian government. A local source announced on Friday\u00a0that Nexo had complained about the steps taken by law enforcement during its investigations.\u00a0 Nexo is reportedly\u00a0getting ready to sue the government for damages stemming\u2026","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/42586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=42586"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/42586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/9717"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=42586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=42586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=42586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}