{"id":90639,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=90639"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"elliptic-dissects-wsj-claims-of-crypto-being-used-by-hamas","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/fr\/elliptic-dissects-wsj-claims-of-crypto-being-used-by-hamas\/","title":{"rendered":"Elliptic diss\u00e8que les affirmations du WSJ selon lesquelles la cryptographie serait utilis\u00e9e par le Hamas"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Elliptic a d\u00e9clar\u00e9 que le WSJ et les l\u00e9gislateurs am\u00e9ricains manipulaient les faits pour donner une mauvaise image de la cryptographie.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>La soci\u00e9t\u00e9 a d\u00e9clar\u00e9 qu\u2019il n\u2019existe aucune preuve sugg\u00e9rant que le Hamas collecte massivement des fonds via la cryptographie.<\/strong><\/li>\n\n\n\n<li><strong>Il a ajout\u00e9 que le montant r\u00e9el collect\u00e9 via la cryptographie \u00ab reste minime \u00bb.<\/strong><\/li>\n\n\n\n<li><strong>Cela illustre la faiblesse de la cryptographie en tant qu\u2019outil de collecte de fonds pour le terrorisme \u00bb, a not\u00e9 Elliptic.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Elliptic, un fournisseur d&#039;analyse de blockchain bas\u00e9 \u00e0 Londres, a r\u00e9pondu \u00e0 de r\u00e9centes all\u00e9gations selon lesquelles des actifs num\u00e9riques seraient utilis\u00e9s par l&#039;organisation terroriste Hamas dans son conflit contre Isra\u00ebl. Il est int\u00e9ressant de noter qu\u2019un rapport du Wall Street Journal (WSJ) affirme que le groupe Hamas collecte des fonds aupr\u00e8s de ses partisans via des crypto-monnaies pour contourner les sanctions internationales.<\/p>\n\n\n\n<p>Dans un article de blog intitul\u00e9 \u00ab Remettre les pendules \u00e0 l\u2019heure sur le financement participatif crypto par le Hamas \u00bb, Elliptic a d\u00e9clar\u00e9 que les affirmations faites par un rapport du WSJ plus t\u00f4t ce mois-ci selon lesquelles le Hamas et le Jihad islamique palestinien (JIP) avaient collect\u00e9 130 millions de dollars via des rails bas\u00e9s sur la blockchain n\u2019\u00e9taient pas fond\u00e9es. tout \u00e0 fait vrai. La soci\u00e9t\u00e9 d&#039;analyse blockchain a diss\u00e9qu\u00e9 les affirmations du WSJ, fournissant des informations cruciales.<\/p>\n\n\n\n<p>Elliptic a d\u00e9clar\u00e9 qu\u2019il n\u2019y a \u00ab aucune preuve pour \u00e9tayer l\u2019affirmation selon laquelle le Hamas a re\u00e7u des volumes importants de dons cryptographiques \u00bb, tout en ajoutant :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Au cours des derni\u00e8res ann\u00e9es, le Hamas a commenc\u00e9 \u00e0 exp\u00e9rimenter la crypto-monnaie comme moyen de financement participatif aupr\u00e8s du public via les m\u00e9dias sociaux. Cependant, la tra\u00e7abilit\u00e9 unique de ces actifs fait que les montants lev\u00e9s restent minimes par rapport aux autres sources de financement.<\/p>\n<\/blockquote>\n\n\n\n<p>Il est int\u00e9ressant de noter qu&#039;en avril, les Brigades Al-Qassam (AQB) du Hamas ont \u00e9t\u00e9 pouss\u00e9es \u00e0 abandonner leurs efforts de collecte de fonds via les crypto-monnaies apr\u00e8s que les autorit\u00e9s ont s\u00e9v\u00e8rement puni les donateurs. Il est int\u00e9ressant de noter que les autorit\u00e9s isra\u00e9liennes ont saisi une quantit\u00e9 importante d\u2019actifs num\u00e9riques aupr\u00e8s des principaux \u00e9changes cryptographiques au d\u00e9but du mois, selon un rapport. <a href=\"https:\/\/www.ft.com\/content\/e03a370b-777f-46c2-8576-d1cee731efe2\" rel=\"nofollow noopener\" target=\"_blank\">rapport<\/a> du Financial Times.<\/p>\n\n\n\n<p>&quot;Cela illustre la faiblesse de la cryptographie en tant qu&#039;outil de collecte de fonds pour le terrorisme&quot;, a not\u00e9 Elliptic dans le billet de blog, tout en ajoutant que le montant collect\u00e9 par le Hamas via la blockchain &quot;reste minime&quot;. La soci\u00e9t\u00e9 d&#039;analyse de blockchain affirme que le WSJ et les l\u00e9gislateurs am\u00e9ricains ont manipul\u00e9 des donn\u00e9es pour pr\u00e9senter le fait que les monnaies num\u00e9riques jouent un r\u00f4le important dans le financement des activit\u00e9s terroristes du Hamas.&nbsp;<\/p>\n\n\n\n<p>Elliptic a \u00e9galement fourni un exemple d&#039;une campagne de collecte de fonds \u00ab importante \u00bb de crypto-monnaie du Hamas, men\u00e9e par Gaza Now, d\u00e9clarant qu&#039;elle n&#039;avait collect\u00e9 que $21 000 depuis l&#039;attaque du Hamas contre Isra\u00ebl le 7 octobre. Sur cet argent, $9 000 ont \u00e9t\u00e9 gel\u00e9s par l&#039;\u00e9metteur de stablecoin Tether, tandis qu&#039;un autre $2,000 a \u00e9t\u00e9 gel\u00e9 par un \u00e9change cryptographique.<\/p>\n\n\n\n<p>Comme indiqu\u00e9 pr\u00e9c\u00e9demment par BitcoinWisdom, les \u00e9changes cryptographiques comme Coinbase devraient faire face \u00e0 <a href=\"https:\/\/bitcoinwisdom.com\/fr\/coinbase-to-face-hurdles-in-lobbying-efforts-amid-rumors-of-hamas-crypto-use\/\">r\u00e9sistance dans leurs efforts de lobbying aux \u00c9tats-Unis<\/a> apr\u00e8s le conflit isra\u00e9lien en raison de l\u2019utilisation d\u2019actifs num\u00e9riques par le Hamas.<\/p>","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 d\u2019analyse de blockchain Elliptic a d\u00e9clar\u00e9 qu\u2019il n\u2019y avait aucune preuve sugg\u00e9rant que le Hamas collecte massivement des fonds via la cryptographie.<\/p>","protected":false},"author":21,"featured_media":90641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[135],"class_list":["post-90639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-blockchain"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/10\/Crypto-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/fr\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Blockchain analysis firm Elliptic said that there is no evidence that suggests that Hamas is extensively raising funds via crypto.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/90639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/comments?post=90639"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/posts\/90639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media\/90641"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/media?parent=90639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/categories?post=90639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/fr\/wp-json\/wp\/v2\/tags?post=90639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}