{"id":19543,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=19543"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"latin-american-bank-debuts-its-mynt","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/latin-american-bank-debuts-its-mynt\/","title":{"rendered":"La pi\u00f9 grande banca di investimento dell&#039;America Latina debutta il suo scambio di criptovalute, Mynt"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>La pi\u00f9 grande banca di investimento dell&#039;America Latina, BTG Pactual, ha lanciato la sua attivit\u00e0 di intermediazione di asset digitali, Mynt, che fornir\u00e0 servizi relativi alle criptovalute ai clienti. <\/strong><\/li><li><strong>Mynt debutter\u00e0 sul mercato con cinque asset digitali: Bitcoin (BTC), Ethereum (ETH), Cardano (ADA), Solana (SOL) e Polkadot (DOT).<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>In mezzo alla forte concorrenza tra le banche brasiliane per entrare nel mercato delle criptovalute e per fare una solida presenza nello spazio, la pi\u00f9 grande banca di investimento dell&#039;America Latina, BTG Pactual, ha lanciato il suo broker di asset digitali Mynt.<\/p>\n\n\n\n<p>Secondo un recente <a href=\"https:\/\/portaldobitcoin.uol.com.br\/btg-estreia-corretora-de-criptomoedas-na-corrida-com-xp-e-planeja-usar-stablecoin\/\" rel=\"nofollow noopener\" target=\"_blank\">rapporto<\/a> di portaldobitcoin, Mynt ha alcune caratteristiche uniche. Debutta sul mercato con cinque asset digitali: Bitcoin (BTC), Ethereum (ETH), Cardano (ADA), Solana (SOL) e Polkadot (DOT). Andr\u00e9 Portilho, Head of Digital Assets presso il colosso bancario, ha dichiarato:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Elencheremo pi\u00f9 monete, ma ci\u00f2 dipende dalla domanda dei clienti e dal nostro processo interno di valutazione del progetto&quot;.<\/p><\/blockquote>\n\n\n\n<p>Inoltre, il dirigente ha rivelato che il piano della piattaforma include l&#039;integrazione di una stablecoin. Quando gli \u00e8 stato chiesto se si trattasse della propria stablecoin o di un altro partner, Portilho ha deciso di non offrire altre informazioni. Tuttavia, BTG mira a mantenere il sistema il pi\u00f9 semplice possibile per evitare di incontrare tecnologie complesse con i suoi clienti.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Interessante coincidenza<\/h2>\n\n\n\n<p>\u00c8 interessante notare che il nuovo lancio arriva lo stesso giorno del suo principale rivale <a href=\"https:\/\/bitcoinwisdom.com\/it\/brazilian-brokerage-firm-xp-reveals-the-launch-date-of-its-crypto-exchange\/\">XP ha lanciato una piattaforma di trading di criptovalute<\/a>. La societ\u00e0 ha dichiarato il 15 agosto che la piattaforma appena lanciata offre attualmente solo trading BTC ed ETH, ma la pi\u00f9 grande intermediazione brasiliana per valore di mercato mira a offrire esposizione a dieci asset digitali entro la fine del 2022.<\/p>\n\n\n\n<p>La corsa tra le banche brasiliane ha preso forma intensa quando la pi\u00f9 grande banca digitale brasiliana per valore di mercato, Nubank, ha lanciato la sua piattaforma di criptovalute nel giugno di quest&#039;anno. Inoltre, il mese scorso, la societ\u00e0 ha riferito di aver gi\u00e0 raggiunto il milione di utenti. Dopo aver lanciato Nucripto a maggio e aver implementato il servizio ai suoi 46,5 milioni di clienti a giugno, Nubank mirava a raggiungere questo traguardo entro un anno.<\/p>\n\n\n\n<p>Tuttavia, Mynt ha molte caratteristiche uniche rispetto alle piattaforme dei concorrenti di BTG Pactual. Mentre altri hanno incluso gli scambi nelle loro applicazioni primarie, BTG non costringe i suoi clienti a diventare automaticamente client Mynt.<\/p>\n\n\n\n<p>Il fatto che un utente non possa prelevare o depositare criptovalute \u00e8 ancora vero, proprio come con altri servizi. Portilho ha affermato che la societ\u00e0 ha in programma di lanciare il sistema &quot;in settimane o mesi&quot;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Pensiamo che i clienti vorranno portare gli asset a BTG, visti i casi che abbiamo avuto di restrizioni di prelievo&quot;, <\/p><cite>Ha aggiunto.<\/cite><\/blockquote>\n\n\n\n<p>In particolare, alla domanda sul potenziale movimento dei prezzi, Portilho non ha mostrato alcun interesse a fare previsioni sul prezzo delle criptovalute. &quot;Non so se abbiamo ancora toccato il fondo&quot;, ha detto.<\/p>\n\n\n\n<p>Ha scelto una teoria controversa per supportare un potenziale nuovo ciclo rialzista affermando che &quot;l&#039;halving \u00e8 diventato un mito del prezzo del bitcoin. In passato era senza dubbio importante, ma oggi non lo \u00e8 pi\u00f9&quot;.<\/p>","protected":false},"excerpt":{"rendered":"<p>The largest investment bank in Latin America, BTG Pactual, launched its digital asset brokerage, Mynt which will provide crypto-related services to clients. Mynt will debut in the market with five digital assets: Bitcoin (BTC), Ethereum (ETH), Cardano (ADA), Solana (SOL), and Polkadot (DOT). Amid the heavy competition among Brazilian banks to enter the crypto market [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":19575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1358,1357],"class_list":["post-19543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-btg-pactual","tag-mynt"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Mynt-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The largest investment bank in Latin America, BTG Pactual, launched its digital asset brokerage, Mynt which will provide crypto-related services to clients. Mynt will debut in the market with five digital assets: Bitcoin (BTC), Ethereum (ETH), Cardano (ADA), Solana (SOL), and Polkadot (DOT). Amid the heavy competition among Brazilian banks to enter the crypto market&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/19543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=19543"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/19543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/19575"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=19543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=19543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=19543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}