{"id":21165,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=21165"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"dutch-judge-puts-tornado-cash-developer-in-jail-for-additional-90-days","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/dutch-judge-puts-tornado-cash-developer-in-jail-for-additional-90-days\/","title":{"rendered":"Il giudice olandese mette lo sviluppatore Tornado Cash in prigione per ulteriori 90 giorni"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>L&#039;arresto di Alexey Pertsev da parte delle autorit\u00e0 olandesi, sviluppatore del mixer di criptovalute basato su Ethereum, Tornado Cash, per presunto favoreggiamento del riciclaggio di denaro tramite l&#039;ormai approvato Tornado Cash, ha provocato qualche giorno fa una seria rabbia tra i membri della comunit\u00e0 crittografica.<\/p>\n\n\n\n<p>Tuttavia, i recenti sviluppi<a href=\"https:\/\/thedefiant.io\/tornado-dev-90-days-jail\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\"> nel caso hanno<\/a> intensificato il contraccolpo. All&#039;a <a href=\"https:\/\/thedefiant.io\/tornado-dev-90-days-jail\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">udito<\/a> avvenuto mercoled\u00ec nei Paesi Bassi, il giudice ha respinto la richiesta degli avvocati di Pertsev di rilasciare l&#039;imputato su cauzione e ha deciso che dovesse essere detenuto per altri tre mesi.<\/p>\n\n\n\n<p>Inizialmente portato davanti a un giudice istruttore il 12 agosto, Pertsev, con sede ad Amsterdam, ha ricevuto un termine di custodia iniziale di due settimane.<\/p>\n\n\n\n<p>Gli avvocati di Pertsev hanno chiesto che gli fosse concessa la libert\u00e0 su cauzione durante un&#039;udienza a porte chiuse tenutasi mercoled\u00ec a Den Bosch, nei Paesi Bassi. Il giudice ha respinto tale richiesta e ha fissato un termine di 90 giorni per la prima udienza pubblica, il che significa che l&#039;udienza pubblica iniziale dovr\u00e0 concludersi entro tre mesi. Pertsev non deve ancora affrontare formalmente alcuna accusa penale.<\/p>\n\n\n\n<p>Come riportato da BitcoinWisdom, il <a href=\"https:\/\/bitcoinwisdom.com\/it\/dutch-authorities-arrest-suspected-tornado-cash\/\" class=\"ek-link\">Le autorit\u00e0 olandesi hanno arrestato lo sviluppatore 29enne<\/a> il 10 agosto, appena due giorni dopo che il Dipartimento del Tesoro degli Stati Uniti ha imposto sanzioni alla piattaforma di mixaggio di criptovalute, che aveva collegato a oltre $1 miliardo di transazioni subdole e hacker nordcoreani.<\/p>\n\n\n\n<p>L&#039;arresto non \u00e8 stato accolto bene dagli appassionati di criptovalute che denunciano diversi casi utili di utilizzo di Tornado Cash che \u00e8 molto efficiente nel rendere private le transazioni. Tuttavia, la situazione sembra continuare a peggiorare per il mixer di Ethereum. <\/p>\n\n\n\n<p>La FIOD, un&#039;autorit\u00e0 olandese responsabile della supervisione delle finanze relative ai crimini, ha rivelato che l&#039;indagine iniziale \u00e8 iniziata a giugno prima che gli Stati Uniti avessero imposto sanzioni a Tornado Cash e sembra che da allora la situazione sia solo peggiorata. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;\u00c8 sospettato di coinvolgimento nell&#039;occultamento di flussi finanziari criminali e nel favoreggiamento del riciclaggio di denaro attraverso la miscelazione di criptovalute attraverso il servizio di miscelazione decentralizzato di Ethereum Tornado Cash.&quot; \u00a0<\/p><cite>il Servizio di Informazione e Investigazione Fiscale ha detto in a\u00a0<a href=\"https:\/\/www.fiod.nl\/arrest-of-suspected-developer-of-tornado-cash\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">dichiarazione<\/a><\/cite><\/blockquote>\n\n\n\n<p>L&#039;amministratore delegato del principale scambio di criptovalute <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/it\/kraken-review\/\" title=\"Kraken\" data-wpil-keyword-link=\"linked\">Kraken<\/a>, Josse Powell, ha recentemente messo in dubbio il fatto se le sanzioni contro il mixer di Ethereum rimarranno in un tribunale basso o se sia costituzionale da fare. Sembra che la comunit\u00e0 delle criptovalute non sia contenta della decisione presa dalle autorit\u00e0 di regolamentazione.<\/p>\n\n\n\n<p>Recentemente, <a href=\"https:\/\/bitcoinwisdom.com\/it\/coin-center-to-challenge-the-us-treasury\/\" class=\"ek-link\">Coin Center ha detto che far\u00e0 causa alle autorit\u00e0<\/a> per le sanzioni che hanno imposto a Tornado Cash definendolo un passo incostituzionale. L\u2019azienda no-profit ha affermato che le sanzioni violano potenzialmente \u201ci diritti costituzionali al giusto processo e alla libert\u00e0 di parola, e che l\u2019OFAC non ha agito adeguatamente per mitigare l\u2019impatto prevedibile che la sua azione avrebbe sugli americani innocenti\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>The developer of Ethereum-based crypto mixer Tornado Cash, Alexey Pertsev\u2019s arrest by Dutch authorities for allegedly facilitating money laundering via the now-sanctioned Tornado Cash, resulted in a serious rage among crypto community members a few days back. However, the recent developments in the case have intensified the backlash. At a hearing that took place in [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":21169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1213],"class_list":["post-21165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tornado-cash"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The developer of Ethereum-based crypto mixer Tornado Cash, Alexey Pertsev\u2019s arrest by Dutch authorities for allegedly facilitating money laundering via the now-sanctioned Tornado Cash, resulted in a serious rage among crypto community members a few days back. However, the recent developments in the case have intensified the backlash. At a hearing that took place in&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/21165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=21165"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/21165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/21169"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=21165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=21165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=21165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}