{"id":22974,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=22974"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"thodex-ceo-apprehended-in-albania","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/thodex-ceo-apprehended-in-albania\/","title":{"rendered":"Il CEO della borsa turca Thodex arrestato in Albania, rischia l&#039;estradizione in Turchia"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>L&#039;amministratore delegato (CEO) dell&#039;ormai defunto exchange di criptovalute turco Thodex, Faruk Fatih \u00d6zer, \u00e8 stato recentemente arrestato dalle forze dell&#039;ordine in Albania.<\/strong><\/li><li><strong>In particolare, l&#039;ufficio del procuratore capo dell&#039;Anatolia di Istanbul ha aperto un&#039;indagine dopo aver ricevuto denunce da diverse persone.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Secondo una dichiarazione del ministero dell&#039;Interno turco, l&#039;amministratore delegato dell&#039;ormai defunto exchange di criptovalute turco Thodex, Faruk Fatih \u00d6zer, \u00e8 stato recentemente arrestato dalle forze dell&#039;ordine in Albania e sar\u00e0 probabilmente trasferito in Turchia.<\/p>\n\n\n\n<p>Thodex, che qualche anno fa era uno dei principali scambi di criptovalute del paese, ha improvvisamente interrotto il trading dei suoi utenti nell&#039;aprile 2021. Ci\u00f2 ha provocato una massiccia situazione di panico, facendo perdere a oltre 391.000 utenti tutti i loro soldi duramente guadagnati.&nbsp;<\/p>\n\n\n\n<p>Le stime delle perdite totali causate dall&#039;arresto della gamma Thodex ampiamente. <a href=\"https:\/\/blog.chainalysis.com\/reports\/2022-crypto-crime-report-introduction\/\" rel=\"nofollow noopener\" target=\"_blank\">Secondo<\/a> secondo Chainalysis, sono andati persi circa $2,52 miliardi, pari a 90% dell\u2019intero valore perso in tutto il mondo a causa dei furti di tappeti lo scorso anno. D\u2019altra parte, un\u2019accusa dell\u2019aprile 2022 sostiene danni per oltre $24 milioni. Come parte di tale accusa, un pubblico ministero turco ha chiesto pene detentive per un totale di 40.564 anni per \u00d6zer e i suoi colleghi.<\/p>\n\n\n\n<p>L&#039;incidente \u00e8 considerato il pi\u00f9 grande incidente di tutti i tempi poich\u00e9, secondo quanto riferito, \u00d6zer \u00e8 fuggito dal paese con oltre 2 miliardi di criptovalute in Albania, secondo le fonti locali. <a href=\"https:\/\/www.dha.com.tr\/gundem\/thodexin-kurucusu-faruk-fatih-ozerin-havalimanindan-ayrilirken-fotografi-1822744\" rel=\"nofollow noopener\" target=\"_blank\">rapporti<\/a> al momento.&nbsp;<\/p>\n\n\n\n<p>In particolare, l&#039;ufficio del procuratore capo dell&#039;Anatolia di Istanbul ha aperto un&#039;indagine dopo aver ricevuto denunce da diverse persone.<\/p>\n\n\n\n<p>Secondo a <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2021-04-22\/turks-suspect-massive-crypto-losses-as-exchange-ceo-goes-missing#xj4y7vzkg\" rel=\"nofollow noopener\" target=\"_blank\">rapporto<\/a> da Bloomberg, Ozer ha affermato in una dichiarazione di aver considerato l\u2019idea di \u201carrendersi\u201d o \u201csuicidarsi\u201d prima di fuggire definitivamente dal paese per \u201crimanere in vita e combattere, lavorare e ripagare\u201d i suoi debiti. Questa dichiarazione \u00e8 stata rilasciata poco dopo il crollo di Thodex. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Il giorno in cui avr\u00f2 ripagato tutto il mio debito, torner\u00f2 nel mio paese e mi consegner\u00f2 alla giustizia&quot;<\/p><cite>Lui continu\u00f2.<\/cite><\/blockquote>\n\n\n\n<p>Il CEO di Thodex ha negato le accuse di furto e ha mostrato l&#039;intenzione di rimborsare i fondi agli investitori dal suo account Twitter ora cancellato. All&#039;epoca, \u00d6zer afferm\u00f2 che il vero motivo per sospendere le negoziazioni e vietare i prelievi era quello di esaminare 30.000 conti clienti che presentavano anomalie sospette rilevate &quot;durante un colloquio di investimento di tre mesi&quot;.<\/p>","protected":false},"excerpt":{"rendered":"<p>The Chief Executive Officer (CEO) of the now-defunct Turkish crypto exchange Thodex, Faruk Fatih \u00d6zer, has been recently detained by law enforcement authorities in Albania. Notably, the Istanbul Anatolian Chief Public Prosecutor&#8217;s Office opened an investigation after receiving complaints from several people. As per a statement from Turkey&#8217;s Interior Ministry, the Chief Executive Officer of [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":22994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1626],"class_list":["post-22974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-thodex"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Thodex-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The Chief Executive Officer (CEO) of the now-defunct Turkish crypto exchange Thodex, Faruk Fatih \u00d6zer, has been recently detained by law enforcement authorities in Albania. Notably, the Istanbul Anatolian Chief Public Prosecutor&#8217;s Office opened an investigation after receiving complaints from several people. As per a statement from Turkey&#8217;s Interior Ministry, the Chief Executive Officer of&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/22974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=22974"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/22974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/22994"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=22974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=22974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=22974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}