{"id":23150,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=23150"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"btbt-stock-up-1-3-bit-digital-reports-profitable-22q2-earnings-results","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/btbt-stock-up-1-3-bit-digital-reports-profitable-22q2-earnings-results\/","title":{"rendered":"BTBT Stock Up 1.3%, Bit Digital riporta risultati redditizi nel 22Q2\u00a0"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>Bit Digital ha guadagnato 197,28 Bitcoin e 104,29 ETH durante il secondo trimestre, terminato il 30 giugno.<\/strong><\/li><li><strong>La societ\u00e0 ha ricevuto i minatori di 10.000 unit\u00e0 precedentemente annunciati acquistati da Bitmain.<\/strong><\/li><li><strong>Bit Digital, che appartiene al settore dei servizi tecnologici di Zacks, ha mancato la stima del consenso di Zacks del 52,34%.<\/strong><\/li><\/ul>\n<hr>\n\n\n\n<p>Bit Digital Inc. (Nasdaq: BTBT), una societ\u00e0 di mining di criptovalute con sede a New York, ha annunciato i risultati degli utili non certificati del secondo trimestre. Per i tre mesi terminati il 30 giugno 2022, Bit Digital ha registrato un fatturato di $6,5 milioni dalle sue operazioni di mining di Bitcoin. Inoltre, la societ\u00e0 ha registrato un fatturato di $0,3 milioni dalle operazioni di mining di Ethereum.<\/p>\n\n\n\n<p>Detto in questo modo, Bit Digital ha guadagnato 197,28 <a href=\"https:\/\/bitcoinwisdom.com\/it\/bitcoin-price-falls-below-20k-total-crypto-market-cap-under-1t\/\">Bitcoin<\/a> e 104,29 ETH durante il secondo trimestre, terminato il 30 giugno. Portando cos\u00ec in tesoreria BTC e <a href=\"https:\/\/pricepredictions.com\/forecast\/ethereum\" rel=\"nofollow noopener\" target=\"_blank\">ET<\/a> rispettivamente a 860,57 e 313,56.<\/p>\n\n\n\n<p>Secondo quanto riferito, la societ\u00e0 possedeva 38.135 minatori bitcoin e 731 minatori Ethereum al 30 giugno 2022. Inoltre, la societ\u00e0 ha affermato che i minatori BTC ed ETH hanno un tasso di hash totale massimo stimato di 2,7 EH\/s e 0,3 TH\/s, rispettivamente.<\/p>\n\n\n\n<p>Vale la pena notare che la societ\u00e0 ha ricevuto i minatori da 10.000 unit\u00e0 precedentemente annunciati acquistati da Bitmain. A seguito degli ulteriori minatori di risorse digitali, la societ\u00e0 ha firmato un nuovo accordo di hosting da 20 MW con Coinmint LLC.<\/p>\n\n\n\n<p>Bit Digital ha annunciato di aver venduto 903 minatori MicroBT Whatsminer M21S Bitcoin e 9 minatori MicroBT Whatsminer M20S Bitcoin durante il trimestre.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Dopo la fine del trimestre, abbiamo anche annunciato un nuovo accordo di hosting da 5 MW con un fornitore in Canada in una localit\u00e0 che \u00e8 principalmente alimentata da energia idroelettrica... Abbiamo chiuso il trimestre con $45 milioni in contanti, oltre $70 milioni in liquidit\u00e0 totale, zero debiti , e nessun obbligo di acquisto di minatori in sospeso\u201d, la gestione di Bit Digital <a href=\"https:\/\/www.prnewswire.com\/news-releases\/bit-digital-inc-announces-second-quarter-of-fiscal-year-2022-financial-results-301614926.html\" rel=\"nofollow noopener\" target=\"_blank\">notato<\/a>.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Bit Digital e le prospettive di mercato<\/h2>\n\n\n\n<p>A seguito del rapporto non certificato del 22Q2, il mercato azionario della societ\u00e0 ha guadagnato oggi circa l&#039;1%, secondo i dati forniti da <a href=\"https:\/\/www.marketwatch.com\/investing\/stock\/btbt?mod=search_symbol\" rel=\"nofollow noopener\" target=\"_blank\">MarketWatch<\/a>. Tuttavia, il mercato azionario della societ\u00e0 \u00e8 sceso di circa l&#039;88% nell&#039;ultimo anno.<\/p>\n\n\n\n<p>In particolare, il mercato azionario di Bit Digital ha registrato gravi perdite nell&#039;ultimo anno, una situazione simile nel settore delle criptovalute. Secondo i nostri dati di mercato, il prezzo del Bitcoin \u00e8 scambiato a <span data-realtime=\"on\"><span data-live-price=\"BTCUSDT\" data-price=\"77496.47128839288780\" data-rate=\"1\" data-currency=\"USD\"><b class=\"fiat-symbol\">$<\/b><span>77,496.47<\/span><\/span><\/span>, in calo di circa il 70 percento rispetto all&#039;ATH.<\/p>\n\n\n\n<p>La societ\u00e0 ha una valutazione di mercato dichiarata di circa $120 milioni con 82,43 milioni di azioni in circolazione.&nbsp;<\/p>\n\n\n\n<p>Bit Digital, che appartiene al settore dei servizi tecnologici di Zacks, ha mancato la stima del consenso di Zacks del 52,34%. Inoltre, la societ\u00e0 ha registrato un fatturato di $28,34 milioni un anno fa nello stesso trimestre. Da allora, la societ\u00e0 non \u00e8 stata in grado di battere le stime dei ricavi di consenso negli ultimi quattro trimestri.<\/p>\n\n\n\n<p>In avanti, gli analisti hanno stabilito una stima degli utili basata sul portafoglio di investimenti della societ\u00e0. Secondo <a href=\"https:\/\/www.zacks.com\/stock\/news\/1974281\/bit-digital-inc-btbt-reports-q2-loss-misses-revenue-estimates?cid=CS-MKTWTCH-HL-tale_of_the_tape%7Cyseop_template_4-1974281&amp;mod=mw_quote_news\" rel=\"nofollow noopener\" target=\"_blank\">Zacks stima<\/a>, l&#039;attuale stima EPS di consenso \u00e8 $0.03 su $21.1 milioni di ricavi per il prossimo trimestre e $0.15 su $73 milioni di ricavi per l&#039;anno fiscale in corso.<\/p>\n\n\n\n<p>La societ\u00e0 \u00e8, tuttavia, fortemente investita in un mercato volatile delle criptovalute che \u00e8 altamente imprevedibile. Pertanto, le stime possono o meno giocare secondo le aspettative. Inoltre, il mercato delle criptovalute \u00e8 segnato da folli speculazioni sin dall&#039;inizio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bit Digital ha guadagnato 197,28 Bitcoin e 104,29 ETH durante il secondo trimestre, terminato il 30 giugno.<\/p>","protected":false},"author":18,"featured_media":23207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1628],"class_list":["post-23150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-bit-digital"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577.jpg",1600,1067,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-300x200.jpg",300,200,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-768x512.jpg",640,427,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577.jpg",1600,1067,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/5980577-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Rebecca Davidson","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/rebeccad\/"},"uagb_comment_info":0,"uagb_excerpt":"Bit Digital earned 197.28 Bitcoins and 104.29 ETH during the second quarter, which ended on June 30.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/23150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=23150"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/23150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/23207"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=23150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=23150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=23150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}