{"id":24911,"date":"2022-09-11T08:05:51","date_gmt":"2022-09-11T08:05:51","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=24911"},"modified":"2022-09-11T08:05:58","modified_gmt":"2022-09-11T08:05:58","slug":"new-french-crypto-bill","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/new-french-crypto-bill\/","title":{"rendered":"Nuova legge sulle criptovalute francesi per consentire alle autorit\u00e0 di sequestrare le risorse digitali"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>I leader hanno presentato un nuovo disegno di legge sulle criptovalute francesi, che dar\u00e0 alle autorit\u00e0 il potere di sequestrare le risorse digitali che apparterrebbero a sospetti criminali.<\/strong><\/li><li><strong>Il governo del presidente Emmanuel Macron vuole impedire agli investitori in risorse digitali di riciclare il proprio denaro e mira a collaborare con la polizia britannica su questa iniziativa.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>In base a una nuova legge proposta mercoled\u00ec dal governo francese, i cittadini potrebbero rischiare il congelamento dei loro asset crittografici se le autorit\u00e0 trovassero sospette attivit\u00e0 illecite nei loro account.<\/p>\n\n\n\n<p>La recente proposta rivela che il governo guidato dal presidente Emmanuel Macron vuole seguire l&#039;esempio del Regno Unito e dare alla polizia pi\u00f9 autorit\u00e0 per sequestrare beni che potrebbero essere potenzialmente utilizzati per sfuggire al loro controllo e riciclare denaro. <\/p>\n\n\n\n<p>Un rapporto che mostra alcuni frammenti del progetto di legge del governo recita:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&quot;Troppo spesso, i criminali convertono i frutti dei loro illeciti in criptovalute, che possono essere pi\u00f9 facilmente disperse e quindi nascoste.&quot;<\/p><\/blockquote>\n\n\n\n<p>Secondo le proposte del governo, una volta ottenuto il via libera da parte del pubblico ministero o del giudice istruttore, le partecipazioni bancarie dovrebbero essere sequestrate. <\/p>\n\n\n\n<p>Il rapporto afferma:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cGli agenti [della polizia] saranno dotati di attrezzature innovative e ad alte prestazioni e beneficeranno di immobili che offriranno condizioni di lavoro e di accoglienza rinnovate e risponderanno alle crescenti esigenze di formazione\u201d.<\/p><\/blockquote>\n\n\n\n<p>Le proposte, che riprendono ampiamente quelle avanzate per la prima volta nel marzo 2022, estenderebbero agli asset digitali le stesse regole che gi\u00e0 disciplinano le partecipazioni sui conti correnti bancari tradizionali.<\/p>\n\n\n\n<p>Sebbene gran parte del disegno di legge sia dedicato alla criminalit\u00e0 online, come la richiesta che le autorit\u00e0 affrontino i pagamenti di ransomware, affronta anche una serie di altre questioni sotto la giurisdizione del ministro degli Interni francese G\u00e9rald Darmanin, inclusa la formazione di 200 nuove squadre di polizia rurale. e modifica nella gestione dei casi di violenza domestica.<\/p>\n\n\n\n<p>Le misure saranno esaminate dalla commissione di diritto costituzionale del Senato francese, incaricata di valutare le modifiche al codice penale del paese, in una riunione della settimana successiva.<\/p>\n\n\n\n<p>In particolare, gli investitori crittografici francesi devono affrontare incongruenze quando si tratta di normative. A luglio, queste normative poco chiare hanno portato alla <a href=\"https:\/\/racingnews365.com\/how-frances-advertising-laws-affected-f1-teams-crypto-branding\" rel=\"nofollow noopener\" target=\"_blank\">rimozione<\/a> di annunci crittografici nella gara di F1.<\/p>\n\n\n\n<p>Ricordiamo che il governo guidato dall&#039;ex primo ministro britannico Boris Johnson si \u00e8 impegnato ad ampliare i poteri per sequestrare e recuperare le risorse di criptovaluta nell&#039;ambito della legge sulla criminalit\u00e0 economica di maggio. \u00c8 interessante notare che mercoled\u00ec il neoeletto Primo Ministro Liz Truss e il suo governo hanno riaffermato il loro impegno verso questi obiettivi.<\/p>","protected":false},"excerpt":{"rendered":"<p>I leader francesi hanno presentato una nuova legge sulle criptovalute, che dar\u00e0 alle autorit\u00e0 il potere di sequestrare beni digitali che apparterrebbero a sospetti criminali. Il governo del presidente Emmanuel Macron vuole impedire agli investitori in risorse digitali di riciclare il proprio denaro e mira a collaborare con la polizia britannica su questa iniziativa. Sotto un nuovo [\u2026]<\/p>","protected":false},"author":21,"featured_media":24918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[191,12],"tags":[1648],"class_list":["post-24911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-talk","category-news","tag-crypto-bill"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/09\/Crypto-1-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"A new French crypto bill has been presented by leaders, which will give authorities the power to seize digital assets that would belong to suspected criminals. President Emmanuel Macron\u2019s government wants to prevent investors in digital assets from laundering their money and aims to work with the UK police on the initiative. Under a new&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/24911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=24911"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/24911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/24918"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=24911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=24911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=24911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}