{"id":36312,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=36312"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"ark-invest-buys-more-coinbase-stocks","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/ark-invest-buys-more-coinbase-stocks\/","title":{"rendered":"Ark Invest acquista pi\u00f9 azioni Coinbase"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Le informazioni sulle negoziazioni giornaliere di Ark Investment Management LLC affermano che tre fondi Ark hanno acquistato oltre 420.000 azioni della societ\u00e0 di cambio con sede negli Stati Uniti, Coinbase, questo marted\u00ec.<\/strong><\/li>\n\n\n\n<li><strong>Il CEO di Coinbase Brian Armstrong ha commentato la crisi di FTX e ha affermato che Coinbase non adotta comportamenti rischiosi e che la sua azienda non ha intenzione di acquisire FTX US.<\/strong><\/li>\n\n\n\n<li><strong>Il recente acquisto di COIN da parte di Ark coincide con il recente avvertimento dell&#039;Autorit\u00e0 federale di vigilanza finanziaria tedesca o della BaFin alla divisione tedesca di Coinbase di prestare attenzione alle sue operazioni nella regione.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Ark Invest di Cathie Wood ha recentemente aggiunto una partecipazione nello scambio di criptovalute <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/it\/coinbase-review\/\" title=\"Coinbase\" data-wpil-keyword-link=\"linked\">Coinbase<\/a> dopo che il suo pi\u00f9 grande concorrente Binance ha firmato un accordo per acquistare le attivit\u00e0 non statunitensi di FTX.&nbsp;<\/p>\n\n\n\n<p>Anche se l&#039;accordo tra <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/it\/ftx-review\/\" title=\"FTX\" data-wpil-keyword-link=\"linked\">FTX<\/a> e Binance \u00e8 ora cancellato, le comunicazioni giornaliere sul trading di Ark Investment Management LLC affermano che tre fondi Ark hanno acquistato oltre 420.000 azioni della societ\u00e0 di cambio con sede negli Stati Uniti questo marted\u00ec. Questo \u00e8 il secondo acquisto di Cathie Wood da luglio; prima di ci\u00f2, Ark Funds aveva acquistato azioni COIN il 24 ottobre.<\/p>\n\n\n\n<p>In particolare, il CEO di Coinbase Brian Armstrong ha recentemente commentato la crisi di FTX e ha affermato che Coinbase non adotta comportamenti rischiosi e che la sua azienda non ha intenzione di acquisire FTX US.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ark compra il tuffo<\/h2>\n\n\n\n<p>La societ\u00e0 di Wood, che detiene pi\u00f9 di 7,7 milioni di azioni COIN o una quota di 4,3% in Coinbase al 30 settembre, \u00e8 il quarto maggiore azionista dell&#039;exchange.<\/p>\n\n\n\n<p>Ark ha deciso di acquistare il calo quando COIN \u00e8 precipitato marted\u00ec 11%, segnando i livelli pi\u00f9 bassi dal 1 luglio.&nbsp;<\/p>\n\n\n\n<p>Tra le crescenti preoccupazioni su come il rapporto tra <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/it\/binance-review\/\" title=\"Binance\" data-wpil-keyword-link=\"linked\">Binance<\/a> e FTX rimodeller\u00e0 l&#039;industria delle criptovalute $1 trilioni, la maggior parte delle criptovalute \u00e8 tornata a terra. Bitcoin \u00e8 al minimo di due anni, scambiato intorno alla zona $16.000 al momento della scrittura.<\/p>\n\n\n\n<p>Nonostante la continua incertezza nel settore, Coinbase sta pianificando attivamente una strategia di espansione negli Stati Uniti. Di recente, Armstrong ha affermato che problemi come la crisi di liquidit\u00e0 sorgono a causa della mancanza di una chiara certezza normativa nel paese. Lui <a href=\"https:\/\/twitter.com\/brian_armstrong\/status\/1590088673726717952\" rel=\"nofollow noopener\" target=\"_blank\">ha dichiarato<\/a>:<\/p>\n\n\n\n<p>&quot;Dovremmo continuare a lavorare con i politici per creare una regolamentazione sensata per gli scambi\/custodi centralizzati in ciascun mercato (come stiamo facendo da qualche tempo), ma poi dobbiamo vedere l&#039;applicazione di condizioni di parit\u00e0, cosa che non \u00e8 avvenuta.&quot; ad oggi.&quot;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BaFin sonda Coinbase Germania<\/h2>\n\n\n\n<p>Il recente acquisto di COIN da parte di Ark coincide con il recente avvertimento dell&#039;Autorit\u00e0 federale di vigilanza finanziaria tedesca o della BaFin alla divisione tedesca di Coinbase di prestare attenzione alle sue operazioni nella regione. L&#039;accusa \u00e8 stata emessa a causa del comportamento disorganizzato, che non \u00e8 all&#039;altezza degli standard stabiliti dalla societ\u00e0. Inoltre, tale atto da parte della societ\u00e0 non \u00e8 conforme alla legislazione locale.<\/p>\n\n\n\n<p>BaFin, che \u00e8 responsabile della regolamentazione del settore dei servizi finanziari nel paese, mira ad abbassare il tasso di riciclaggio di denaro nazionale. Per raggiungere questo obiettivo, l&#039;organizzazione monitora organizzazioni finanziarie come servizi di pagamento, fondi pensione, banche, istituti finanziari, compagnie assicurative e altri.<\/p>\n\n\n\n<p>Secondo BaFin, Coinbase Germany \u00e8 stata oggetto di numerose richieste da parte di vari altri organismi di regolamentazione in tutto il mondo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cathie Wood\u2019s Ark Invest has recently added a stake in crypto exchange Coinbase after its biggest competitor Binance signed a deal to buy FTX\u2019s non-US business.&nbsp; Though the deal between FTX and Binance is now canceled, Ark Investment Management LLC\u2019s daily trading disclosures state that three Ark funds purchased over 420,000 shares in the US-based [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":36313,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[338],"class_list":["post-36312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-coinbase"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/11\/Coinbase-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Cathie Wood\u2019s Ark Invest has recently added a stake in crypto exchange Coinbase after its biggest competitor Binance signed a deal to buy FTX\u2019s non-US business.&nbsp; Though the deal between FTX and Binance is now canceled, Ark Investment Management LLC\u2019s daily trading disclosures state that three Ark funds purchased over 420,000 shares in the US-based&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/36312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=36312"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/36312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/36313"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=36312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=36312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=36312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}