{"id":38145,"date":"2022-11-28T18:24:06","date_gmt":"2022-11-28T18:24:06","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=38145"},"modified":"2022-11-28T18:25:06","modified_gmt":"2022-11-28T18:25:06","slug":"meta-faces-heavy-fine-for-data-breach","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/meta-faces-heavy-fine-for-data-breach\/","title":{"rendered":"Meta affronta una pesante multa per violazione dei dati"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>I regolatori irlandesi hanno multato Meta per oltre $900 milioni dal 2021.<\/strong><\/li>\n\n\n\n<li><strong>La Commissione irlandese per la protezione dei dati ha multato Meta $400 milioni per aver gestito in modo improprio i dati dei bambini.<\/strong><\/li>\n\n\n\n<li><strong>Un portavoce di Meta ha detto che la societ\u00e0 sta rivedendo la recente sanzione.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>La societ\u00e0 madre di Facebook, Meta, ha subito un altro scontro con le autorit\u00e0 europee ed \u00e8 stata multata di circa $275 milioni per aver violato la legge europea sulla protezione dei dati. IL <a aria-label=\"gigante della tecnologia (si apre in una nuova scheda)\" href=\"https:\/\/bitcoinwisdom.com\/it\/meta-ready-for-mass-layoffs-report\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">gigante tecnologico<\/a> si diceva che avesse gestito male i dati degli utenti, il che ha portato a una fuga di informazioni personali di oltre mezzo miliardo di utenti.<\/p>\n\n\n\n<p>La multa, annunciata dalla Commissione irlandese per la protezione dei dati (DPC), aumenta il totale delle multe inflitte dall&#039;autorit\u00e0 di regolamentazione contro Meta dallo scorso anno a oltre $900 milioni. A settembre l&#039;autorit\u00e0 di regolamentazione irlandese ha multato il colosso dei social media per $400 milioni per aver gestito in modo improprio i dati dei bambini.<\/p>\n\n\n\n<p>Il DPC\u00a0<a href=\"https:\/\/www.dataprotection.ie\/en\/news-media\/press-releases\/data-protection-commission-announces-decision-in-facebook-data-scraping-inquiry\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">ammesso<\/a> che la decisione contiene accertamenti di violazione degli articoli 25 (1) e 25 (2) del GDPR, che riguardano la protezione dei dati fin dalla progettazione e dalla pratica. I gruppi di difesa della privacy che vogliono che i funzionari dell&#039;Unione Europea attuino il regolamento generale sulla protezione dei dati in modo pi\u00f9 vigoroso vedranno le multe contro Meta come un enorme miglioramento. La legge, che \u00e8 stata attuata nel 2018, \u00e8 stata lodata come un punto di svolta nella regolamentazione delle imprese tecnologiche. Tuttavia, le autorit\u00e0 di regolamentazione dell&#039;UE sono state prese di mira per non aver applicato rigorosamente le linee guida.<\/p>\n\n\n\n<p>L\u2019Irlanda svolge un ruolo fondamentale nel far rispettare le leggi sulla privacy dei dati dell\u2019UE. Le principali aziende tecnologiche come Google e Meta hanno tutte la loro sede europea in Irlanda. L&#039;ultima multa contro Meta deriva da un&#039;indagine condotta dalle autorit\u00e0 di regolamentazione irlandesi nel 2021 sulla base delle accuse secondo cui Facebook non aveva protetto la sua piattaforma dallo &quot;scraping&quot; di dati, che consentivano alle informazioni degli utenti, inclusi nomi, indirizzi e date di nascita, di essere pubblicato su un forum di hacker online. Le autorit\u00e0 di regolamentazione irlandesi hanno affermato che l&#039;incidente costituisce una violazione delle leggi che richiedono la protezione dei dati personali degli utenti.<\/p>\n\n\n\n<p>Meta ha annunciato di aver adottato politiche volte a prevenire situazioni simili, sottolineando che \u201clo scraping non autorizzato dei dati \u00e8 inaccettabile e contrario alle nostre regole\u201d. Non \u00e8 noto se il colosso dei social media far\u00e0 appello contro la multa. Tuttavia, un portavoce dell\u2019azienda ha detto che sta rivedendo la decisione.<\/p>\n\n\n\n<p>Meta ha detto in una dichiarazione,<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La protezione della privacy e della sicurezza dei dati delle persone \u00e8 fondamentale per il funzionamento della nostra azienda. Ecco perch\u00e9 abbiamo collaborato pienamente con la Commissione irlandese per la protezione dei dati su questa importante questione. Abbiamo apportato modifiche ai nostri sistemi durante il periodo in questione, inclusa la rimozione della possibilit\u00e0 di eseguire lo scraping delle nostre funzionalit\u00e0 in questo modo utilizzando i numeri di telefono. <\/p>\n<\/blockquote>\n\n\n\n<p>\u00a0Meta ha affermato di aver implementato una serie di misure di sicurezza per fermare lo scraping dei dati, tra cui limiti di velocit\u00e0, strumenti tecnici per bloccare azioni automatizzate sospette e impostazioni per consentire agli utenti di scegliere la quantit\u00e0 di dati visibili al pubblico.<\/p>\n\n\n\n<p>Le autorit\u00e0 di regolamentazione in Europa stanno prestando maggiore attenzione alle aziende tecnologiche mentre la privacy degli utenti diventa una conversazione globale. Anche altre aziende tecnologiche, come Amazon, sono state esaminate dalle autorit\u00e0 di regolamentazione per alcune delle loro pratiche. L&#039;anno scorso, Amazon ha ricevuto una multa di quasi 750 milioni di euro dalle autorit\u00e0 di regolamentazione in Lussemburgo per le sue pratiche pubblicitarie online.<\/p>","protected":false},"excerpt":{"rendered":"<p>La societ\u00e0 madre di Facebook, Meta, ha subito un altro scontro con le autorit\u00e0 europee ed \u00e8 stata multata di circa $275 milioni per aver violato la legge europea sulla protezione dei dati. Si dice che il gigante della tecnologia abbia gestito male i dati degli utenti, il che ha portato alla fuga delle informazioni personali di oltre mezzo miliardo di utenti. La multa, annunciata dall&#039;irlandese Data [\u2026]<\/p>","protected":false},"author":19,"featured_media":8401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[191,12],"tags":[687,588],"class_list":["post-38145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-talk","category-news","tag-european-union","tag-meta"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration.jpg",1280,804,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration-300x188.jpg",300,188,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration-768x482.jpg",640,402,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration-1024x643.jpg",640,402,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration.jpg",1280,804,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration.jpg",1280,804,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/Meta-Experimenting-Facebooks-NFT-Integration.jpg",18,12,false]},"uagb_author_info":{"display_name":"Lawrence Woriji","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/lawrencew\/"},"uagb_comment_info":0,"uagb_excerpt":"Facebook&#8217;s parent company, Meta, has suffered another brush with European authorities and has been fined roughly $275 million for breaching European data protection law. The tech giant was said to have mishandled user data, which led to a leak of the personal information of over half a billion users. The fine, announced by Ireland\u2019s Data&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/38145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=38145"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/38145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/8401"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=38145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=38145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=38145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}