{"id":42759,"date":"2023-01-15T11:24:41","date_gmt":"2023-01-15T11:24:41","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=42759"},"modified":"2023-01-15T11:24:41","modified_gmt":"2023-01-15T11:24:41","slug":"hodlnaut-creditors-demand-liquidation","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/hodlnaut-creditors-demand-liquidation\/","title":{"rendered":"I creditori Hodlnaut non cercano una ristrutturazione, chiedono la liquidazione"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>I creditori del prestatore di criptovalute Hodlnaut preferiscono la liquidazione dei beni e non sono favorevoli ai piani di ristrutturazione dell&#039;azienda. <\/strong><\/li>\n\n\n\n<li><strong>Una ristrutturazione rimetterebbe i direttori, che hanno portato al crollo della societ\u00e0 di criptovalute, ancora una volta a capo delle sue operazioni. <\/strong><\/li>\n\n\n\n<li><strong>Hodlnaut aveva esposizione all&#039;ecosistema Terra di Do Kwon e allo scambio di criptovalute di Sam Bankman-Fried, FTX.<\/strong><\/li>\n\n\n\n<li><strong>Di recente, la polizia di Singapore ha avviato un&#039;indagine sul prestatore di criptovalute per segnalazioni di presunte frodi.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Tra le numerose societ\u00e0 di criptovalute che hanno presentato istanza di protezione dai creditori ai sensi del capitolo 11, molte hanno scelto di seguire un piano di ristrutturazione in modo da poter continuare con le loro operazioni e pagare le persone a cui devono i soldi. Tuttavia, alcuni creditori vogliono che queste societ\u00e0 crittografiche vendano tutti gli asset che potrebbero avere in modo da poter recuperare i soldi il prima possibile. \u00c8 fondamentale notare che i creditori del prestatore di criptovalute Hodlnaut preferiscono la liquidazione dei beni.&nbsp;<\/p>\n\n\n\n<p>Secondo un rapporto di <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2023-01-13\/singapore-crypto-firm-hodlnaut-s-creditors-seek-its-liquidation?sref=IIP4JEyu\" rel=\"nofollow noopener\" target=\"_blank\">Bloomberg<\/a>, i creditori di Hodlnaut non sono molto favorevoli al piano di ristrutturazione che \u00e8 stato loro presentato perch\u00e9 ci\u00f2 significherebbe che gli amministratori in base ai quali \u00e8 fallita la piattaforma di prestito e prestito di criptovalute con sede a Singapore rimarrebbero responsabili delle operazioni fino a quando l&#039;azienda non sar\u00e0 in grado di pagare indietro i creditori.&nbsp;<\/p>\n\n\n\n<p>\u00c8 interessante notare che il rapporto afferma che i creditori di Hodlnaut vogliono sciogliere l&#039;azienda il prima possibile in modo da poter massimizzare ci\u00f2 che possono ottenere dalla piattaforma. Ci\u00f2 aiuter\u00e0 i creditori a distribuire tra loro gli asset rimanenti e ad evitare un ulteriore collasso dell\u2019azienda poich\u00e9 l\u2019inverno delle criptovalute non finir\u00e0 presto.&nbsp;<\/p>\n\n\n\n<p>Come riportato in precedenza da <a href=\"https:\/\/bitcoinwisdom.com\/it\/hodlnaut-lost-190m-in-terra-ecosystem-crash\/\">BitcoinSaggezza<\/a>, Hodlnaut ha perso $190 milioni a causa del crollo della stablecoin Terra, o UST (ora USTC o Terra Classic USD), dopo aver convertito alcune delle sue partecipazioni in asset digitali in UST all&#039;inizio del 2022. Il crollo di Terra sotto la guida di Do Kwon , la cui ultima posizione nota \u00e8 la Siberia, ha danneggiato molte aziende crittografiche.<\/p>\n\n\n\n<p>A seguito della sua interruzione del ritiro, Hodlnaut ha licenziato alcuni dipendenti e ha anche presentato istanza di collocamento presso dirigenti giudiziari provvisori nominati con ordinanza del tribunale a <a href=\"https:\/\/bitcoinwisdom.com\/it\/distressed-crypto-lending-protocol-hodlnaut-sends-home-40-employees-applies-for-singapores-judicial-management\/\">tutelare gli interessi dei creditori<\/a>, secondo un rapporto di BitcoinWisdom. \u00c8 inoltre fondamentale notare che la piattaforma di prestito crittografico ha cancellato oltre 1.000 documenti &quot;chiave&quot; che avrebbero potuto rivelarsi di valore significativo rispetto alle pratiche dell&#039;azienda e alla sua esposizione alla stablecoin. <\/p>\n\n\n\n<p>I problemi della piattaforma di prestito crittografico non hanno avuto fine poich\u00e9 \u00e8 stata nuovamente colpita dal crollo dell&#039;exchange di criptovalute multimiliardario. <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/it\/ftx-review\/\" title=\"FTX\" data-wpil-keyword-link=\"linked\">FTX<\/a>, sotto la guida del suo fondatore, Sam Bankman-Fried, noto anche come SBF nel settore delle criptovalute. Secondo quanto riferito, Hodlnaut deteneva quasi $13 milioni nello scambio, che ha anche congelato i prelievi e ha presentato istanza di fallimento del Capitolo 11. D&#039;altra parte, SBF ha <a href=\"https:\/\/bitcoinwisdom.com\/it\/bankman-fried-denies-fraud-allegations\/\">ha negato tutte le accuse mossegli<\/a> e ha affermato che FTX sarebbe stato solvibile se avesse continuato a guidare l&#039;azienda.<\/p>\n\n\n\n<p>\u00c8 interessante notare che la polizia di Singapore ha avviato un&#039;indagine sul prestatore di criptovalute dopo aver ricevuto numerose segnalazioni secondo cui i direttori e i dirigenti dell&#039;azienda tradivano i loro clienti. I rapporti affermavano inoltre che Hodlnaut &quot;ha rilasciato false dichiarazioni sull&#039;accesso dell&#039;azienda a un determinato token digitale&quot;.<\/p>","protected":false},"excerpt":{"rendered":"<p>I creditori del prestatore di criptovalute Hodlnaut preferiscono la liquidazione dei beni e non sono favorevoli ai piani di ristrutturazione dell&#039;azienda. <\/p>","protected":false},"author":21,"featured_media":42760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[190,12],"tags":[135,172,1398],"class_list":["post-42759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-blockchain","tag-crypto","tag-hodlnaut"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut.jpg",1650,928,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut.jpg",1650,928,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/01\/Hodlnaut-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The creditors of crypto lender Hodlnaut prefer the liquidation of assets and are not in favor of the firm's restructuring plans.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/42759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=42759"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/42759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/42760"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=42759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=42759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=42759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}