{"id":48972,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=48972"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"billionaire-believes-bitcoin-might-reach-30k-this-quarter","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/billionaire-believes-bitcoin-might-reach-30k-this-quarter\/","title":{"rendered":"Il miliardario crede che Bitcoin potrebbe raggiungere $30K questo trimestre"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>L&#039;investitore miliardario Mike Novogratz ha dichiarato che Bitcoin (BTC) dovrebbe raggiungere un prezzo di $30.000 in questo trimestre.<\/strong><\/li>\n\n\n\n<li><strong>Nelle ultime 24 ore, Bitcoin ha visto il suo pi\u00f9 grande guadagno in oltre un mese, quando il suo prezzo \u00e8 salito alle stelle di 12%.<\/strong><\/li>\n\n\n\n<li><strong>Secondo i dati di Lookonchain, negli ultimi sei giorni sono confluiti nel mercato delle criptovalute quasi $1,6 miliardi di fondi istituzionali.<\/strong><\/li>\n\n\n\n<li><strong>La maggior parte dei fondi era sotto forma di stablecoin, in particolare la moneta USD emessa da Circle.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Il crollo delle societ\u00e0 crittografiche nel 2022 ha spinto la moneta crittografica pi\u00f9 grande del mondo, Bitcoin (BTC), su una traiettoria discendente dalla quale il token non \u00e8 stato in grado di riprendersi per diversi mesi. \u00c8 interessante notare che il supporto della blockchain e della tecnologia crittografica \u00e8 recentemente arrivato a sostegno della principale criptovaluta con l&#039;investitore miliardario Mike Novogratz che ha affermato che ci si pu\u00f2 aspettare che la moneta crittografica raggiunga un prezzo di $30.000 in questo trimestre.&nbsp;<\/p>\n\n\n\n<p>Il 2022 \u00e8 stato probabilmente uno degli anni peggiori nel settore delle criptovalute, con Bitcoin (BTC) che \u00e8 crollato di oltre 70% rispetto al massimo storico osservato nel novembre 2021. \u00c8 interessante notare che il 2023 \u00e8 stato un anno abbastanza positivo per BTC poich\u00e9 il principale asset digitale ha riconquistato il $ Capitalizzazione di mercato di 400 miliardi di dollari. Nel frattempo, anche i parametri on-chain della criptovaluta stanno diventando rialzisti.&nbsp;<\/p>\n\n\n\n<p>Novogratz, che \u00e8 il CEO e fondatore di Galaxy Digital, una societ\u00e0 di servizi finanziari e gestione degli investimenti, ha dichiarato che non sar\u00e0 sorpreso se Bitcoin superer\u00e0 con successo il livello di prezzo $30.000 in questo trimestre. Inoltre, presso una Bank of America <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2023-02-15\/novogratz-sees-chance-of-bitcoin-hitting-30-000-this-quarter?sref=323RPL5z#xj4y7vzkg\" rel=\"nofollow noopener\" target=\"_blank\">conferenza<\/a> il 15 febbraio Novogratz ha fatto i seguenti commenti:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cQuando guardo l&#039;azione dei prezzi, quando guardo l&#039;entusiasmo dei clienti che chiamano, la FOMO che cresce, non mi sorprenderebbe se fossimo a $30.000 entro la fine del trimestre. E avrei dato entrambe le mie scarpe perch\u00e9 ci\u00f2 fosse vero solo sei settimane fa&quot;, ha detto aggiungendo, &quot;come se finissimo l&#039;anno $30.000, sar\u00f2 il ragazzo pi\u00f9 felice.&quot;<\/p>\n<\/blockquote>\n\n\n\n<p>\u00c8 anche fondamentale notare che nelle ultime 24 ore Bitcoin ha visto il suo pi\u00f9 grande guadagno in oltre un mese, quando il suo prezzo \u00e8 salito alle stelle di 12%. Inoltre, la criptovaluta pi\u00f9 grande \u00e8 ora tornata al di sopra della regione di prezzo $24.000 come occhio di bue per il livello di prezzo $25.000, che \u00e8 un&#039;area di resistenza per la criptovaluta.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">&quot;Non mi sorprenderebbe se fossimo a $30.000 entro la fine del trimestre&quot;, ha affermato Mike Novogratz, CEO di Galaxy Digital. <a href=\"https:\/\/t.co\/8ngwzbiQKJ\" rel=\"nofollow\">https:\/\/t.co\/8ngwzbiQKJ<\/a><\/p>\u2014 Bloomberg Crypto (@cripto) <a href=\"https:\/\/twitter.com\/crypto\/status\/1625989153895682050?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">15 febbraio 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Inoltre, per raggiungere il prezzo previsto da Novogratz, Bitcoin deve salire di altri 20%, che non \u00e8 una percentuale molto alta dato che la moneta crittografica \u00e8 salita di 12% in un solo giorno. \u00c8 anche fondamentale notare che il sentimento degli investitori nel mercato delle criptovalute si \u00e8 finalmente trasformato in avidit\u00e0, il che conferma il fatto che la pressione di acquisto per BTC \u00e8 aumentata in modo significativo.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">L\u2019indice Bitcoin Fear and Greed \u00e8 62 \u2013 Avidit\u00e0<br>Prezzo attuale: $24.587 <a href=\"https:\/\/t.co\/Ao9qHlIgxl\" rel=\"nofollow\">pic.twitter.com\/Ao9qHlIgxl<\/a><\/p>\u2014 Indice Bitcoin Fear and Greed (@BitcoinFear) <a href=\"https:\/\/twitter.com\/BitcoinFear\/status\/1626182126499405825?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">16 febbraio 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Come riportato in precedenza da BitcoinWisdom, Novogratz lo aveva previsto <a href=\"https:\/\/bitcoinwisdom.com\/it\/bitcoin-will-hit-500k-predicts-mike-novogratz\/\">Bitcoin raggiunger\u00e0 un prezzo di $500.000<\/a> ma \u201cnon tra cinque anni\u201d a causa delle condizioni sfavorevoli. L&#039;investitore miliardario ha affermato che il presidente della Federal Reserve Jerome Powell ha trovato &quot;i suoi superpoteri bancari centrali&quot; che hanno peggiorato l&#039;azione dei prezzi di BTC e messo la principale criptovaluta su una traiettoria ribassista.&nbsp;<\/p>\n\n\n\n<p>Inoltre, all&#039;evento Token2049 tenutosi a Marina Bay Sands, Singapore, il CEO di Galaxy Digital ha dichiarato che il prossimo mercato rialzista di Bitcoin sarebbe stato un <a href=\"https:\/\/bitcoinwisdom.com\/it\/next-bitcoin-bull-run-will-be-cocktail-of-utility-and-speculation-mike-novogratz-at-token2049\/\">cocktail del 50% di utilit\u00e0 e del 50% di speculazione<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#039;investitore miliardario Mike Novogratz ha dichiarato che Bitcoin (BTC) dovrebbe raggiungere un prezzo di $30.000 in questo trimestre.<\/p>","protected":false},"author":21,"featured_media":48975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[185,12],"tags":[130,172],"class_list":["post-48972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-crypto"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2.jpg",1140,815,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-300x214.jpg",300,214,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-768x549.jpg",640,458,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-1024x732.jpg",640,458,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2.jpg",1140,815,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2.jpg",1140,815,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Billionaire investor Mike Novogratz stated that Bitcoin (BTC) can be expected to reach a price of $30,000 this quarter.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/48972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=48972"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/48972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/48975"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=48972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=48972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=48972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}