{"id":61466,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=61466"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"the-sec-has-failed-to-prove-that-do-kwon-defrauded-investors-lawyers","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/the-sec-has-failed-to-prove-that-do-kwon-defrauded-investors-lawyers\/","title":{"rendered":"La SEC non \u00e8 riuscita a dimostrare che Do Kwon ha truffato gli investitori: gli avvocati"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Gli avvocati che rappresentano il fondatore di Terraform Labs, Do Kwon, affermano che la SEC non \u00e8 stata in grado di provare che l&#039;imprenditore abbia truffato gli investitori.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>Hanno chiesto al giudice di archiviare il caso contro l&#039;imprenditore di criptovalute presentato dal regolatore perch\u00e9 le acquisizioni erano infondate.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>La SEC afferma che il creatore della stablecoin UST (ora USTC) ha truffato gli investitori vendendo loro titoli non registrati.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>Gli avvocati hanno sostenuto che la stablecoin UST (ora USTC) fosse una valuta e non un titolo, come sostiene la SEC.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Il crollo dell&#039;ecosistema Terra ha spazzato via oltre $60 miliardi dalla capitalizzazione di mercato totale del mercato delle criptovalute e l&#039;industria si sta ancora riprendendo dagli effetti di quell&#039;implosione. Tuttavia, la persona responsabile del crollo di questo ecosistema e di molti investitori costretti a vendere le proprie propriet\u00e0 per riprendersi dai debiti, Do Kwon, afferma di essere innocente. Gli avvocati che rappresentano l&#039;imprenditore di criptovalute hanno affermato che la SEC non \u00e8 riuscita a dimostrare di aver truffato gli investitori.&nbsp;<\/p>\n\n\n\n<p>Secondo un rapporto di <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2023-04-22\/do-kwon-says-sec-is-out-of-bounds-in-pursuing-crypto-fraud-suit\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">Bloomberg<\/a>, gli avvocati di Do Kwon hanno affermato il 21 aprile che la Securities and Exchange Commission (SEC) degli Stati Uniti non \u00e8 riuscita a dimostrare che il fondatore di Terraform Labs fosse responsabile di una frode. Di conseguenza, gli avvocati hanno chiesto al giudice di respingere la causa poich\u00e9 non era basata su fatti ma su sentimenti.\u00a0<\/p>\n\n\n\n<p>La SEC sostiene nella causa che Do Kwon ha ingannato gli investitori ed \u00e8 stato responsabile di aver condotto una frode offrendo titoli non registrati agli investitori in criptovalute negli Stati Uniti. Tuttavia, gli avvocati che rappresentano l&#039;imprenditore delle criptovalute hanno detto al giudice che le acquisizioni dell&#039;ente regolatore erano infondate.&nbsp;<\/p>\n\n\n\n<p>Gli avvocati hanno chiesto al giudice di archiviare il caso aggiungendo che le leggi degli Stati Uniti vietano al regolatore &quot;di utilizzare la legge federale sui titoli per affermare la giurisdizione sulle risorse digitali in questo caso&quot;. Inoltre, gli avvocati hanno affermato che la SEC non \u00e8 stata in grado di collegare Do Kwon con il crollo della stablecoin UST, aggiungendo che UST (ora USTC) non \u00e8 un titolo ma una valuta.&nbsp;<\/p>\n\n\n\n<p>Il procedimento giudiziario \u00e8 iniziato dopo <a href=\"https:\/\/bitcoinwisdom.com\/it\/do-kwon-has-been-arrested-in-montenegro\/\" class=\"ek-link\">Do Kwon \u00e8 stato arrestato<\/a> nella capitale del paese europeo Montenegro, Podgorica, il 23 marzo con documenti falsificati. Insieme all&#039;imprenditore di criptovalute, \u00e8 stato catturato anche il suo ex assistente, Han Mo, e i due sono in attesa di estradizione negli Stati Uniti o in Corea del Sud.\u00a0<\/p>\n\n\n\n<p>\u00c8 fondamentale notare qui che <a href=\"https:\/\/bitcoinwisdom.com\/it\/breaking-south-korean-court-issues-arrest-warrant-against-terra-luna-founder-do-kwon\/\" class=\"ek-link\">La Corea del Sud ha emesso un mandato<\/a> per l&#039;arresto di Do Kwon nel settembre 2022. Ora, il fondatore di Terraform Labs rischia circa cinque anni di prigione montenegrina se verr\u00e0 ritenuto colpevole di aver utilizzato passaporti costaricani falsificati per entrare in Montenegro. Inoltre, il procuratore Haris \u0160aboti\u0107 ha detto che avrebbe completato le indagini prima del 23 aprile e che, se non fossero state trovate prove sufficienti, Kwon sarebbe stato sollevato dalle accuse.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cNel caso in cui riceviamo diverse richieste di estradizione, vorrei dire che la determinazione in quale Stato verranno estradati si basa su diversi fattori come la gravit\u00e0 del reato commesso, il luogo e il momento in cui il reato \u00e8 stato commesso , l\u2019ordine con cui abbiamo ricevuto la richiesta di estradizione e molti altri fattori\u201d, ha affermato il ministro della Giustizia montenegrino Marko Kova\u010d.<\/p>\n<\/blockquote>\n\n\n\n<p>Tuttavia, spetta al giudice decidere in quale paese (Corea del Sud o Stati Uniti) Do Kwon sar\u00e0 estradato. Ancora pi\u00f9 importante, secondo un avvocato, le carceri montenegrine sono piccole e sovraffollate e prive di cure mediche adeguate, il che implica che Do Kwon passer\u00e0 un momento difficile se ritenuto colpevole dal giudice.&nbsp;<\/p>\n\n\n\n<p>Un altro fatto importante da menzionare qui \u00e8 che Do Kwon ha prepagato lo studio legale Kim &amp; Chang oltre $7 milioni prima del collasso dell&#039;ecosistema Terra. Ci\u00f2 implica che l&#039;imprenditore di criptovalute sapeva in anticipo dell&#039;implosione di Terra.<\/p>","protected":false},"excerpt":{"rendered":"<p>Gli avvocati che rappresentano il fondatore di Terraform Labs, Do Kwon, affermano che la SEC non \u00e8 stata in grado di provare che l&#039;imprenditore abbia truffato gli investitori.\u00a0<\/p>","protected":false},"author":21,"featured_media":61467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[191,12],"tags":[405,267],"class_list":["post-61466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-talk","category-news","tag-do-kwon","tag-sec"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/04\/Do-Kwon-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The lawyers representing the founder of Terraform Labs, Do Kwon, claim that the SEC has not been able to prove that the entrepreneur defrauded investors.\u00a0","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/61466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=61466"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/61466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/61467"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=61466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=61466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=61466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}