{"id":63486,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=63486"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"cash-app-reports-bitcoin-revenue-worth-2b","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/cash-app-reports-bitcoin-revenue-worth-2b\/","title":{"rendered":"L&#039;app Cash riporta entrate Bitcoin per un valore di $2B"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Block di Jack Dorsey ha realizzato un sorprendente $2.16 miliardi di entrate in Bitcoin da Cash App nel primo trimestre del 2023.<\/strong><\/li>\n\n\n\n<li><strong>Le entrate in Bitcoin dell&#039;azienda sono aumentate di 18% da $1,83 miliardi nel quarto trimestre e di 25% dal primo trimestre del 2022.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>Le azioni della societ\u00e0 sono crollate dopo che un rapporto di Hindenburg Research ha affermato che Block ha ingannato gli investitori per $1 miliardo.<\/strong><\/li>\n\n\n\n<li><strong>I ricavi multimiliardari del Bitcoin, secondo il documento degli azionisti, sono stati \u201cparzialmente compensati\u201d da un calo del prezzo del Bitcoin.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>L&#039;inverno delle criptovalute ha colpito le attivit\u00e0 di molte societ\u00e0 di criptovalute e gli scambi di criptovalute hanno registrato utili negativi per diversi trimestri nel 2022. \u00c8 interessante notare che Block, la societ\u00e0 di tecnologia finanziaria del fondatore di Twitter Jack Dorsey, ha riportato i guadagni in Bitcoin del primo trimestre dal suo prodotto principale, Cash App . Block ha subito gravi danni alla sua attivit\u00e0 a causa di una recente posizione corta aperta dalla societ\u00e0 di ricerca sugli investimenti con sede negli Stati Uniti Hindenburg Research LLC.<\/p>\n\n\n\n<p>Secondo un recente azionista<a href=\"https:\/\/s29.q4cdn.com\/628966176\/files\/doc_financials\/2023\/q1\/Shareholder-Letter_Block_1Q23.pdf\" rel=\"nofollow noopener\" target=\"_blank\"> lettera<\/a>, Block ha realizzato l&#039;incredibile cifra di $2,16 miliardi di entrate Bitcoin dalla Cash App nel primo trimestre del 2023. \u00c8 importante notare che le entrate Bitcoin dell&#039;azienda, che conteggiano le entrate Bitcoin come vendite totali della criptovaluta ai clienti, sono aumentate di 18% da $1,83. miliardi nel quarto trimestre e 25% dal primo trimestre del 2022.&nbsp;<\/p>\n\n\n\n<p>L&#039;annuncio afferma:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cAbbiamo generato un profitto lordo di $1,71 miliardi, in crescita di 32% anno su anno. Cash App ha generato un utile lordo di $931 milioni, in aumento di 49% anno su anno, e Square ha generato un utile lordo di $770 milioni, in aumento di 16% anno su anno.<\/p>\n<\/blockquote>\n\n\n\n<p>Nel primo trimestre del 2023, i profitti complessivi di Cash App hanno superato $931 milioni, indicando una crescita di 49% anno su anno. In particolare, l&#039;utile di Cash App ha superato l&#039;utile lordo della societ\u00e0, che ammontava a $1,71 miliardi.&nbsp;<\/p>\n\n\n\n<p>Il documento riporta che la crescita nel primo trimestre del 2023 \u00e8 stata guidata dalle &quot;commissioni di transazione sia della Cash App Card che del Deposito Istantaneo, nonch\u00e9 dai contributi della nostra piattaforma BNPL, dagli interessi maturati sui fondi dei clienti e dalle entrate derivanti da altri prodotti di servizi finanziari&quot;.<\/p>\n\n\n\n<p>I ricavi multimiliardari del Bitcoin, secondo il documento degli azionisti, sono stati \u201cparzialmente compensati\u201d da un calo del prezzo del Bitcoin, rispetto allo stesso periodo del 2022, e sono stati alimentati da \u201cun aumento della quantit\u00e0 di Bitcoin venduto ai clienti .\u201d<\/p>\n\n\n\n<p>Insieme ai ricavi del primo trimestre in aumento di 26% anno su anno, la societ\u00e0 fintech ha anche registrato un utile per azione di 40 centesimi, superando le proiezioni degli analisti di 35 centesimi per azione di 14%. Tuttavia, il rinomato servizio di pagamento aziendale Square, anch&#039;esso di propriet\u00e0 di Block, ha registrato un piccolo calo (3,8%) dei profitti per il quarto trimestre del 2022.<\/p>\n\n\n\n<p>Durante la conferenza sugli utili<a href=\"https:\/\/events.q4inc.com\/attendee\/650897171\" rel=\"nofollow noopener\" target=\"_blank\"> chiamata<\/a>, Dorsey ha menzionato i \u201cprotocolli aperti\u201d e l\u2019intelligenza artificiale come tecnologie che aiuterebbero l\u2019azienda a rispondere in modo efficace ai \u201ccambiamenti significativi\u201d nel sistema finanziario globale. Ha identificato la de-dollarizzazione e i continui fallimenti bancari negli Stati Uniti come le cause principali.<\/p>\n\n\n\n<p>\u00c8 interessante notare che Block ha appena introdotto circa 100 nuovi prodotti, funzionalit\u00e0 e partnership nell&#039;ecosistema di Square per aiutare i venditori a diversificare le proprie fonti di reddito e ad automatizzare maggiormente le proprie operazioni commerciali.<\/p>\n\n\n\n<p>Come riportato in precedenza da BitcoinWisdom, il fondatore di Cash App, Bob Lee, \u00e8 stato pugnalato a morte all&#039;inizio di quest&#039;anno. Nima Momeni, 38 anni, residente a Emeryville, una citt\u00e0 situata nel nord-ovest della contea di Alameda, in California, \u00e8 stata<a href=\"https:\/\/bitcoinwisdom.com\/it\/emeryville-man-accused-of-stabbing-cash-app-creator-bob-lee\/\"> arrestato per l&#039;omicidio dell&#039;imprenditore<\/a>. Il capo della polizia di San Francisco Bill Scott ha rivelato che, secondo la famiglia del defunto, Lee e Momeni si conoscevano prima dell&#039;incidente.\u00a0<\/p>\n\n\n\n<p>\u00c8 fondamentale notare che il prezzo delle azioni di Block \u00e8 crollato in modo significativo negli ultimi mesi e gli investitori hanno perso significativamente i loro investimenti. Il titolo ha subito un forte calo dopo che Hindenburg Research ha pubblicato una lunga ricerca<a href=\"https:\/\/hindenburgresearch.com\/block\/\" rel=\"nofollow noopener\" target=\"_blank\"> rapporto<\/a> sostenendo che la societ\u00e0 era responsabile di una perdita di $1 miliardo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Block di Jack Dorsey ha realizzato un sorprendente $2.16 miliardi di entrate in Bitcoin da Cash App nel primo trimestre del 2023.<\/p>","protected":false},"author":21,"featured_media":63488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[1718],"class_list":["post-63486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-cash-app"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/Cash-App-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Jack Dorsey\u2019s Block made an astonishing $2.16 billion in Bitcoin revenue from Cash App in the first quarter of 2023.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/63486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=63486"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/63486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/63488"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=63486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=63486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=63486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}