{"id":68504,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=68504"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"former-sec-chief-warns-crypto-influencers-regarding-future-actions","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/former-sec-chief-warns-crypto-influencers-regarding-future-actions\/","title":{"rendered":"L&#039;ex capo della SEC mette in guardia gli influencer crittografici riguardo alle azioni future"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>L&#039;ex capo della SEC John Reed Stark ha avvertito gli influencer di criptovaluta di essere pronti per un&#039;azione legale.<\/strong><\/li>\n\n\n\n<li><strong>Stark ha chiamato gli influencer dei social media che hanno supportato diversi progetti crittografici fraudolenti durante la corsa al rialzo.\u00a0<\/strong><\/li>\n\n\n\n<li><strong>Gli influencer coinvolti direttamente o indirettamente nella manipolazione dei prezzi di tali token dovranno affrontare l&#039;azione del regolatore.<\/strong><\/li>\n\n\n\n<li><strong>L&#039;ex capo della SEC ha sottolineato che la natura delle frodi sui titoli rende pi\u00f9 facile l&#039;identificazione e il perseguimento.\u00a0<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>La Securities and Exchange Commission (SEC) degli Stati Uniti sta perseguendo gli influencer di criptovaluta che hanno sostenuto progetti di truffa di asset digitali e sono stati indagati per aver influenzato i prezzi di diversi token sulle piattaforme dei social media. L&#039;ex capo della SEC John Reed Stark ha recentemente portato la questione su Twitter per avvertire gli influencer di criptovaluta di essere pronti per un&#039;azione legale.<\/p>\n\n\n\n<p>Mercoled\u00ec, Stark, noto per la sua forte risposta alle violazioni informatiche e alla conformit\u00e0 alle normative digitali, <a href=\"https:\/\/twitter.com\/JohnReedStark\/status\/1663642497581473794\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">chiamato<\/a> influencer dei social media che hanno supportato diversi progetti crittografici fraudolenti e influenzato direttamente o indirettamente i prezzi di mercato di tali token durante la corsa al rialzo.\u00a0<\/p>\n\n\n\n<p>Ha affermato che qualsiasi tipo di manipolazione dei prezzi \u2013 che si tratti del prezzo di titoli quotati in borsa, titoli a microcapitalizzazione, titoli di penny stock o cripto-titoli \u2013 si traduce in un grave reato penale. Ha aggiunto:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&quot;Ci\u00f2 che mi stupisce di pi\u00f9 dei promotori di criptovalute in particolare \u00e8 il modo sfacciato e arrogante con cui molti di loro truffano le loro vittime, sempre in bella vista. Che si tratti di Twitter, Discord, Instagram, Reddit, ecc., la frode \u00e8 sempre facile da trovare, facile da archiviare e facile da presentare a un giudice o a una giuria.<\/p>\n<\/blockquote>\n\n\n\n<p>A differenza di altri tipi di frode, in cui il colpevole in genere tenta di nascondersi dietro la propria identit\u00e0, l&#039;ex capo della SEC ha sottolineato che la natura delle frodi sui titoli rende pi\u00f9 facile l&#039;identificazione e il perseguimento.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cAgli enti regolatori e alle forze dell\u2019ordine basta solo accendere i loro computer per scoprire uno straordinario e splendente percorso probatorio di prove a carico convincenti e vivide. In effetti, lungi dal legare le mani al governo, i social media sono diventati la corda virtuale che molti fratelli (e sorelle) delle criptovalute usano per impiccarsi&quot;, ha affermato Stark.<\/p>\n<\/blockquote>\n\n\n\n<p>\u00c8 interessante notare che Stark ha fatto riferimento al caso del noto influencer di criptovalute Francis Sabo, che \u00e8 stato recentemente accusato di uno schema di frode di titoli da $100 milioni e accusato di manipolare azioni negoziate in borsa sui social media.<\/p>\n\n\n\n<p>Oltre a Sabo, \u00e8 stato scoperto che molti altri crypto influencer hanno infranto la legge in materia di titoli. Un noto influencer che ha attirato critiche da parte del pubblico per aver promosso progetti dubbi \u00e8 Bitboy Crypto. Lo YouTuber ha affrontato una causa da $1 miliardo per aver approvato titoli non registrati il 31 marzo. La SEC ha intentato numerose azioni legali contro influencer nel novembre 2022 per aver commercializzato i token Hex (HEX), Pulsechain (PLS) e PulseX (PLSX).<\/p>\n\n\n\n<p>Come riportato in precedenza da BitcoinWisdom, il pi\u00f9 grande scambio di criptovalute negli Stati Uniti, Coinbase, potrebbe <a href=\"https:\/\/bitcoinwisdom.com\/it\/coinbase-is-very-likely-to-face-enforcement-action-from-sec-says-berenberg\/\" class=\"ek-link\">presto affrontare un&#039;azione legale<\/a> dalla US SEC, secondo un rapporto Berenberg. Questa azione sar\u00e0 simile a quelle che il regolatore ha intrapreso contro le piattaforme di trading Bittrex e <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/it\/kraken-review\/\" title=\"Kraken\" data-wpil-keyword-link=\"linked\">Kraken<\/a> negli ultimi mesi.<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#039;ex capo della SEC John Reed Stark ha avvertito gli influencer di criptovaluta di essere pronti per un&#039;azione legale.<\/p>","protected":false},"author":21,"featured_media":68506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[135,172,267],"class_list":["post-68504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-blockchain","tag-crypto","tag-sec"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/05\/SEC-3-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Former SEC chief John Reed Stark has warned cryptocurrency influencers to be prepared for legal action.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/68504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=68504"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/68504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/68506"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=68504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=68504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=68504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}