{"id":85575,"date":"2023-09-27T22:17:52","date_gmt":"2023-09-27T22:17:52","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=85575"},"modified":"2023-09-27T22:17:52","modified_gmt":"2023-09-27T22:17:52","slug":"a-us-lawmaker-claims-sec-chairman-is-loyal","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/it\/a-us-lawmaker-claims-sec-chairman-is-loyal\/","title":{"rendered":"Un parlamentare statunitense sostiene che il presidente della SEC \u00e8 leale alle banche"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>Il parlamentare statunitense Tom Emmer ritiene che la precedente esperienza bancaria di Gensler lo renda un regolatore parziale.<\/strong><\/li>\n\n\n\n<li><strong>Emmer ha affermato che Gensler era fedele alle principali istituzioni finanziarie.<\/strong><\/li>\n\n\n\n<li><strong>Altri legislatori hanno criticato Gensler per non essere riuscito a rimanere trasparente con il Congresso.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Gary Gensler, presidente della Securities and Exchange Commission (SEC), \u00e8 comparso mercoled\u00ec davanti al Comitato per i servizi finanziari della Camera (HFSC) ed \u00e8 stato <a href=\"https:\/\/iqconnect.house.gov\/iqextranet\/view_newsletter.aspx?id=108787&amp;c=MN06TE\" target=\"_blank\" aria-label=\"oggetto (si apre in una nuova scheda)\" rel=\"noreferrer noopener nofollow\" class=\"ek-link\">soggetto<\/a> a domande e critiche severe. Il parlamentare statunitense Tom Emmer ha accusato Gensler di essere fedele a Wall Street \u201ca evidente scapito dell\u2019innovazione, della concorrenza e degli americani comuni\u201d.<\/p>\n\n\n\n<p>Emmer ha detto che \u00e8 chiaro che Gensler sta \u201clavorando per consolidare il proprio potere anche se ci\u00f2 significa schiacciare le opportunit\u00e0 per gli americani comuni e, francamente, il futuro finanziario di questo paese\u201d.<\/p>\n\n\n\n<p>Emmer ha fatto diverse allusioni all&#039;esperienza finanziaria di Gensler, che comprendeva 18 anni come partner e co-responsabile finanziario presso Goldman Sachs. Emmer ritiene che i legami di Gensler con il settore bancario gli impediscano di agire come un regolatore imparziale.<\/p>\n\n\n\n<p>Secondo Emmer,<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Considerando i tuoi 18 anni di carriera in una delle pi\u00f9 grandi banche del mondo e la fortuna finanziaria personale che hai accumulato l\u00ec, pensi che sia possibile per te fungere da regolatore imparziale e non favorire i grandi intermediari finanziari?<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Il capogruppo della maggioranza Tom Emmer interroga il presidente della SEC Gary Gensler all&#039;udienza sui servizi finanziari | 27.9.23\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/vwFQfjBJJw0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Emmer lo ha inoltre affermato<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Questa prospettiva non ha nulla a che fare con la preoccupazione che hai notato in un discorso dell&#039;anno scorso in cui hai detto, cito: &quot;Nell&#039;ultimo anno, diversi dirigenti bancari hanno condiviso con me le loro preoccupazioni sull&#039;enorme numero di depositanti che hanno trasferito denaro dalle loro banche&quot;. conti in scambi e portafogli legati alle criptovalute.<\/p>\n<\/blockquote>\n\n\n\n<p>Il rappresentante Patrick McHenry ha anche proposto durante l&#039;udienza che la SEC possa essere citata in giudizio per i documenti relativi al precedente <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/it\/ftx-review\/\" title=\"FTX\" data-wpil-keyword-link=\"linked\">FTX<\/a> L&#039;amministratore delegato Sam Bankman-Fried. McHenry ha detto che Gensler ha cercato di \u201csoffocare l\u2019ecosistema delle risorse digitali\u201d e \u201cha rifiutato di essere trasparente con il Congresso\u201d.<\/p>\n\n\n\n<p>La SEC lo ha fatto <a href=\"https:\/\/bitcoinwisdom.com\/it\/sec-accuses-binance-us-of-lack-of-transparency\/\" target=\"_blank\" aria-label=\"frequentemente (si apre in una nuova scheda)\" rel=\"noreferrer noopener\" class=\"ek-link\">frequentemente<\/a> viene criticata per aver trascurato di chiarire la propria posizione su come determinate risorse digitali si intersecano con le leggi sui titoli.<\/p>","protected":false},"excerpt":{"rendered":"<p>Gary Gensler, presidente della Securities and Exchange Commission (SEC), \u00e8 comparso mercoled\u00ec davanti al Comitato per i servizi finanziari della Camera (HFSC) ed \u00e8 stato oggetto di severe domande e critiche. Il parlamentare statunitense Tom Emmer ha accusato Gensler di essere fedele a Wall Street \u201ca evidente scapito dell\u2019innovazione, della concorrenza e degli americani comuni\u201d. Emmer ha detto che era [\u2026]<\/p>","protected":false},"author":19,"featured_media":75051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[190,12],"tags":[172,267],"class_list":["post-85575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-crypto","tag-sec"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/07\/SEC-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Lawrence Woriji","author_link":"https:\/\/bitcoinwisdom.com\/it\/author\/lawrencew\/"},"uagb_comment_info":0,"uagb_excerpt":"Gary Gensler, the chairman of the Securities and Exchange Commission (SEC), appeared before the House Financial Services Committee (HFSC) on Wednesday and was subject to severe questioning and criticism. US lawmaker Tom Emmer accused Gensler of being loyal to Wall Street &#8220;at the clear expense of innovation, competition, and everyday Americans.&#8221; Emmer said it was&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/85575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/comments?post=85575"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/posts\/85575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media\/75051"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/media?parent=85575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/categories?post=85575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/it\/wp-json\/wp\/v2\/tags?post=85575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}