{"id":20420,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=20420"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"mayor-of-japanese-city-visits-ripple-hq-but-why","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/mayor-of-japanese-city-visits-ripple-hq-but-why\/","title":{"rendered":"Prefeito da cidade japonesa visita a sede da Ripple; Mas por que?"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><strong>O prefeito da cidade de Fakuoka, Soichiro Takashima, a sexta maior cidade do Jap\u00e3o, se reuniu com o vice-presidente de estrat\u00e9gia e opera\u00e7\u00f5es corporativas da Ripple, Emi Yoshikawa e sua equipe na sede da empresa.<\/strong><\/li><li><strong>Embora o Jap\u00e3o tenha um alto imposto corporativo sobre a deten\u00e7\u00e3o de criptomoedas, as empresas japonesas n\u00e3o t\u00eam vergonha de investir em tecnologia de criptomoedas e blockchain.<\/strong><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>O prefeito da cidade de Fakuoka, Soichiro Takashima, a sexta maior cidade do Jap\u00e3o, reuniu-se com o vice-presidente de estrat\u00e9gia e opera\u00e7\u00f5es corporativas da Ripple, Emi Yoshikawa e sua equipe na sede da empresa de tecnologia sediada nos EUA. <\/p>\n\n\n\n<p>No s\u00e1bado, Yoshikawa revelou que o prefeito de Fukuoka, capital da prov\u00edncia de Fukuoka no Jap\u00e3o, tem uma popula\u00e7\u00e3o de cerca de 1,6 milh\u00e3o (em junho de 2021), visitou a sede da empresa. A tradu\u00e7\u00e3o aproximada do post do Twitter \u00e9:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cRecebemos hoje o prefeito da cidade de Fukuoka, Soichiro Takashima, e sua equipe no Ripple HQ! Fukuoka \u00e9 uma cidade l\u00edder em iniciativas Web3 no Jap\u00e3o. Hoje, o prefeito Takashima da cidade de Fukuoka e pessoas do departamento internacional visitaram a sede da Ripple! Tenho grandes esperan\u00e7as na cidade de Fukuoka, que est\u00e1 trabalhando ativamente no Web3,\u201c<\/p><cite>disse Yoshikawa em um post no Twitter. <\/cite><\/blockquote>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"ja\" dir=\"ltr\">Recebemos o prefeito da cidade de Fukuoka, Soichiro Takashima, e sua equipe no <a href=\"https:\/\/twitter.com\/Ripple?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">@Ondula\u00e7\u00e3o<\/a> Sede hoje! Fukuoka \u00e9 uma cidade l\u00edder em <a href=\"https:\/\/twitter.com\/hashtag\/Web3?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#Web3<\/a> iniciativas no Jap\u00e3o \ud83c\uddef\ud83c\uddf5.<br>\u672c \u3001 \u798f\u5ca1 \u5e02 \u9ad8\u5cf6 \u9ad8\u5cf6 \u5e02\u9577 \u3068 \u90e8\u9580 \u7b49 \u306e \u65b9 \u3005 ripple \u672c\u793e \u3092 \u8a2a\u554f \u304f\u3060\u3055\u3044 \u307e\u3057\uff01 web3 \u306b \u7684 \u306b \u53d6\u308a\u7d44\u3093 \u53d6\u308a\u7d44\u3093 \u3067 \u3044\u308b \u798f\u5ca1 \u5e02 \u5927\u5909 \u671f\u5f85 \u3057 \u3066 \u3044 \u3002\ud83d\udc4f \u3002\ud83d\udc4f \u3067 \u3067 \u798f\u5ca1 \u5e02 \u3001 \u5927\u5909 \u3057 \u3057 \u3066 \u307e\u3059 \u3002\ud83d\udc4f \u3002\ud83d\udc4f \u3002\ud83d\udc4f \u3044\u308b \u798f\u5ca1 \u5e02 \u3001 \u671f\u5f85 \u3057 \u3066 \u3044 \u307e\u3059 \u3002\ud83d\udc4f \u3002\ud83d\udc4f <a href=\"https:\/\/t.co\/IMlrwY7JTY\" rel=\"nofollow\">pic.twitter.com\/IMlrwY7JTY<\/a><\/p>-Emi Yoshikawa {X} (@emy_wng) <a href=\"https:\/\/twitter.com\/emy_wng\/status\/1560750777320124417?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">19 de agosto de 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Parece que o prefeito Takashima se interessou muito pelas opera\u00e7\u00f5es da Ripple. <\/p>\n\n\n\n<p>Em 23 de mar\u00e7o de 2022, em <a href=\"https:\/\/ripple.com\/insights\/women-in-blockchain-emi-yoshikawas-global-influence\/\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">postagem do blog<\/a>, a empresa de rede de remessas mencionou o fato de que Yoshikawa apareceu na &#039;Forbes Japan&#039; ao lado de outras mulheres pioneiras para \u201cdiscutir suas experi\u00eancias compartilhadas no espa\u00e7o blockchain\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cDepois de testemunhar a crise financeira de 2008 em Wall Street, Emi optou por mudar de rumo, frequentando a Harvard Business School para continuar seus estudos. Ela viu potencial na ind\u00fastria de cripto para preencher as rachaduras no sistema financeiro existente - um sistema que ela viu quebrar apenas alguns anos antes - e trabalha na Ripple desde 2016 \u201d,<\/p><cite>observou a empresa de pagamento. <\/cite><\/blockquote>\n\n\n\n<p>Yoshikawa tem seis anos de experi\u00eancia em blockchain e um diploma de Harvard em seu curr\u00edculo e tamb\u00e9m foi o membro fundador do Blockchain Research Center da Universidade de Kyoto. <\/p>\n\n\n\n<p>Embora n\u00e3o tenham sido revelados muitos detalhes sobre a reuni\u00e3o, pode-se confirmar que h\u00e1 chances de uma potencial parceria ou acordo entre Fakuoka City e Ripple, apesar de sua rivalidade e caso com a Comiss\u00e3o de Valores Mobili\u00e1rios dos Estados Unidos (SEC). <\/p>\n\n\n\n<p>Recentemente, notou-se tamb\u00e9m que a <a href=\"https:\/\/bitcoinwisdom.com\/pt\/crypto-lobbying-groups-in-japan\/\" class=\"ek-link\">grupos de lobby de criptomoedas no Jap\u00e3o expressaram suas preocupa\u00e7\u00f5es<\/a> sobre um imposto corporativo de cerca de 30% sobre lucros de participa\u00e7\u00f5es em criptomoedas e ganhos n\u00e3o realizados. A Japan Virtual and Crypto Asset Exchange Association e a Japan Cryptoasset Business Association (JCBA) est\u00e3o conversando com as autoridades para facilitar as leis tribut\u00e1rias corporativas.\u00a0<\/p>\n\n\n\n<p> As empresas japonesas tamb\u00e9m n\u00e3o t\u00eam vergonha de investir em criptomoedas e tecnologia blockchain. Montadoras <a href=\"https:\/\/bitcoinwisdom.com\/pt\/japanese-automakers-toyota-and-nissan-unveil-metaverse-plans\/\" class=\"ek-link\">Toyota e Nissan s\u00e3o apresentados<\/a> seus planos para as ind\u00fastrias do metaverso tamb\u00e9m. <\/p>","protected":false},"excerpt":{"rendered":"<p>The Mayor of Fakuoka City, Soichiro Takashima, the sixth largest city in Japan, met with the VP of Corporate Strategy and Operations at Ripple, Emi Yoshikawa and his team at the headquarters the firm. While Japan has high corporate tax on holding crypto, Japanese firms are not shy of investing in crypto and blockchain technology. [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":20423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":1,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[],"class_list":["post-20420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Ripple-1-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The Mayor of Fakuoka City, Soichiro Takashima, the sixth largest city in Japan, met with the VP of Corporate Strategy and Operations at Ripple, Emi Yoshikawa and his team at the headquarters the firm. While Japan has high corporate tax on holding crypto, Japanese firms are not shy of investing in crypto and blockchain technology.&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/20420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=20420"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/20420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/20423"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=20420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=20420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=20420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}