{"id":21165,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=21165"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"dutch-judge-puts-tornado-cash-developer-in-jail-for-additional-90-days","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/dutch-judge-puts-tornado-cash-developer-in-jail-for-additional-90-days\/","title":{"rendered":"Juiz holand\u00eas coloca desenvolvedora do Tornado Cash na cadeia por mais 90 dias"},"content":{"rendered":"<ul class=\"wp-block-list\"><li><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>O desenvolvedor do misturador de criptografia baseado em Ethereum, Tornado Cash, a pris\u00e3o de Alexey Pertsev pelas autoridades holandesas por supostamente facilitar a lavagem de dinheiro por meio do agora sancionado Tornado Cash, resultou em grande f\u00faria entre os membros da comunidade de criptografia h\u00e1 alguns dias.<\/p>\n\n\n\n<p>No entanto, os desenvolvimentos recentes<a href=\"https:\/\/thedefiant.io\/tornado-dev-90-days-jail\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\"> no caso tem<\/a> intensificou a rea\u00e7\u00e3o. Em um <a href=\"https:\/\/thedefiant.io\/tornado-dev-90-days-jail\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">audi\u00e7\u00e3o<\/a> que ocorreu na Holanda na quarta-feira, o juiz rejeitou os pedidos dos advogados de Pertsev para que o r\u00e9u fosse libertado sob fian\u00e7a e decidiu que ele deveria ser detido por mais tr\u00eas meses.<\/p>\n\n\n\n<p>Inicialmente levado perante um juiz de instru\u00e7\u00e3o em 12 de agosto, Pertsev, com sede em Amsterd\u00e3, recebeu um prazo de cust\u00f3dia inicial de duas semanas.<\/p>\n\n\n\n<p>Os advogados de Pertsev solicitaram que ele recebesse fian\u00e7a durante uma audi\u00eancia a portas fechadas realizada na quarta-feira em Den Bosch, na Holanda. O juiz negou o pedido e estabeleceu um prazo de 90 dias para a audi\u00eancia p\u00fablica inicial, o que significa que a audi\u00eancia p\u00fablica inicial deve ser conclu\u00edda dentro de tr\u00eas meses. Pertsev ainda n\u00e3o enfrenta formalmente nenhuma acusa\u00e7\u00e3o criminal.<\/p>\n\n\n\n<p>Como o BitcoinWisdom relatou, o <a href=\"https:\/\/bitcoinwisdom.com\/pt\/dutch-authorities-arrest-suspected-tornado-cash\/\" class=\"ek-link\">Autoridades holandesas prenderam o desenvolvedor de 29 anos<\/a> em 10 de agosto, apenas dois dias depois que o Departamento do Tesouro dos Estados Unidos imp\u00f4s san\u00e7\u00f5es \u00e0 plataforma de mistura de criptomoedas, que havia vinculado a mais de $1 bilh\u00e3o em transa\u00e7\u00f5es desonestas e hackers norte-coreanos.<\/p>\n\n\n\n<p>A pris\u00e3o n\u00e3o foi bem recebida pelos entusiastas de criptomoedas que citam v\u00e1rios casos \u00fateis de uso do Tornado Cash, que \u00e9 muito eficiente em tornar as transa\u00e7\u00f5es privadas. No entanto, a situa\u00e7\u00e3o parece continuar piorando para o mixer Ethereum. <\/p>\n\n\n\n<p>A FIOD, uma autoridade holandesa respons\u00e1vel por supervisionar as finan\u00e7as relacionadas a crimes, revelou que a investiga\u00e7\u00e3o inicial come\u00e7ou em junho, antes que os EUA impuseram san\u00e7\u00f5es ao Tornado Cash e parece que a situa\u00e7\u00e3o s\u00f3 aumentou desde ent\u00e3o. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEle \u00e9 suspeito de envolvimento na oculta\u00e7\u00e3o de fluxos financeiros criminosos e na facilita\u00e7\u00e3o da lavagem de dinheiro por meio da mistura de criptomoedas por meio do servi\u00e7o descentralizado de mistura Ethereum, Tornado Cash\u201d, \u00a0<\/p><cite>o Servi\u00e7o de Informa\u00e7\u00e3o e Investiga\u00e7\u00e3o Fiscal afirmou em\u00a0<a href=\"https:\/\/www.fiod.nl\/arrest-of-suspected-developer-of-tornado-cash\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">declara\u00e7\u00e3o<\/a><\/cite><\/blockquote>\n\n\n\n<p>O CEO da principal exchange de criptomoedas <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/pt\/kraken-review\/\" title=\"Kraken\" data-wpil-keyword-link=\"linked\">Kraken<\/a>, Josse Powell, questionou recentemente o fato se as san\u00e7\u00f5es contra o misturador Ethereum permanecer\u00e3o em um tribunal de baixa ou se \u00e9 constitucional faz\u00ea-lo. Parece que a comunidade criptogr\u00e1fica n\u00e3o est\u00e1 feliz com a decis\u00e3o tomada pelas autoridades reguladoras.<\/p>\n\n\n\n<p>Recentemente, <a href=\"https:\/\/bitcoinwisdom.com\/pt\/coin-center-to-challenge-the-us-treasury\/\" class=\"ek-link\">Coin Center disse que vai processar as autoridades<\/a> pelas san\u00e7\u00f5es que impuseram ao Tornado Cash, considerando-o uma medida inconstitucional. A empresa sem fins lucrativos disse que as san\u00e7\u00f5es violam potencialmente \u201cos direitos constitucionais ao devido processo e \u00e0 liberdade de express\u00e3o, e que a OFAC n\u00e3o agiu adequadamente para mitigar o impacto previs\u00edvel que a sua a\u00e7\u00e3o teria sobre americanos inocentes\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>The developer of Ethereum-based crypto mixer Tornado Cash, Alexey Pertsev\u2019s arrest by Dutch authorities for allegedly facilitating money laundering via the now-sanctioned Tornado Cash, resulted in a serious rage among crypto community members a few days back. However, the recent developments in the case have intensified the backlash. At a hearing that took place in [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":21169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[1213],"class_list":["post-21165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-tornado-cash"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/08\/Tornado-Cash-3-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"The developer of Ethereum-based crypto mixer Tornado Cash, Alexey Pertsev\u2019s arrest by Dutch authorities for allegedly facilitating money laundering via the now-sanctioned Tornado Cash, resulted in a serious rage among crypto community members a few days back. However, the recent developments in the case have intensified the backlash. At a hearing that took place in&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/21165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=21165"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/21165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/21169"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=21165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=21165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=21165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}