{"id":2762,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=2762"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"riot-blockchain-to-develop-of-mining-capacity","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/riot-blockchain-to-develop-of-mining-capacity\/","title":{"rendered":"Riot Blockchain desenvolver\u00e1 1 GW de capacidade de minera\u00e7\u00e3o"},"content":{"rendered":"<p>Riot Blockchain (RIOT). \u00e9 uma das maiores empresas de minera\u00e7\u00e3o de bitcoin (BTC) de capital aberto do mundo. A empresa anunciou hoje que desenvolver\u00e1 1 gigawatt (GW) de capacidade de energia no condado de Navarro, Texas, dedicado \u00e0 minera\u00e7\u00e3o de bitcoin. A mudan\u00e7a far\u00e1 da Riot uma das maiores mineradoras da Am\u00e9rica do Norte.<\/p>\n\n\n\n<p>A Riot tem sido um importante player no espa\u00e7o de minera\u00e7\u00e3o de BTC desde que foi fundada em 2017. A empresa minerou mais de 250.000 BTC desde a sua cria\u00e7\u00e3o.<\/p>\n\n\n\n<p>A expans\u00e3o da Riot est\u00e1 programada para ocorrer em fases. A primeira fase envolver\u00e1 uma capacidade inicial de 400 megawatts (MW) com computadores refrigerados por imers\u00e3o instalados em 265 acres de terra, com opera\u00e7\u00f5es de minera\u00e7\u00e3o e hospedagem previstas para come\u00e7ar em julho de 2023, a empresa&nbsp;<a href=\"https:\/\/www.riotblockchain.com\/investors\/news-events\/press-releases\/detail\/127\/riot-blockchain-announces-1-gw-development-in-navarro\" rel=\"noreferrer noopener nofollow\" target=\"_blank\">anunciado em comunicado<\/a>.<\/p>\n\n\n\n<p>Os 600 MW restantes de capacidade de minera\u00e7\u00e3o entrar\u00e3o em opera\u00e7\u00e3o em tr\u00eas fases nos pr\u00f3ximos 18 meses. Quando tudo estiver dito e feito, a Riot estima que o custo total da primeira fase da expans\u00e3o ser\u00e1 de cerca de $333 milh\u00f5es, que est\u00e1 programado para ser investido no restante de 2022, 2023 e no primeiro trimestre de 2024.<\/p>\n\n\n\n<p>\u201cAp\u00f3s a conclus\u00e3o da expans\u00e3o, a capacidade desenvolvida da Riot totalizar\u00e1 1,7 GW, estabelecendo a empresa entre as maiores opera\u00e7\u00f5es de minera\u00e7\u00e3o de bitcoin do mundo\u201d, disse o CEO da Riot, Jason Les, no comunicado.<\/p>\n\n\n\n<p>Em um&nbsp;<a href=\"https:\/\/d1io3yog0oux5.cloudfront.net\/_76f92ccf67adada44bc381075ca0bc4d\/riotblockchain\/db\/447\/4156\/pdf\/Riot+Corporate+Deck+Updated+March+18+2022.pdf\" rel=\"noreferrer noopener nofollow\" target=\"_blank\">apresenta\u00e7\u00e3o recente<\/a>&nbsp;da Riot, a empresa anunciou que tem cerca de $312,3 milh\u00f5es em dinheiro. Isso segue o arquivamento de 1\u00ba de abril, a Riot solicitou a venda de at\u00e9 $500 milh\u00f5es em a\u00e7\u00f5es de tempos em tempos, tamb\u00e9m conhecida como oferta \u201cat-the-market\u201d (ATM), cujos recursos podem ser usados para investimentos em projetos existentes e futuros.<\/p>\n\n\n\n<p>A Riot teve um desempenho impressionante este ano, com o estoque acima de 1.600% desde meados de janeiro. Em 16 de abril, a Riot anunciou que havia aumentado seu hashrate em mais 42%. O local de expans\u00e3o proposto est\u00e1 dentro de duas horas das instala\u00e7\u00f5es de Whinstone da Riot, que tem uma capacidade total de energia de 750 MW com 400 MW atualmente desenvolvidos. Isso economizar\u00e1 para a empresa uma economia significativa de custos de energia devido \u00e0 sua proximidade a uma subesta\u00e7\u00e3o.<\/p>\n\n\n\n<p>A Riot Blockchain (RIOT) \u00e9 uma das principais empresas de minera\u00e7\u00e3o de criptomoedas do mundo e continua expandindo suas opera\u00e7\u00f5es. A Riot far\u00e1 parceria com a Priority Power para gerenciamento de desenvolvimento de sites, interconex\u00e3o de concession\u00e1rias, contratos de compra de energia e flexibilidade de carga de energia.<\/p>\n\n\n\n<p>\u201cNosso aumento de hashrate e capacidade de reduzir nossos custos de energia por meio de nossa expans\u00e3o cont\u00ednua na Am\u00e9rica do Norte \u00e9 uma prova da dedica\u00e7\u00e3o da Riot em ser uma empresa l\u00edder de minera\u00e7\u00e3o de bitcoin\u201d, disse Jeffrey Fulton, COO da Riot Blockchain.<\/p>\n\n\n\n<p>\u201c\u00c0 medida que continuamos a executar nosso plano de neg\u00f3cios, acreditamos que nossa escala, eletricidade de baixo custo e alto desempenho nos permitir\u00e3o manter uma posi\u00e7\u00e3o de lideran\u00e7a no setor de minera\u00e7\u00e3o de bitcoin\u201d, disse Jason Les, CEO da Riot, em comunicado.<\/p>\n\n\n\n<p>A Riot \u00e9 uma das maiores mineradoras p\u00fablicas de bitcoin na Am\u00e9rica do Norte, com aproximadamente 2.400 plataformas de minera\u00e7\u00e3o de criptomoedas implantadas. As principais opera\u00e7\u00f5es da empresa est\u00e3o localizadas no estado de Washington Central, onde tem acesso a algumas das energias hidrel\u00e9tricas de menor custo do pa\u00eds.<\/p>\n\n\n\n<p>Em janeiro, a Riot concluiu um aumento de capital de $200 milh\u00f5es para financiar a expans\u00e3o de suas opera\u00e7\u00f5es de minera\u00e7\u00e3o de bitcoin. Na \u00e9poca, a Riot disse que planejava usar os recursos para adicionar at\u00e9 4.000 novos S19 Pro Antminers da Bitmain e 1.000 mineradores Innosilicon T3+.<\/p>\n\n\n\n<p>Al\u00e9m das opera\u00e7\u00f5es de autominera\u00e7\u00e3o da empresa, a Riot hospeda aproximadamente 200MW de clientes institucionais de minera\u00e7\u00e3o de bitcoin em suas instala\u00e7\u00f5es. No m\u00eas passado, a Riot anunciou que havia firmado um acordo definitivo para adquirir a Whinstone US, Inc., uma operadora de instala\u00e7\u00f5es de minera\u00e7\u00e3o de bitcoin em Rockdale, Texas. A expectativa \u00e9 que o neg\u00f3cio seja fechado ainda este ano.<\/p>\n\n\n\n<p>A Riot Blockchain n\u00e3o \u00e9 a \u00fanica empresa que tenta tirar proveito da eletricidade barata e dos baixos custos trabalhistas no Texas. No ano passado, a Hashflare abriu uma instala\u00e7\u00e3o de minera\u00e7\u00e3o de bitcoin em Rockdale que pode acomodar at\u00e9 1.000 S9 Antminers. A empresa alem\u00e3 Envion AG anunciou planos em janeiro passado para um data center de 85 MW alimentado por energia renov\u00e1vel de parques e\u00f3licos do Texas. Mais recentemente, a gigante de minera\u00e7\u00e3o de criptomoedas Bitmain anunciou na ter\u00e7a-feira que construir\u00e1 sua segunda instala\u00e7\u00e3o de minera\u00e7\u00e3o nos EUA perto de Rockdale.<\/p>","protected":false},"excerpt":{"rendered":"<p>Riot Blockchain (RIOT). is one of the largest publicly traded bitcoin (BTC) mining companies in the world. The company announced today it will develop 1 gigawatt (GW) of power capacity in Navarro County, Texas dedicated to bitcoin mining. The move will make Riot one of the largest miners in North America. Riot has been a [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2763,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[190,12],"tags":[135,172,170],"class_list":["post-2762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-blockchain","tag-crypto","tag-mining"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8.jpg",1600,900,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8.jpg",1600,900,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/04\/chmwbyk5ve8.jpg",18,10,false]},"uagb_author_info":{"display_name":"Martin K","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/martin\/"},"uagb_comment_info":0,"uagb_excerpt":"Riot Blockchain (RIOT). is one of the largest publicly traded bitcoin (BTC) mining companies in the world. The company announced today it will develop 1 gigawatt (GW) of power capacity in Navarro County, Texas dedicated to bitcoin mining. The move will make Riot one of the largest miners in North America. Riot has been a&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/2762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=2762"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/2762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/2763"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=2762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=2762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}