{"id":48972,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=48972"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"billionaire-believes-bitcoin-might-reach-30k-this-quarter","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/billionaire-believes-bitcoin-might-reach-30k-this-quarter\/","title":{"rendered":"Bilion\u00e1rio acredita que Bitcoin pode chegar a $30K neste trimestre"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>O investidor bilion\u00e1rio Mike Novogratz afirmou que o Bitcoin (BTC) pode atingir um pre\u00e7o de $30.000 neste trimestre.<\/strong><\/li>\n\n\n\n<li><strong>Nas \u00faltimas 24 horas, o Bitcoin teve seu maior ganho em mais de um m\u00eas, quando seu pre\u00e7o disparou em 12%.<\/strong><\/li>\n\n\n\n<li><strong>De acordo com dados da Lookonchain, quase $1,6 bilh\u00f5es em fundos institucionais entraram no mercado de criptomoedas nos \u00faltimos seis dias.<\/strong><\/li>\n\n\n\n<li><strong>A maioria dos fundos estava na forma de stablecoins, especialmente a USD Coin emitida pela Circle.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>O colapso das empresas de criptografia em 2022 empurrou a maior moeda criptogr\u00e1fica do mundo, Bitcoin (BTC), para uma trajet\u00f3ria descendente da qual o token n\u00e3o consegue se recuperar h\u00e1 v\u00e1rios meses. Curiosamente, o apoio da blockchain e da tecnologia criptogr\u00e1fica veio recentemente em apoio \u00e0 criptomoeda l\u00edder, com o investidor bilion\u00e1rio Mike Novogratz afirmando que a criptomoeda pode atingir um pre\u00e7o de $30.000 neste trimestre.&nbsp;<\/p>\n\n\n\n<p>2022 foi provavelmente um dos piores anos na ind\u00fastria de criptografia, com o Bitcoin (BTC) caindo mais de 70% desde seu m\u00e1ximo hist\u00f3rico testemunhado em novembro de 2021. Curiosamente, 2023 foi um ano bastante positivo para o BTC, j\u00e1 que o principal ativo digital recuperou o Capitaliza\u00e7\u00e3o de mercado de $400 bilh\u00f5es de d\u00f3lares. Enquanto isso, as m\u00e9tricas da rede da criptomoeda tamb\u00e9m est\u00e3o se tornando otimistas.&nbsp;<\/p>\n\n\n\n<p>Novogratz, que \u00e9 CEO e fundador da Galaxy Digital, uma empresa de servi\u00e7os financeiros e gest\u00e3o de investimentos, afirmou que n\u00e3o ficar\u00e1 surpreso se o Bitcoin quebrar com sucesso o n\u00edvel de pre\u00e7o de $30.000 neste trimestre. Al\u00e9m disso, em um Banco da Am\u00e9rica <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2023-02-15\/novogratz-sees-chance-of-bitcoin-hitting-30-000-this-quarter?sref=323RPL5z#xj4y7vzkg\" rel=\"nofollow noopener\" target=\"_blank\">confer\u00eancia<\/a> em 15 de fevereiro, Novogratz fez os seguintes coment\u00e1rios:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cQuando observo a a\u00e7\u00e3o do pre\u00e7o, quando observo o entusiasmo dos clientes ligando, o aumento do FOMO, n\u00e3o me surpreenderia se estiv\u00e9ssemos em $30.000 at\u00e9 o final do trimestre. E eu teria dado os dois sapatos para que isso fosse verdade h\u00e1 apenas seis semanas\u201d, disse ele, acrescentando: \u201cSe terminarmos o ano com $30.000, serei o cara mais feliz\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p>Tamb\u00e9m \u00e9 crucial observar que, nas \u00faltimas 24 horas, o Bitcoin teve seu maior ganho em mais de um m\u00eas, quando seu pre\u00e7o disparou em 12%. Al\u00e9m disso, a maior moeda criptogr\u00e1fica est\u00e1 agora acima da regi\u00e3o de pre\u00e7os $24.000 como o alvo para o n\u00edvel de pre\u00e7os $25.000, que \u00e9 uma \u00e1rea de resist\u00eancia para a criptomoeda.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\u201cN\u00e3o me surpreenderia se estiv\u00e9ssemos em $30.000 at\u00e9 o final do trimestre\u201d, disse o CEO da Galaxy Digital, Mike Novogratz. <a href=\"https:\/\/t.co\/8ngwzbiQKJ\" rel=\"nofollow\">https:\/\/t.co\/8ngwzbiQKJ<\/a><\/p>\u2014 Bloomberg Crypto (@crypto) <a href=\"https:\/\/twitter.com\/crypto\/status\/1625989153895682050?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">15 de fevereiro de 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Al\u00e9m disso, para atingir o pre\u00e7o previsto por Novogratz, o Bitcoin precisa saltar mais 20%, o que n\u00e3o \u00e9 um percentual muito alto, visto que a criptomoeda saltou 12% em um \u00fanico dia. \u00c9 tamb\u00e9m crucial notar que o sentimento dos investidores no mercado criptogr\u00e1fico finalmente se transformou em gan\u00e2ncia, o que confirma o facto de a press\u00e3o de compra do BTC ter aumentado significativamente.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">O \u00edndice de medo e gan\u00e2ncia do Bitcoin \u00e9 62 \u2013 Gan\u00e2ncia<br>Pre\u00e7o atual: $24.587 <a href=\"https:\/\/t.co\/Ao9qHlIgxl\" rel=\"nofollow\">pic.twitter.com\/Ao9qHlIgxl<\/a><\/p>\u2014 \u00cdndice de Medo e Gan\u00e2ncia do Bitcoin (@BitcoinFear) <a href=\"https:\/\/twitter.com\/BitcoinFear\/status\/1626182126499405825?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">16 de fevereiro de 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Conforme relatado anteriormente por BitcoinWisdom, Novogratz previu que <a href=\"https:\/\/bitcoinwisdom.com\/pt\/bitcoin-will-hit-500k-predicts-mike-novogratz\/\">Bitcoin atingir\u00e1 um pre\u00e7o de $500.000<\/a> mas \u201cn\u00e3o em cinco anos\u201d devido a condi\u00e7\u00f5es desfavor\u00e1veis. O investidor bilion\u00e1rio afirmou que o presidente do Federal Reserve, Jerome Powell, encontrou \u201cseus superpoderes de banco central\u201d que pioraram a a\u00e7\u00e3o dos pre\u00e7os do BTC e colocaram a principal criptomoeda em uma trajet\u00f3ria de baixa.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, no evento Token2049 realizado em Marina Bay Sands, Cingapura, o CEO da Galaxy Digital afirmou que o pr\u00f3ximo mercado de alta do Bitcoin seria um <a href=\"https:\/\/bitcoinwisdom.com\/pt\/next-bitcoin-bull-run-will-be-cocktail-of-utility-and-speculation-mike-novogratz-at-token2049\/\">coquetel de 50% de utilidade e 50% de especula\u00e7\u00e3o<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>O investidor bilion\u00e1rio Mike Novogratz afirmou que o Bitcoin (BTC) pode atingir um pre\u00e7o de $30.000 neste trimestre.<\/p>","protected":false},"author":21,"featured_media":48975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[185,12],"tags":[130,172],"class_list":["post-48972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-crypto"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2.jpg",1140,815,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-300x214.jpg",300,214,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-768x549.jpg",640,458,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-1024x732.jpg",640,458,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2.jpg",1140,815,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2.jpg",1140,815,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/02\/Bitcoin-2-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Billionaire investor Mike Novogratz stated that Bitcoin (BTC) can be expected to reach a price of $30,000 this quarter.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/48972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=48972"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/48972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/48975"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=48972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=48972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=48972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}