{"id":65602,"date":"2023-05-16T16:38:05","date_gmt":"2023-05-16T16:38:05","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=65602"},"modified":"2023-05-16T16:38:09","modified_gmt":"2023-05-16T16:38:09","slug":"mica-receives-final-approval-from-eu-finance","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/mica-receives-final-approval-from-eu-finance\/","title":{"rendered":"MiCA Recebe Aprova\u00e7\u00e3o Final dos Ministros das Finan\u00e7as da UE"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>MiCA fornece a primeira pol\u00edtica abrangente do mundo sobre criptomoedas.<\/strong><\/li>\n\n\n\n<li><strong>A nova pol\u00edtica cobre os requisitos legais e processos de registro para provedores de carteira, trocas de criptomoedas e emissores.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>Ap\u00f3s uma vota\u00e7\u00e3o na ter\u00e7a-feira, 16 de maio, o Conselho de Assuntos Econ\u00f3micos e Financeiros da Uni\u00e3o Europeia, composto pelos ministros das finan\u00e7as de todos os estados membros, aprovou a t\u00e3o aguardada lei dos Mercados de Criptoativos (MiCA). A vota\u00e7\u00e3o foi amplamente vista como o obst\u00e1culo legislativo final. Os ministros votaram a favor da regulamenta\u00e7\u00e3o hist\u00f3rica da criptografia e das altera\u00e7\u00f5es a algumas das pol\u00edticas relacionadas com a lei.<\/p>\n\n\n\n<p>Elisabeth Svantesson, Ministra das Finan\u00e7as da Su\u00e9cia e presidente da reuni\u00e3o, expressou a sua satisfa\u00e7\u00e3o com o novo regulamento num <a href=\"https:\/\/www.consilium.europa.eu\/en\/press\/press-releases\/2023\/05\/16\/digital-finance-council-adopts-new-rules-on-markets-in-crypto-assets-mica\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">declara\u00e7\u00e3o<\/a>. Ela observou que \u201cos eventos recentes confirmaram a necessidade urgente de impor regras que protejam melhor os europeus que investiram nestes ativos e evitem o uso indevido da ind\u00fastria criptogr\u00e1fica para fins de lavagem de dinheiro e financiamento do terrorismo\u201d.<\/p>\n\n\n\n<p>Espera-se que o regulamento se torne lei neste ver\u00e3o, ap\u00f3s receber a aprova\u00e7\u00e3o dos ministros das finan\u00e7as. O pr\u00f3ximo passo envolve a publica\u00e7\u00e3o das regras no jornal oficial da UE. Posteriormente, haver\u00e1 um per\u00edodo de transi\u00e7\u00e3o para permitir que as empresas e os reguladores se ajustem aos novos regulamentos antes de serem completamente implementados. Segundo relatos, algumas regulamenta\u00e7\u00f5es de stablecoin entrar\u00e3o em vigor daqui a um ano, enquanto outras s\u00f3 entrar\u00e3o em vigor daqui a 18 meses.<\/p>\n\n\n\n<p>Svantesson classificou a aprova\u00e7\u00e3o de hoje como \u201cum importante passo em frente na luta contra a lavagem de dinheiro\u201d. Ela disse,<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>A decis\u00e3o de hoje \u00e9 uma m\u00e1 not\u00edcia para aqueles que utilizaram indevidamente criptoativos para as suas atividades ilegais, para contornar as san\u00e7\u00f5es da UE ou para financiar o terrorismo e a guerra. Fazer isso n\u00e3o ser\u00e1 mais poss\u00edvel na Europa sem exposi\u00e7\u00e3o.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"what-does-mica-cover\">O que o MiCA cobre?<\/h2>\n\n\n\n<p>A MiCA foi aprovada no m\u00eas passado em Estrasburgo por membros do Parlamento Europeu, estabelecendo padr\u00f5es regulat\u00f3rios precisos e obriga\u00e7\u00f5es para o uso de criptomoedas e produtos e servi\u00e7os relacionados dentro da Uni\u00e3o Europeia. Abrange tokens utilit\u00e1rios, ativos digitais, stablecoins e uma variedade de criptomoedas.<\/p>\n\n\n\n<p>Algumas das disposi\u00e7\u00f5es importantes da MiCA s\u00e3o o processo de registro e os requisitos legais para provedores de carteira, trocas de criptomoedas e emissores operarem na UE. A nova lei tamb\u00e9m estabelece que os emissores de stablecoin devem aderir a crit\u00e9rios espec\u00edficos de seguran\u00e7a e mitiga\u00e7\u00e3o de risco.<\/p>\n\n\n\n<p>Al\u00e9m disso, a MiCA exige que os servi\u00e7os de cust\u00f3dia ofere\u00e7am medidas de seguran\u00e7a e prote\u00e7\u00e3o adequadas para lidar com qualquer seguran\u00e7a cibern\u00e9tica e falhas operacionais. A MiCA tamb\u00e9m oferece uma estrutura para conter informa\u00e7\u00f5es privilegiadas, manipula\u00e7\u00e3o de mercado e outros maus comportamentos no espa\u00e7o criptogr\u00e1fico.<\/p>\n\n\n\n<p>A Comiss\u00e3o Europeia sugeriu inicialmente o MiCA em setembro de 2020. No entanto, enfrentou v\u00e1rios obst\u00e1culos e atrasos durante o processo legislativo. Curiosamente, os provedores de servi\u00e7os criptogr\u00e1ficos na Europa t\u00eam <a href=\"https:\/\/bitcoinwisdom.com\/pt\/cz-reacts-to-eus-passage-of-mica\/\">elogiado<\/a>&nbsp;a aprova\u00e7\u00e3o do MiCA, uma vez que fornece um quadro regulamentar uniforme em toda a Europa em termos de requisitos legais e processos operacionais.<\/p>\n\n\n\n<p>Juntamente com a aprova\u00e7\u00e3o do MiCA, o Parlamento Europeu tamb\u00e9m aprovou dois outros atos legislativos, incluindo regras que regem a divulga\u00e7\u00e3o de informa\u00e7\u00f5es sobre transfer\u00eancias financeiras e criptoativos espec\u00edficos.<\/p>\n\n\n\n<p>O Conselho decidiu que as autoridades fiscais locais ser\u00e3o obrigadas a trocar informa\u00e7\u00f5es entre si para garantir que as transa\u00e7\u00f5es criptogr\u00e1ficas estrangeiras n\u00e3o sofram impostos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s uma vota\u00e7\u00e3o na ter\u00e7a-feira, 16 de maio, o Conselho de Assuntos Econ\u00f3micos e Financeiros da Uni\u00e3o Europeia, composto pelos ministros das finan\u00e7as de todos os estados membros, aprovou a t\u00e3o aguardada lei dos Mercados de Criptoativos (MiCA). A vota\u00e7\u00e3o foi amplamente vista como o obst\u00e1culo legislativo final. Os ministros votaram a favor da regulamenta\u00e7\u00e3o e das altera\u00e7\u00f5es criptogr\u00e1ficas hist\u00f3ricas [...]<\/p>","protected":false},"author":19,"featured_media":3017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":""},"categories":[190,12],"tags":[172,687],"class_list":["post-65602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-crypto","tag-european-union"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys.jpg",1600,1009,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys-300x189.jpg",300,189,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys-768x484.jpg",640,403,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys-1024x646.jpg",640,404,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys-1536x969.jpg",1536,969,true],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys.jpg",1600,1009,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/05\/c241mbgtgys.jpg",18,12,false]},"uagb_author_info":{"display_name":"Lawrence Woriji","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/lawrencew\/"},"uagb_comment_info":0,"uagb_excerpt":"Following a vote on Tuesday,\u00a0May 16, the Economic and Financial Affairs Council of the European Union, comprised of the finance ministers of all member states, approved the keenly-anticipated Markets in Crypto-Assets (MiCA) law. The vote was widely seen as the final legislative hurdle. The ministers voted in favor of the landmark crypto regulation and amendments&hellip;","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/65602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=65602"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/65602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/3017"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=65602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=65602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=65602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}