{"id":6698,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=6698"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"celsius-assures-the-community-of-getting-a-solution-to-the-ongoing-crisis","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/celsius-assures-the-community-of-getting-a-solution-to-the-ongoing-crisis\/","title":{"rendered":"Celsius garante \u00e0 comunidade obter uma solu\u00e7\u00e3o para a crise em andamento"},"content":{"rendered":"<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>A Celcius garantiu \u00e0 comunidade que o processo de consulta de especialistas em v\u00e1rios campos ajudar\u00e1 na descoberta de uma solu\u00e7\u00e3o r\u00e1pida.<\/strong><\/li><\/ul>\n<hr>\n\n\n\n<p>Devido \u00e0 crise em curso sobre a decis\u00e3o da empresa de suspender as retiradas, Celsius divulgou um memorando atrav\u00e9s de uma postagem no meio, garantindo \u00e0 sua comunidade um compromisso total para resolver a crise em curso. De acordo com a postagem do blog, a equipe revelou que est\u00e1 trabalhando na melhor e mais r\u00e1pida forma de estabilizar a liquidez e as opera\u00e7\u00f5es. Celsius revelou que est\u00e1 trabalhando incansavelmente para encontrar solu\u00e7\u00f5es que envolvam a comunidade em tempos subsequentes.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, a equipa revelou o seu compromisso em embarcar numa miss\u00e3o not\u00e1vel para proteger os activos dos investidores, ao mesmo tempo que procura as op\u00e7\u00f5es dispon\u00edveis. Celsius indicou que algumas das op\u00e7\u00f5es incluem incitar transa\u00e7\u00f5es estrat\u00e9gicas enquanto reestrutura os seus passivos, incluindo outros meios.<\/p>\n\n\n\n<p>No entanto, Celcius admitiu que todo o processo pode ser demorado devido \u00e0 sua complexidade e \u00e0 inten\u00e7\u00e3o da equipa de explorar todas as op\u00e7\u00f5es dispon\u00edveis. No entanto, Celcius garantiu \u00e0 comunidade que o processo de consulta de especialistas em diversas \u00e1reas ajudar\u00e1 na descoberta de uma solu\u00e7\u00e3o r\u00e1pida.<\/p>\n\n\n\n<p>Conclusivamente, a equipe expressou satisfa\u00e7\u00e3o com a coopera\u00e7\u00e3o da comunidade, Celsius <a href=\"https:\/\/blog.celsius.network\/across-celsius-today-c71b29513a9b\" rel=\"nofollow noopener\" target=\"_blank\">divulgado<\/a> como tem sido uma fonte de motiva\u00e7\u00e3o com a promessa de transmitir informa\u00e7\u00f5es em tempo \u00fatil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Problemas na rede Celsius&nbsp;<\/strong><\/h2>\n\n\n\n<p>H\u00e1 dias, Celsius tem sido uma tend\u00eancia controversa devido \u00e0 plataforma de empr\u00e9stimo <a href=\"https:\/\/bitcoinwisdom.com\/pt\/celsius-warns-that-more-time-is-required-before-the-lending-business-can-resume\/\">decis\u00e3o<\/a> para interromper saques, swaps e transfer\u00eancias entre contas. O principal ponto de preocupa\u00e7\u00e3o \u00e9 que a Celsius impediu que seus usu\u00e1rios acessassem seu dinheiro com aviso pr\u00e9vio.&nbsp;<\/p>\n\n\n\n<p>Notavelmente, esta decis\u00e3o n\u00e3o agradou a muitos e provocou inquieta\u00e7\u00e3o na comunidade. Os membros da comunidade desaprovaram a decis\u00e3o, incluindo amea\u00e7as de um processo contra Celsius.<\/p>\n\n\n\n<p>A pesquisa sobre a posi\u00e7\u00e3o da Celsius em rela\u00e7\u00e3o \u00e0 situa\u00e7\u00e3o revelou que a empresa tomou emprestado o DAI com uma taxa de garantia atual de 195,93%, com mais de $545 milh\u00f5es em WBTC bloqueados como garantia. Esses dados s\u00e3o fornecidos por <a href=\"https:\/\/oasis.app\/25977#Overview\" rel=\"nofollow noopener\" target=\"_blank\">O\u00e1sis<\/a>; um protocolo que ajuda os usu\u00e1rios a emprestar DAI contra garantias aprovadas. Al\u00e9m disso, Celsius tem atualmente um pre\u00e7o de liquida\u00e7\u00e3o 26% abaixo do pre\u00e7o atual do BTC, <span data-realtime=\"on\"><span data-live-price=\"BTCUSDT\" data-price=\"76999.62857685839117\" data-rate=\"1\" data-currency=\"USD\"><b class=\"fiat-symbol\">$<\/b><span>76,999.63<\/span><\/span><\/span>. Esta situa\u00e7\u00e3o \u00e9 motivo de preocupa\u00e7\u00e3o para os utilizadores porque se a Celcius n\u00e3o aumentar as suas garantias, toda a posi\u00e7\u00e3o que ronda o meio bilh\u00e3o ser\u00e1 liquidada on-chain.<\/p>\n\n\n\n<p>Notavelmente, o <a href=\"https:\/\/bitcoinwisdom.com\/pt\/celsius-ceo-reportedly-on-the-run\/\">empresa<\/a> entrou mais garantias v\u00e1rias vezes desde o in\u00edcio dos problemas, mas ainda n\u00e3o reembolsou o empr\u00e9stimo. Nesse per\u00edodo, sua posi\u00e7\u00e3o ficou abaixo de 5% da liquida\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Vale a pena notar que os membros da comunidade lamentaram a <a href=\"https:\/\/bitcoinwisdom.com\/pt\/celsius-pauses-activity-on-social-sites-to-focus-on-prevailing-crisis\/\">sil\u00eancio<\/a> de Celsius durante este per\u00edodo turbulento. Antes, quando a empresa suspendeu as retiradas, os membros da comunidade descobriram que a empresa enviou $320 milh\u00f5es para <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/pt\/ftx-review\/\" title=\"FTX\" data-wpil-keyword-link=\"linked\">FTX<\/a> sem qualquer explica\u00e7\u00e3o para a comunidade.&nbsp;<\/p>\n\n\n\n<p>Isso indicou que a equipe est\u00e1 trabalhando nos bastidores, mas sem o devido envolvimento ou garantia de quando retomar\u00e3o a retirada.<\/p>\n\n\n\n<p>No momento, o comunicado do blog veio no melhor momento, embora n\u00e3o seja o que os membros da comunidade Celsius desejam ouvir, mas ainda assim indica a disposi\u00e7\u00e3o da equipe em ir at\u00e9 o fim do assunto e oferecer a melhor solu\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p><!-- wp:heading {\"level\":1} --><\/p>\n<h1><\/h1>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:list --><\/p>\n<ul>\n<li><strong>A Celcius garantiu \u00e0 comunidade que o processo de consulta de especialistas em v\u00e1rios campos ajudar\u00e1 na descoberta de uma solu\u00e7\u00e3o r\u00e1pida.<\/strong><\/li>\n<\/ul>\n<p><!-- \/wp:list --><\/p>","protected":false},"author":18,"featured_media":8323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[],"class_list":["post-6698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm.jpg",1600,1069,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm-300x200.jpg",300,200,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm-768x513.jpg",640,428,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm-1024x684.jpg",640,428,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm-1536x1026.jpg",1536,1026,true],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm.jpg",1600,1069,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2022\/07\/btbjmecsfkm.jpg",18,12,false]},"uagb_author_info":{"display_name":"Rebecca Davidson","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/rebeccad\/"},"uagb_comment_info":0,"uagb_excerpt":"Celcius assured the community that the process of consulting experts across numerous fields will aid the discovery of a swift solution.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/6698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=6698"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/6698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/8323"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=6698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=6698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=6698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}