{"id":75192,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=75192"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"etoro-sued-by-australian-regulator-over-trading-products","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/etoro-sued-by-australian-regulator-over-trading-products\/","title":{"rendered":"eToro processado por regulador australiano sobre produtos comerciais"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>A ASIC processou a eToro pela venda de seu produto de contrato por diferen\u00e7a (CFD) para usu\u00e1rios na Austr\u00e1lia.<\/strong><\/li>\n\n\n\n<li><strong>A ASIC procura avaliar o processo de triagem seguido pelo eToro para fornecer a exposi\u00e7\u00e3o dos utilizadores aos CFDs.<\/strong><\/li>\n\n\n\n<li><strong>ASIC afirma: \u201cO mercado-alvo para o produto CFD era amplo demais para um produto comercial t\u00e3o vol\u00e1til e de alto risco\u201d.<\/strong><\/li>\n\n\n\n<li><strong>A ASIC afirma que entre 5 de outubro de 2021 e 14 de junho de 2023, 20.000 usu\u00e1rios perderam dinheiro negociando CFDs.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>O regulador do setor financeiro na Austr\u00e1lia processou <a class=\"wpil_keyword_link\" href=\"https:\/\/bitcoinwisdom.com\/pt\/etoro-review\/\" title=\"eToro\" data-wpil-keyword-link=\"linked\">eToro<\/a>, uma empresa de com\u00e9rcio social e investimento multiativos, com sede no Reino Unido, nos Estados Unidos e tamb\u00e9m na Austr\u00e1lia. A a\u00e7\u00e3o foi movida sobre a venda de produtos comerciais \u201cvol\u00e1teis\u201d que foram oferecidos pela plataforma de negocia\u00e7\u00e3o a seus usu\u00e1rios na regi\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Em 3 de agosto, a Australian Securities and Investments Commission (ASIC) <a href=\"https:\/\/asic.gov.au\/about-asic\/news-centre\/find-a-media-release\/2023-releases\/23-204mr-asic-sues-etoro-in-its-first-design-and-distribution-action-to-protect-consumers-from-high-risk-cfd-products\/\" class=\"ek-link\" rel=\"nofollow noopener\" target=\"_blank\">anunciado<\/a> que havia processado a plataforma de investimento online eToro em rela\u00e7\u00e3o ao seu produto de contrato por diferen\u00e7a (CFD). O regulador alega \u201cviola\u00e7\u00f5es das obriga\u00e7\u00f5es de design e distribui\u00e7\u00e3o e das obriga\u00e7\u00f5es de licen\u00e7a do eToro para agir de forma eficiente, honesta e justa\u201d, no processo.\u00a0<\/p>\n\n\n\n<p>A a\u00e7\u00e3o est\u00e1 focada no processo de triagem seguido pelo eToro para determinar se um candidato se enquadra no mercado-alvo do produto CFD. O regulador alegou que o \u201cmercado-alvo da plataforma de negocia\u00e7\u00e3o para o produto CFD era demasiado amplo para um produto comercial t\u00e3o vol\u00e1til e de alto risco, onde a maioria dos clientes perde dinheiro, e que o teste de triagem foi totalmente inadequado para avaliar se um cliente de varejo era prov\u00e1vel estar dentro do mercado-alvo.\u201d<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cA nossa mensagem para a ind\u00fastria \u00e9 que os mercados-alvo de CFD devem ser definidos de forma restrita, dado o risco significativo de que os clientes de retalho possam perder todos os seus fundos depositados. Os emissores de CFD devem cumprir o regime de design e distribui\u00e7\u00e3o e n\u00e3o podem simplesmente fazer engenharia reversa em seus mercados-alvo para se adequarem \u00e0s bases de clientes existentes\u201d, disse a vice-presidente da ASIC, Sarah Court.<\/p>\n<\/blockquote>\n\n\n\n<p>A ASIC afirma que entre 5 de outubro de 2021 e 14 de junho de 2023, quase 20.000 dos clientes que usaram o eToro perderam dinheiro negociando CFDs, e o site da plataforma afirma que 77% de contas de investidores de varejo perdem dinheiro ao negociar CFDs com a empresa.<\/p>\n\n\n\n<p>O regulador tamb\u00e9m alega que o eToro \u201cn\u00e3o fez todas as coisas necess\u00e1rias para garantir que os servi\u00e7os financeiros abrangidos pela sua licen\u00e7a fossem prestados de forma eficiente, honesta e justa, aplicando o teste de triagem para determinar se deveria emitir o produto CFD para clientes de varejo\u201d.&nbsp;<\/p>\n\n\n\n<p>Conforme relatado anteriormente por BitcoinWisdom, o ASIC afirmou recentemente que ir\u00e1 <a href=\"https:\/\/bitcoinwisdom.com\/pt\/australian-regulators-to-review-binance-derivati\/\" class=\"ek-link\">revisar as opera\u00e7\u00f5es com derivativos<\/a> da maior bolsa de criptografia do mundo, Binance. Al\u00e9m disso, os bancos locais encerraram seu apoio \u00e0 troca de criptomoedas e \u00e0 desbancariza\u00e7\u00e3o da plataforma de negocia\u00e7\u00e3o de criptomoedas. <a href=\"https:\/\/bitcoinwisdom.com\/pt\/binance-australia-was-notified-just-12-hours-before-debanking\/\" class=\"ek-link\">afetou cerca de 1 milh\u00e3o de investidores em criptomoedas<\/a> na Austr\u00e1lia.<\/p>","protected":false},"excerpt":{"rendered":"<p>A ASIC processou a eToro pela venda de seu produto de contrato por diferen\u00e7a (CFD) para usu\u00e1rios na Austr\u00e1lia.<\/p>","protected":false},"author":21,"featured_media":75193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[191,12],"tags":[1732,345],"class_list":["post-75192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-talk","category-news","tag-asic","tag-etoro"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/eToro-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"ASIC has sued eToro over the sale of its contract for difference (CFD) product to users in Australia.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/75192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=75192"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/75192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/75193"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=75192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=75192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=75192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}