{"id":76135,"date":"2026-08-03T09:43:40","date_gmt":"2026-08-03T09:43:40","guid":{"rendered":"https:\/\/bitcoinwisdom.com\/?p=76135"},"modified":"2026-08-03T09:43:40","modified_gmt":"2026-08-03T09:43:40","slug":"sec-has-settled-its-case-against-bittrex-and-its-ex-ceo-for-24m","status":"publish","type":"post","link":"https:\/\/bitcoinwisdom.com\/pt\/sec-has-settled-its-case-against-bittrex-and-its-ex-ceo-for-24m\/","title":{"rendered":"A SEC resolveu seu caso contra a Bittrex e seu ex-CEO por $24M"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><strong>A exchange de criptomoedas Bittrex e a SEC chegaram a um acordo que aguarda aprova\u00e7\u00e3o do tribunal.<\/strong><\/li>\n\n\n\n<li><strong>O processo alegou que a Bittrex e seu ex-CEO operavam uma bolsa de valores n\u00e3o registrada.<\/strong><\/li>\n\n\n\n<li><strong>A Bittrex concordou em pagar uma restitui\u00e7\u00e3o de $14,4 milh\u00f5es, juntamente com outras multas totalizando $24 milh\u00f5es.<\/strong><\/li>\n\n\n\n<li><strong>A Bittrex entrou com pedido de fal\u00eancia do Cap\u00edtulo 11 no Tribunal de Fal\u00eancias dos EUA para Delaware em abril, ap\u00f3s o processo.<\/strong><\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p>A Comiss\u00e3o de Valores Mobili\u00e1rios dos Estados Unidos (SEC) anunciou seu acordo em um caso contra a plataforma de negocia\u00e7\u00e3o de criptografia Bittrex e seu ex-CEO, William Shihara, por um valor total de $24 milh\u00f5es. De acordo com o processo, o regulador alegou que a empresa de criptografia operava uma bolsa de valores n\u00e3o registrada na regi\u00e3o. Esta \u00e9 a estrat\u00e9gia do regulador de \u201cregula\u00e7\u00e3o pela aplica\u00e7\u00e3o da lei\u201d, condenada por muitos.&nbsp;<\/p>\n\n\n\n<p>De acordo com um 10 de agosto <a href=\"https:\/\/www.sec.gov\/news\/press-release\/2023-150\" rel=\"nofollow noopener\" target=\"_blank\">perceber<\/a>, o acordo entre a SEC e a Bittrex ainda n\u00e3o foi aprovado pelo tribunal. No entanto, o acordo pro\u00edbe permanentemente a Bittrex e a Shihara de violar v\u00e1rias se\u00e7\u00f5es do Securities Exchange Act de 1934.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, \u201cBittrex e Bittrex Global concordaram em pagar, em bases solid\u00e1rias, restitui\u00e7\u00e3o de $14,4 milh\u00f5es, juros de pr\u00e9-julgamento de $4 milh\u00f5es e uma multa civil de $5,6 milh\u00f5es, para um pagamento monet\u00e1rio total de $24 milh\u00f5es, \u201d confirmou o regulador.<\/p>\n\n\n\n<p>\u201cDurante anos, a Bittrex trabalhou com emissores de tokens para \u2018limpar\u2019 suas declara\u00e7\u00f5es on-line de quaisquer ind\u00edcios de que eram contratos de investimento \u2013 tudo em um esfor\u00e7o para fugir das leis federais de valores mobili\u00e1rios. Eles falharam\u201d, disse Gurbir S. Grewal, Diretor da Divis\u00e3o de Fiscaliza\u00e7\u00e3o da ag\u00eancia, acrescentando:\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cO acordo de hoje deixa claro que n\u00e3o se pode escapar \u00e0 responsabilidade simplesmente mudando os r\u00f3tulos ou alterando as descri\u00e7\u00f5es porque o que importa s\u00e3o as realidades econ\u00f3micas dessas ofertas. Sou grato \u00e0 equipe da SEC por perseguir agressivamente a n\u00e3o conformidade na ind\u00fastria de criptografia, resolvendo este assunto e trazendo al\u00edvio adicional aos investidores prejudicados.\u201d<\/p>\n<\/blockquote>\n\n\n\n<p>A a\u00e7\u00e3o foi movida em abril, na qual o regulador alegou que Bittrex e Shihara, que foi CEO da empresa de 2014 a 2019, eram respons\u00e1veis por operar uma c\u00e2mara de compensa\u00e7\u00e3o de criptografia e uma bolsa de valores n\u00e3o registrada. Al\u00e9m disso, o regulador afirma que a bolsa pediu aos emissores de tokens que removessem certas \u201cdeclara\u00e7\u00f5es problem\u00e1ticas\u201d das suas p\u00e1ginas de redes sociais porque isso levaria as autoridades reguladoras a investigar as a\u00e7\u00f5es da empresa.<\/p>\n\n\n\n<p>Conforme relatado anteriormente por BitcoinWisdom, <a href=\"https:\/\/bitcoinwisdom.com\/pt\/bittrex-files-for-chapter-11-bankruptcy-following-sec-action\/\">Bittrex entrou com pedido de concordata Cap\u00edtulo 11<\/a> no Tribunal de Fal\u00eancias dos Estados Unidos para o Distrito de Delaware em abril, ap\u00f3s o processo da SEC. A empresa teria mais de 100.000 credores, entre $500 milh\u00f5es e $1 bilh\u00f5es em ativos e entre $500 milh\u00f5es e $1 bilh\u00f5es em passivos.<\/p>","protected":false},"excerpt":{"rendered":"<p>A Bittrex entrou com pedido de fal\u00eancia do Cap\u00edtulo 11 no Tribunal de Fal\u00eancias dos EUA para Delaware em abril, ap\u00f3s o processo da SEC.<\/p>","protected":false},"author":21,"featured_media":76136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_uag_custom_page_level_css":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[191,12],"tags":[1667,267],"class_list":["post-76135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-talk","category-news","tag-bittrex","tag-sec"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1.jpg",1200,675,false],"thumbnail":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1-500x330.jpg",500,330,true],"medium":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1-300x169.jpg",300,169,true],"medium_large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1-768x432.jpg",640,360,true],"large":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1-1024x576.jpg",640,360,true],"1536x1536":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1.jpg",1200,675,false],"2048x2048":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1.jpg",1200,675,false],"trp-custom-language-flag":["https:\/\/bitcoinwisdom.com\/wp-content\/uploads\/2023\/08\/SEC-1-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Parth Dubey","author_link":"https:\/\/bitcoinwisdom.com\/pt\/author\/parth\/"},"uagb_comment_info":0,"uagb_excerpt":"Bittrex filed for Chapter 11 bankruptcy with the US Bankruptcy Court for Delaware in April after the SEC lawsuit.","_links":{"self":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/76135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/comments?post=76135"}],"version-history":[{"count":0,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/posts\/76135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media\/76136"}],"wp:attachment":[{"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/media?parent=76135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/categories?post=76135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitcoinwisdom.com\/pt\/wp-json\/wp\/v2\/tags?post=76135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}